{"id":512,"date":"2010-04-13T10:55:44","date_gmt":"2010-04-13T13:55:44","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/"},"modified":"2010-04-13T10:55:44","modified_gmt":"2010-04-13T13:55:44","slug":"comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/","title":{"rendered":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Nesta ter\u00e7a-feira, 13, o Minist\u00e9rio da Sa\u00fade inicia uma pesquisa sobre as condi\u00e7\u00f5es de nascimento, de assist\u00eancia ao parto e de \u00f3bitos em crian\u00e7as com menos de 1 ano. Coordenada pela Funda\u00e7\u00e3o Osvaldo Cruz, a pesquisa, que ser\u00e1 realizada em 75 munic\u00edpios das regi\u00f5es Norte, Nordeste e no Vale do Jequitinhonha em Minas Gerais, come\u00e7a pelo Cear\u00e1. Precisamente nos munic\u00edpios de Maranguape, Ic\u00f3, Itaitinga e Pentecoste, selecionados atrav\u00e9s de sorteio. O Cear\u00e1 \u00e9 o primeiro Estado pesquisado porque tamb\u00e9m foi o primeiro a concluir o estudo de busca ativa de \u00f3bitos infantis, ocorridos no ano 2008.<\/p>\n<p>&nbsp;<\/p>\n<p>Antes de visitar as maternidades e ouvir os diretores e ainda as secretarias municipais de sa\u00fade sobre a estrutura e os processos de assist\u00eancia ao parto, os pesquisadores far\u00e3o aplica\u00e7\u00e3o de question\u00e1rios com as m\u00e3es que perderam os filhos e com m\u00e3es de filhos sobreviventes, no per\u00edodo de 1\u00ba de janeiro a 31 de dezembro de 2008.\u00a0 Tudo para conhecer melhor a ocorr\u00eancia dos \u00f3bitos, uma das prioridades do Minist\u00e9rio da Sa\u00fade, que quer reduzir ainda mais a mortalidade infantil, atrav\u00e9s das estrat\u00e9gias de qualifica\u00e7\u00e3o da assist\u00eancia pr\u00e9-natal, ao parto e ao rec\u00e9m-nascido, educa\u00e7\u00e3o na sa\u00fade, gest\u00e3o do trabalho e da informa\u00e7\u00e3o, vigil\u00e2ncia do \u00f3bito infantil e neonatal, al\u00e9m de mobiliza\u00e7\u00e3o social e de financiamento.<\/p>\n<p>&nbsp;<\/p>\n<p>O Minist\u00e9rio reconhece avan\u00e7os alcan\u00e7ados na redu\u00e7\u00e3o da mortalidade infantil no Brasil nos \u00faltimos anos. No Cear\u00e1, em 2007, a taxa foi de 16,2 por mil nascidos vivos. Em 2008, caiu para 15,8, em 2009 para 15,4, e para 2010 a previs\u00e3o \u00e9 de 14,7. Novas a\u00e7\u00f5es devem contribuir para diminuir mais ainda essa taxa.\u00a0 O Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos, lembra que no in\u00edcio deste ano a Secretaria universalizou a garantia de dois exames de aids para gestantes dos 184 munic\u00edpios cearenses, com o objetivo de reduzir a transmiss\u00e3o vertical da doen\u00e7a. Ele informa que na aten\u00e7\u00e3o prim\u00e1ria, nos \u00faltimos quatro meses, a Sesa, em apoio aos munic\u00edpios, investiu R$40 milh\u00f5es na amplia\u00e7\u00e3o, reforma e aquisi\u00e7\u00e3o de equipamentos para as Unidades B\u00e1sicas de Sa\u00fade. \u201cEstruturando melhor a assist\u00eancia l\u00e1 nos munic\u00edpios, as gestantes ser\u00e3o melhor acompanhadas e teremos crian\u00e7as mais saud\u00e1veis\u201d, comenta Arruda Bastos.<\/p>\n<p>&nbsp;<\/p>\n<p>Apesar dos avan\u00e7os na redu\u00e7\u00e3o da mortalidade infantil, o Minist\u00e9rio da Sa\u00fade observa que as taxas do Norte e Nordeste s\u00e3o superiores a m\u00e9dia nacional. Cerca de 70% dos \u00f3bitos infantis ocorrem na fase neonatal, sendo que 80% s\u00e3o registrados na primeira semana de vida (<a href=\"index.php?option=com_phocadownload&#038;view=category&#038;id=55:&#038;download=316:10-p-1997-2008&#038;Itemid=247\" target=\"_blank\"><strong>clique aqui para ver o gr\u00e1fico<\/strong><\/a>). O Minist\u00e9rio da Sa\u00fade quer derrubar os \u00edndices para corresponder ao compromisso assumido pelo Brasil com os \u201cObjetivos do Mil\u00eanio\u201d. A partir da conclus\u00e3o da pesquisa, j\u00e1 no dia 2 do pr\u00f3ximo m\u00eas, o plano do governo federal \u00e9 intensificar as a\u00e7\u00f5es na esfera da organiza\u00e7\u00e3o dos servi\u00e7os de sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nesta ter\u00e7a-feira, 13, o Minist\u00e9rio da Sa\u00fade inicia uma pesquisa sobre as condi\u00e7\u00f5es de nascimento, de assist\u00eancia ao parto e de \u00f3bitos em crian\u00e7as com menos de 1 ano. Coordenada pela Funda\u00e7\u00e3o Osvaldo Cruz, a pesquisa, que ser\u00e1 realizada em 75 munic\u00edpios das regi\u00f5es Norte, Nordeste e no Vale do Jequitinhonha em Minas Gerais, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-512","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Nesta ter\u00e7a-feira, 13, o Minist\u00e9rio da Sa\u00fade inicia uma pesquisa sobre as condi\u00e7\u00f5es de nascimento, de assist\u00eancia ao parto e de \u00f3bitos em crian\u00e7as com menos de 1 ano. Coordenada pela Funda\u00e7\u00e3o Osvaldo Cruz, a pesquisa, que ser\u00e1 realizada em 75 munic\u00edpios das regi\u00f5es Norte, Nordeste e no Vale do Jequitinhonha em Minas Gerais, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-13T13:55:44+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano\",\"datePublished\":\"2010-04-13T13:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\"},\"wordCount\":538,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\",\"name\":\"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-04-13T13:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/","og_locale":"pt_BR","og_type":"article","og_title":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&nbsp; Nesta ter\u00e7a-feira, 13, o Minist\u00e9rio da Sa\u00fade inicia uma pesquisa sobre as condi\u00e7\u00f5es de nascimento, de assist\u00eancia ao parto e de \u00f3bitos em crian\u00e7as com menos de 1 ano. Coordenada pela Funda\u00e7\u00e3o Osvaldo Cruz, a pesquisa, que ser\u00e1 realizada em 75 munic\u00edpios das regi\u00f5es Norte, Nordeste e no Vale do Jequitinhonha em Minas Gerais, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-04-13T13:55:44+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano","datePublished":"2010-04-13T13:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/"},"wordCount":538,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/","name":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-04-13T13:55:44+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/13\/comeca-pelo-ceara-pesquisa-sobre-nascimento-e-obito-de-criancas-com-menos-de-1-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Come\u00e7a pelo Cear\u00e1 pesquisa sobre nascimento e \u00f3bito de crian\u00e7as com menos de 1 ano"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=512"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/512\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}