{"id":459,"date":"2010-03-23T20:55:01","date_gmt":"2010-03-23T23:55:01","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/"},"modified":"2010-03-23T20:55:01","modified_gmt":"2010-03-23T23:55:01","slug":"ceo-de-russas-atendera-cerca-de-190-mil-pessoas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/","title":{"rendered":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Na manh\u00e3 desta ter\u00e7a-feira (23), o Governo do Estado, por meio da Secretaria de Sa\u00fade do Estado, inaugurou o Centro de Especialidades Odontol\u00f3gicas (CEO) de Russas, na regi\u00e3o do Vale do Jaguaribe. Este \u00e9 o terceiro equipamento inaugurado este ano pelo Governo. Com investimento avaliado em R$ 2,2 milh\u00f5es, a unidade atender\u00e1 cerca de 190 mil pessoas da microrregi\u00e3o de Russas.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo o secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias, que inaugurou a nova unidade representando o governador Cid Gomes, no CEO de Russas ser\u00e3o oferecidos servi\u00e7os de ortodontia, pr\u00f3tese, cirurgias, periodontia, diagn\u00f3stico de c\u00e2ncer de boca \u00e0 popula\u00e7\u00e3o de Jaguaretama, Jaguaruana, Morada Nova e Palhano. Jo\u00e3o Ananias tamb\u00e9m enumerou os investimentos do Governo Estadual na quest\u00e3o da sa\u00fade bucal da popula\u00e7\u00e3o. \u201cEste equipamento faz parte do Programa de Expans\u00e3o e Melhoria da Assist\u00eancia Especializada no Interior. At\u00e9 o fim de 2010 ser\u00e3o 16 CEOs no Cear\u00e1 \u201d, confirmou.<\/p>\n<p>&nbsp;<\/p>\n<p>O secret\u00e1rio afirmou ainda que os investimentos no setor da sa\u00fade incluem ainda a constru\u00e7\u00e3o de dois hospitais, um na regi\u00e3o Norte e outro no Cariri, com obras em andamento, e 21 policl\u00ednicas, das quais 12 j\u00e1 est\u00e3o em constru\u00e7\u00e3o. \u201cCom esses investimentos estamos garantindo a todos os cearenses novos sorrisos e melhoria na qualidade de vida\u201d, concluiu. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Na manh\u00e3 desta ter\u00e7a-feira (23), o Governo do Estado, por meio da Secretaria de Sa\u00fade do Estado, inaugurou o Centro de Especialidades Odontol\u00f3gicas (CEO) de Russas, na regi\u00e3o do Vale do Jaguaribe. Este \u00e9 o terceiro equipamento inaugurado este ano pelo Governo. Com investimento avaliado em R$ 2,2 milh\u00f5es, a unidade atender\u00e1 cerca de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-459","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Na manh\u00e3 desta ter\u00e7a-feira (23), o Governo do Estado, por meio da Secretaria de Sa\u00fade do Estado, inaugurou o Centro de Especialidades Odontol\u00f3gicas (CEO) de Russas, na regi\u00e3o do Vale do Jaguaribe. Este \u00e9 o terceiro equipamento inaugurado este ano pelo Governo. Com investimento avaliado em R$ 2,2 milh\u00f5es, a unidade atender\u00e1 cerca de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-23T23:55:01+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"CEO de Russas atender\u00e1 cerca de 190 mil pessoas\",\"datePublished\":\"2010-03-23T23:55:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\",\"name\":\"CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-03-23T23:55:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEO de Russas atender\u00e1 cerca de 190 mil pessoas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/","og_locale":"pt_BR","og_type":"article","og_title":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&nbsp; Na manh\u00e3 desta ter\u00e7a-feira (23), o Governo do Estado, por meio da Secretaria de Sa\u00fade do Estado, inaugurou o Centro de Especialidades Odontol\u00f3gicas (CEO) de Russas, na regi\u00e3o do Vale do Jaguaribe. Este \u00e9 o terceiro equipamento inaugurado este ano pelo Governo. Com investimento avaliado em R$ 2,2 milh\u00f5es, a unidade atender\u00e1 cerca de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-03-23T23:55:01+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas","datePublished":"2010-03-23T23:55:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/"},"wordCount":236,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/","name":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-03-23T23:55:01+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/23\/ceo-de-russas-atendera-cerca-de-190-mil-pessoas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"CEO de Russas atender\u00e1 cerca de 190 mil pessoas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/459\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}