{"id":361,"date":"2011-03-16T20:35:07","date_gmt":"2011-03-16T23:35:07","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/"},"modified":"2011-03-16T20:35:07","modified_gmt":"2011-03-16T23:35:07","slug":"assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/","title":{"rendered":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta"},"content":{"rendered":"<p>Promover uma mobiliza\u00e7\u00e3o institucional e tra\u00e7ar medidas de combate \u00e0 dengue no Estado e na Assembleia Legislativa. Estes s\u00e3o os principais objetivos da reuni\u00e3o, que acontece nesta quinta-feira (17\/03), \u00e0s 8h, no Complexo de Comiss\u00f5es T\u00e9cnicas Aquiles Peres Mota.<\/p>\n<p>O debate \u00e9 uma iniciativa do presidente da Comiss\u00e3o de Seguridade Social e Sa\u00fade da AL, deputado Carlomano Marques (PMDB), e vai contar com a participa\u00e7\u00e3o do presidente da Casa, deputado Roberto Cl\u00e1udio (PSB); do secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos; e dos demais parlamentares.<\/p>\n<p>Segundo Roberto Cl\u00e1udio, a proposta \u00e9 esclarecer sobre a doen\u00e7a e realizar uma busca geral na Assembleia para identificar a exist\u00eancia ou n\u00e3o de focos do mosquito <em>Aedes aegypti<\/em>, transmissor da dengue, nas instala\u00e7\u00f5es e imedia\u00e7\u00f5es da Casa. \u201cPretendemos promover uma mobiliza\u00e7\u00e3o contra a dengue aqui no Parlamento Estadual\u201d, declarou o presidente.<\/p>\n<p>O deputado Carlomano Marques disse que a Assembleia busca, por meio destas a\u00e7\u00f5es, dar o exemplo simb\u00f3lico de que o combate \u00e0 dengue precisa ser feito por toda a sociedade. \u201cQueremos mostrar \u00e0 popula\u00e7\u00e3o que a luta contra a epidemia de dengue n\u00e3o \u00e9 apenas do Parlamento, \u00e9 uma luta da sociedade\u201d, afirmou o parlamentar, acrescentando que as vistorias devem se estender ao pr\u00e9dio anexo da Casa, que est\u00e1 em constru\u00e7\u00e3o.<\/p>\n<p><strong>Fonte:<\/strong> Ag\u00eancia de Noticias da Assembleia Legislativa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promover uma mobiliza\u00e7\u00e3o institucional e tra\u00e7ar medidas de combate \u00e0 dengue no Estado e na Assembleia Legislativa. Estes s\u00e3o os principais objetivos da reuni\u00e3o, que acontece nesta quinta-feira (17\/03), \u00e0s 8h, no Complexo de Comiss\u00f5es T\u00e9cnicas Aquiles Peres Mota. O debate \u00e9 uma iniciativa do presidente da Comiss\u00e3o de Seguridade Social e Sa\u00fade da AL, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-361","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Promover uma mobiliza\u00e7\u00e3o institucional e tra\u00e7ar medidas de combate \u00e0 dengue no Estado e na Assembleia Legislativa. Estes s\u00e3o os principais objetivos da reuni\u00e3o, que acontece nesta quinta-feira (17\/03), \u00e0s 8h, no Complexo de Comiss\u00f5es T\u00e9cnicas Aquiles Peres Mota. O debate \u00e9 uma iniciativa do presidente da Comiss\u00e3o de Seguridade Social e Sa\u00fade da AL, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-16T23:35:07+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta\",\"datePublished\":\"2011-03-16T23:35:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\",\"name\":\"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2011-03-16T23:35:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/","og_locale":"pt_BR","og_type":"article","og_title":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Promover uma mobiliza\u00e7\u00e3o institucional e tra\u00e7ar medidas de combate \u00e0 dengue no Estado e na Assembleia Legislativa. Estes s\u00e3o os principais objetivos da reuni\u00e3o, que acontece nesta quinta-feira (17\/03), \u00e0s 8h, no Complexo de Comiss\u00f5es T\u00e9cnicas Aquiles Peres Mota. O debate \u00e9 uma iniciativa do presidente da Comiss\u00e3o de Seguridade Social e Sa\u00fade da AL, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-03-16T23:35:07+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta","datePublished":"2011-03-16T23:35:07+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/"},"wordCount":243,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/","name":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2011-03-16T23:35:07+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/03\/16\/assembleia-legislativa-promove-acao-de-combate-a-dengue-nesta-quinta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Assembleia Legislativa promove a\u00e7\u00e3o de combate \u00e0 dengue nesta quinta"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}