{"id":339,"date":"2011-01-04T22:15:16","date_gmt":"2011-01-05T01:15:16","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/"},"modified":"2011-01-04T22:15:16","modified_gmt":"2011-01-05T01:15:16","slug":"arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/","title":{"rendered":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade"},"content":{"rendered":"<p>O secret\u00e1rio Arruda Bastos reafirmou na solenidade de posse na Secretaria da Sa\u00fade do Estado, na tarde desta quarta-feira, 4 de janeiro, a declara\u00e7\u00e3o do governador Cid Gomes de que \u201cem 16 meses, o Cear\u00e1 ter\u00e1 a melhor rede de sa\u00fade p\u00fablica do Brasil\u201d. O secret\u00e1rio disse que os pr\u00f3ximos quatro anos n\u00e3o ser\u00e3o \u201creprise, replay, repeteco\u201d, \u201cmas uma gest\u00e3o repaginada\u201d da sa\u00fade no Cear\u00e1. Em seu discurso de posse, Arruda Bastos elencou os resultados da gest\u00e3o da sa\u00fade no primeiro governo Cid Gomes, que ele mesmo assumiu durante nove meses em 2010 em substitui\u00e7\u00e3o ao agora deputado federal Jo\u00e3o Ananias, e destacou novos compromissos e anunciou mudan\u00e7as na estrutura organizacional da Sesa.<\/p>\n<p><strong>Mais tr\u00eas hospitais<\/strong><\/p>\n<p>Al\u00e9m dos dois novos hospitais regionais, em Juazeiro do Norte e Sobral, 21 policl\u00ednicas, 18 Centros de Especialidades Odontol\u00f3gicas (CEOs) e 32 Unidades de Pronto Atendimento (UPAs 24 horas) distribu\u00eddas pelo Estado e que j\u00e1 come\u00e7aram a ser entregues \u00e0 popula\u00e7\u00e3o, Arruda Bastos anunciou como projeto da nova gest\u00e3o a constru\u00e7\u00e3o de um hospital e urg\u00eancia e emerg\u00eancia em Fortaleza, um hospital geral na Macrorregi\u00e3o Central do Estado, a ser criada, e um hospital terci\u00e1rio de retaguarda na Regi\u00e3o Metropolitana de Fortaleza. O secret\u00e1rio tamb\u00e9m prometeu concluir a transfer\u00eancia do Hospital da Pol\u00edcia Militar para a Secretaria da Sa\u00fade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"banner_posse_arruda_senador\" src=\"images\/stories\/artigos\/banner_posse_arruda_senador_4dd695604503b.jpg\" height=\"274\" width=\"555\" \/><\/p>\n<p><strong>Luta por recursos <\/strong><\/p>\n<p>Arruda Bastos vai manter a luta, junto ao Minist\u00e9rio da Sa\u00fade, para ampliar os recursos da m\u00e9dia e alta complexidade e a articula\u00e7\u00e3o, junto ao Congresso Nacional, para a regulamenta\u00e7\u00e3o da Emenda Constitucional 29 \u201ce a cria\u00e7\u00e3o de uma nova contribui\u00e7\u00e3o para a Sa\u00fade\u201d, conforme discursou. O senador In\u00e1cio Arruda tamb\u00e9m destacou nas suas palavras a urg\u00eancia em regulamentar a EC 29, que redefine os recursos espec\u00edficos para a sa\u00fade, e ainda a aprova\u00e7\u00e3o da CSS, em substitui\u00e7\u00e3o a antiga CPMF. \u201cArruda Bastos, a sua determina\u00e7\u00e3o na defesa por mais recursos tem total apoio dos tr\u00eas senadores do Cear\u00e1 \u2013 Al\u00e9m dele, Eun\u00edcio Oliveira e Jos\u00e9 Pimentel\u201d, afirmou o senador do PCdoB.<\/p>\n<p><strong>Novas coordenadorias<\/strong><\/p>\n<p>\u201cContinuarei o di\u00e1logo franco e aberto com os servidores, os sindicatos e associa\u00e7\u00f5es, avan\u00e7ando na pol\u00edtica salarial, na batalha pelo PCCS, na melhoria das condi\u00e7\u00f5es de trabalho, na redu\u00e7\u00e3o da precariza\u00e7\u00e3o dos v\u00ednculos, na pol\u00edtica de escolha dos gestores por sele\u00e7\u00e3o p\u00fablica e no fortalecimento da negocia\u00e7\u00e3o do SUS\u201d, assinalou Arruda Bastos. Na \u00e1rea administrativa, o secret\u00e1rio anunciou a cria\u00e7\u00e3o das novas Coordenadorias de Planejamento e Or\u00e7amento, de Urg\u00eancia e Emerg\u00eancia e a Superintend\u00eancia da Rede de Assist\u00eancia. Isso porque a Sesa cresceu, com a universaliza\u00e7\u00e3o do SAMU, a constru\u00e7\u00e3o das UPAs, policl\u00ednicas, CEOs, hospitais regionais.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"banner_posse_arruda_ananias\" src=\"images\/stories\/artigos\/banner_posse_arruda_ananias_4dd6956071ef5.jpg\" height=\"274\" width=\"555\" \/><\/p>\n<p><strong>Nova gest\u00e3o<\/strong><\/p>\n<p>\u201cNossa nova gest\u00e3o n\u00e3o ser\u00e1 uma reprise, mas um novo est\u00e1gio capaz de tornar as a\u00e7\u00f5es do governo na sa\u00fade ainda mais eficientes, ainda mais capazes de promover mudan\u00e7as positivas na sociedade. Vamos construir a moderniza\u00e7\u00e3o com humaniza\u00e7\u00e3o da sa\u00fade do Cear\u00e1\u201d, frisou Arruda Bastos. Para esse desafio, o deputado federal Jo\u00e3o Ananias disse que \u201ca tarefa de resolver os problemas da sa\u00fade \u00e9 republicana, que Arruda vai encarar como uma miss\u00e3o\u201d. <br \/>A promotora de sa\u00fade, Isabel Porto, destacou o papel da Sesa na garantia do direito \u00e0 sa\u00fade, assegurado na Constitui\u00e7\u00e3o, afirmando que acredita que o secret\u00e1rio est\u00e1 firme em lutar por servi\u00e7os de qualidade e para todos. Ela destacou ainda a eleg\u00e2ncia do secret\u00e1rio no trato com o Minist\u00e9rio P\u00fablico. Falando em nome dos trabalhadores da Sesa e do SUS, Manoel Fons\u00eaca comparou a Sesa a um time de futebol. Afirmou que o Secret\u00e1rio Arruda Bastos \u00e9 o principal goleador, que al\u00e9m de \u00a8definir estrat\u00e9gias de a\u00e7\u00e3o, pode escolher novos jogadores no meia da partida\u00a8.&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p>Ao final, no seu discurso Arruda Bastos anunciou: \u201ctrabalhar com prioridades vai ser nossa estrat\u00e9gia para continuar reduzindo ainda mais a mortalidade infantil, materna, as filas de cirurgias e procedimentos, a epidemia da viol\u00eancia, as drogas, entre outras a\u00e7\u00f5es priorit\u00e1rias\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"banner_posse_arruda_plateia\" src=\"images\/stories\/artigos\/banner_posse_arruda_plateia_4dd695607ea15.jpg\" height=\"274\" width=\"555\" \/><\/p>\n<p><strong>Posse concorrida<\/strong><\/p>\n<p>Estiveram presentes \u00e0 solenidade de posse cerca de mil convidados, entre eles novos secret\u00e1rios estaduais, deputados federais, deputados estaduais, prefeitos, secret\u00e1rios municipais de sa\u00fade, vereadores, representantes de entidades de classe, diretores de hospitais e unidades de sa\u00fade e trabalhadores da sa\u00fade.<\/p>\n<p><strong>Perfil do secret\u00e1rio<\/strong><\/p>\n<p>Natural  de Fortaleza e de fam\u00edlia tradicional de Baturit\u00e9, Raimundo  Jos\u00e9 Arruda  Bastos, 55 anos, \u00e9 m\u00e9dico, formado pela Universidade  Federal do Cear\u00e1  em 1979, com especializa\u00e7\u00f5es em sa\u00fade p\u00fablica, gest\u00e3o  em sa\u00fade,  oncologia e ainda em administra\u00e7\u00e3o de servi\u00e7os de sa\u00fade e  administra\u00e7\u00e3o  hospitalar. \u00c9 servidor p\u00fablico concursado da Secretaria  de Seguran\u00e7a  P\u00fablica desde 1982, lotado como m\u00e9dico no Hospital da  Pol\u00edcia Militar do  Cear\u00e1.<br \/>Arruda Bastos \u00e9 secret\u00e1rio da sa\u00fade do  Estado. Assumiu a  Secretaria da Sa\u00fade em abril deste ano. Foi  superintendente da Escola de  Sa\u00fade P\u00fablica do Cear\u00e1. \u00c9 conselheiro do  Conselho Estadual de Sa\u00fade, do  Conselho Estadual do Meio Ambiente, do  Conselho Estadual do Fundo de  Combate \u00e0 Pobreza (Fecop). Em n\u00edvel  nacional, vice-presidente do  Conselho de Secret\u00e1rios de Sa\u00fade (Conass).<\/p>\n<p>No  perfil, al\u00e9m de  fun\u00e7\u00f5es na gest\u00e3o, a exemplo de diretor da Associa\u00e7\u00e3o  dos Hospitais do  Cear\u00e1, diretor do Hospital Gonzaga Mota da Prefeitura  de Fortaleza,  diretor da rede de cl\u00ednicas Prontocl\u00ednica e chefe do  servi\u00e7o de  oncologia do Hospital da Pol\u00edcia Militar, destaques na  atua\u00e7\u00e3o sindical.  Arruda Bastos foi diretor administrativo-financeiro  do Sindicato dos  M\u00e9dicos do Estado do Cear\u00e1.<\/p>\n<p>Filiado ao PCdoB,  Arruda  Bastos ainda acumula na hist\u00f3ria de vida atua\u00e7\u00e3o pol\u00edtica. Foi  suplente  de deputado estadual, em 1990, suplente de vereador de  Fortaleza em 1992  e ainda candidato a vice-governador do Cear\u00e1 em 2002 e  a vice-prefeito  de Fortaleza em 2004.<br \/>Filho de Raimundo C\u00e9sar  Bastos (in memorian) e  Maria de Lourdes Arruda Bastos, \u00e9 casado com  Marc\u00edlia Alves Cordeiro  Bastos, com quem tem quatro filhos \u2013 Bruno,  Lia, L\u00edvia e L\u00edlia.<\/p>\n<p><strong>Conhe\u00e7a mais o perfil do Secret\u00e1rio Arruda Bastos<\/strong><\/p>\n<p>&#8211; Secret\u00e1rio da Sa\u00fade do Estado do Cear\u00e1.<br \/>&#8211; Secret\u00e1rio Executivo da Sa\u00fade do Estado de janeiro de 2007 a mar\u00e7o de 2010<br \/>&#8211; Superintendente da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 em 2008.<br \/>&#8211; Conselheiro do Conselho Estadual de Sa\u00fade (Cesau).<br \/>&#8211; Vice presidente adjunto do Conselho de Secret\u00e1rios de Sa\u00fade (CONASS).<br \/>-Conselheiro do Conselho Estadual do Meio Ambiente (COEMA).<br \/>-Conselheiro do FECOP<br \/>&#8211; P\u00f3s-gradua\u00e7\u00e3o em Administra\u00e7\u00e3o Hospitalar<br \/>&#8211; P\u00f3s-gradua\u00e7\u00e3o em Administra\u00e7\u00e3o de Servi\u00e7os e Sa\u00fade<br \/>&#8211; Diretor-geral do Hospital do Sindicato dos Estivadores de 1980 a 1986<br \/>&#8211; Diretor da Associa\u00e7\u00e3o dos Hospitais do Cear\u00e1 de 1982 a 1992<br \/>&#8211; M\u00e9dico do Instituto do C\u00e2ncer do Cear\u00e1 (ICC) de 1981 a 2000<br \/>&#8211; Membro do Conselho Consultivo do Instituto do C\u00e2ncer do Cear\u00e1 (ICC) de 1990 a 1996<br \/>&#8211; Chefe do servi\u00e7o de oncologia do Hospital da Pol\u00edcia Militar desde 1982<br \/>&#8211; Membro da Comiss\u00e3o de Medicina da Revista Brasileira de Sa\u00fade das Pol\u00edcias Militares<br \/>&#8211; Diretor da Associa\u00e7\u00e3o Empresarial da Avenida Bezerra de Menezes (Assembem) desde 2002<br \/>&#8211; Membro efetivo das Sociedades de Cancerologia, Radiologia e Cirurgia<br \/>&#8211; Diretor da rede de cl\u00ednicas Prontocl\u00ednica desde 1986<br \/>&#8211; Diretor do Hospital Gonzaga Mota da Barra do Cear\u00e1 de 2005 a 2006<br \/>&#8211; Diretor administrativo-financeiro do Sindicato dos M\u00e9dicos do Estado do Cear\u00e1 de 2006 a 2009<br \/>&#8211; Acad\u00eamico do curso de Direito da Unifor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio Arruda Bastos reafirmou na solenidade de posse na Secretaria da Sa\u00fade do Estado, na tarde desta quarta-feira, 4 de janeiro, a declara\u00e7\u00e3o do governador Cid Gomes de que \u201cem 16 meses, o Cear\u00e1 ter\u00e1 a melhor rede de sa\u00fade p\u00fablica do Brasil\u201d. O secret\u00e1rio disse que os pr\u00f3ximos quatro anos n\u00e3o ser\u00e3o \u201creprise, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-339","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio Arruda Bastos reafirmou na solenidade de posse na Secretaria da Sa\u00fade do Estado, na tarde desta quarta-feira, 4 de janeiro, a declara\u00e7\u00e3o do governador Cid Gomes de que \u201cem 16 meses, o Cear\u00e1 ter\u00e1 a melhor rede de sa\u00fade p\u00fablica do Brasil\u201d. O secret\u00e1rio disse que os pr\u00f3ximos quatro anos n\u00e3o ser\u00e3o \u201creprise, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-05T01:15:16+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade\",\"datePublished\":\"2011-01-05T01:15:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\"},\"wordCount\":1329,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\",\"name\":\"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2011-01-05T01:15:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O secret\u00e1rio Arruda Bastos reafirmou na solenidade de posse na Secretaria da Sa\u00fade do Estado, na tarde desta quarta-feira, 4 de janeiro, a declara\u00e7\u00e3o do governador Cid Gomes de que \u201cem 16 meses, o Cear\u00e1 ter\u00e1 a melhor rede de sa\u00fade p\u00fablica do Brasil\u201d. O secret\u00e1rio disse que os pr\u00f3ximos quatro anos n\u00e3o ser\u00e3o \u201creprise, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-01-05T01:15:16+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade","datePublished":"2011-01-05T01:15:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/"},"wordCount":1329,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/","name":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2011-01-05T01:15:16+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/01\/04\/arruda-bastos-descarta-reprise-e-anuncia-repaginacao-da-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Arruda Bastos descarta reprise e anuncia repagina\u00e7\u00e3o da sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}