{"id":285,"date":"2009-09-29T13:42:11","date_gmt":"2009-09-29T16:42:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/"},"modified":"2009-09-29T13:42:11","modified_gmt":"2009-09-29T16:42:11","slug":"9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/","title":{"rendered":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas"},"content":{"rendered":"<p>As \u00faltimas horas da Central de Transplantes do Estado e das equipes transplantadoras nos hospitais t\u00eam sido bem movimentadas. Foram realizados nove transplantes de \u00f3rg\u00e3os doados por duas fam\u00edlias. A fam\u00edlia de uma jovem de 23 anos, v\u00edtima de atropelamento no Centro da capital, decidiu doar todos os \u00f3rg\u00e3os. As duas c\u00f3rneas, dois rins, o cora\u00e7\u00e3o e o f\u00edgado j\u00e1 foram transplantados na madrugada desta ter\u00e7a-feira. A outra fam\u00edlia \u00e9 de um homem de 57 anos, que doou os rins e o f\u00edgado. <\/p>\n<p>Com esses novos transplantes aumenta para 520 o total de transplantes realizados no Cear\u00e1 este ano. Esse n\u00famero j\u00e1 \u00e9 superior a quantidade de transplantes feitos em todo o ano de 2006 e est\u00e1 pr\u00f3ximo do n\u00famero de 2007, quando o Cear\u00e1 realizou 618 transplantes. Em 2008, bateu recorde, com 739 transplantes. \u201cO sentimento e a decis\u00e3o de doar devem ser cultivados sempre para que mais gente saia da fila\u00a0 de espera e tenha a chance de voltar a viver com sa\u00fade\u201d, afirma o Secret\u00e1rio da Sa\u00fade do Estado, Jo\u00e3o Ananias. Ele lembra que h\u00e1 1130 pessoas, no Cear\u00e1, aguardando \u00f3rg\u00e3os ou tecidos novos.<\/p>\n<p>O Secret\u00e1rio destaca que os investimentos do Sistema \u00danico de Sa\u00fade em transplantes no Brasil vem aumentando ano a ano: em 2004 foram investidos 409,4 milh\u00f5es de reais, em 2005 subiu para 526,5 milh\u00f5es, em 2006 para 602,9 milh\u00f5es, em 2007 para 713,1 milh\u00f5es, chegando a 824,2milh\u00f5es em 2008, segundo dados do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As \u00faltimas horas da Central de Transplantes do Estado e das equipes transplantadoras nos hospitais t\u00eam sido bem movimentadas. Foram realizados nove transplantes de \u00f3rg\u00e3os doados por duas fam\u00edlias. A fam\u00edlia de uma jovem de 23 anos, v\u00edtima de atropelamento no Centro da capital, decidiu doar todos os \u00f3rg\u00e3os. As duas c\u00f3rneas, dois rins, o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-285","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"As \u00faltimas horas da Central de Transplantes do Estado e das equipes transplantadoras nos hospitais t\u00eam sido bem movimentadas. Foram realizados nove transplantes de \u00f3rg\u00e3os doados por duas fam\u00edlias. A fam\u00edlia de uma jovem de 23 anos, v\u00edtima de atropelamento no Centro da capital, decidiu doar todos os \u00f3rg\u00e3os. As duas c\u00f3rneas, dois rins, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-29T16:42:11+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas\",\"datePublished\":\"2009-09-29T16:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\"},\"wordCount\":263,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\",\"name\":\"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-09-29T16:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/","og_locale":"pt_BR","og_type":"article","og_title":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"As \u00faltimas horas da Central de Transplantes do Estado e das equipes transplantadoras nos hospitais t\u00eam sido bem movimentadas. Foram realizados nove transplantes de \u00f3rg\u00e3os doados por duas fam\u00edlias. A fam\u00edlia de uma jovem de 23 anos, v\u00edtima de atropelamento no Centro da capital, decidiu doar todos os \u00f3rg\u00e3os. As duas c\u00f3rneas, dois rins, o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-09-29T16:42:11+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas","datePublished":"2009-09-29T16:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/"},"wordCount":263,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/","name":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-09-29T16:42:11+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/29\/9-pessoas-ganharam-orgaos-e-corneas-em-menos-de-24-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"9 pessoas ganharam \u00f3rg\u00e3os e c\u00f3rneas em menos de 24 horas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=285"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/285\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}