{"id":263,"date":"2009-09-25T14:53:11","date_gmt":"2009-09-25T17:53:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/"},"modified":"2009-09-25T14:53:11","modified_gmt":"2009-09-25T17:53:11","slug":"16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/","title":{"rendered":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1"},"content":{"rendered":"<p>Para proteger a sa\u00fade da popula\u00e7\u00e3o e dos animais contra a raiva, donos de c\u00e3es e gatos devem vacinar os bichos no s\u00e1bado, 26. Em todo o Estado, a campanha, lan\u00e7ada nesta sexta-feira, prev\u00ea a vacina\u00e7\u00e3o de 1.060.152 c\u00e3es e 592.812 gatos. Tr\u00eas mil postos instalados em pra\u00e7as, locais p\u00fablicos e unidades das secretarias municipais de sa\u00fade funcionar\u00e3o das 8 \u00e0s 17 horas.\u00a0 A campanha tem dura\u00e7\u00e3o de um dia em todas as zonas urbanas do Estado. Nos munic\u00edpios com zona rural, a campanha permanece durante um m\u00eas, com postos volantes. <\/p>\n<p>A Secretaria da Sa\u00fade do Estado, secretarias municipais de sa\u00fade, Pol\u00edcia Militar, For\u00e7as Armadas, Funda\u00e7\u00e3o Nacional de Sa\u00fade (FUNASA), Ematerce, Corpo de Bombeiros e a Empresa de Correios e Tel\u00e9grafos envolver\u00e3o 30 mil pessoas na campanha de vacina\u00e7\u00e3o, incluindo agentes de sa\u00fade e volunt\u00e1rios. Em Fortaleza funcionar\u00e3o no Dia D 800 postos de vacina\u00e7\u00e3o. A vacina\u00e7\u00e3o antirr\u00e1bica \u00e9 gratuita. Os animais devem ser imunizados a partir dos dois meses de idade, inclusive em cadelas no cio e lactantes.<\/p>\n<p>A raiva \u00e9 uma doen\u00e7a infecciosa aguda e mortal. Ela \u00e9 transmitida atrav\u00e9s da mordida, arranh\u00e3o e lambedura de c\u00e3es e gatos contaminados com o v\u00edrus r\u00e1bico. H\u00e1 cinco anos o Cear\u00e1 n\u00e3o registra casos de raiva humana transmitida por c\u00e3es e gatos. Os \u00faltimos registros foram no ano de 2003, quando foram confirmados sete \u00f3bitos.\u00a0 Em 2005 e em 2008 foram confirmadas duas mortes por raiva, com a transmiss\u00e3o da doen\u00e7a ocorrendo por sag\u00fci, mais conhecido como soim. Os saguis de tufo branco, muitas vezes s\u00e3o criados em ambientes dom\u00e9sticos como animais de estima\u00e7\u00e3o, pr\u00f3ximo \u00e0s casas e em contato com as pessoas. Isso \u00e9 um perigo \u00e0 sa\u00fade. Eles transmitem a raiva. A dica \u00e9 respeitar a legisla\u00e7\u00e3o, deixando os saguis, animais silvestres, nas matas e n\u00e3o em ambientes dom\u00e9sticos. A vacina s\u00f3 \u00e9 indicada para c\u00e3es e gatos. N\u00e3o tem indica\u00e7\u00e3o nem efic\u00e1cia nos saguis.\u00a0 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para proteger a sa\u00fade da popula\u00e7\u00e3o e dos animais contra a raiva, donos de c\u00e3es e gatos devem vacinar os bichos no s\u00e1bado, 26. Em todo o Estado, a campanha, lan\u00e7ada nesta sexta-feira, prev\u00ea a vacina\u00e7\u00e3o de 1.060.152 c\u00e3es e 592.812 gatos. Tr\u00eas mil postos instalados em pra\u00e7as, locais p\u00fablicos e unidades das secretarias municipais [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Para proteger a sa\u00fade da popula\u00e7\u00e3o e dos animais contra a raiva, donos de c\u00e3es e gatos devem vacinar os bichos no s\u00e1bado, 26. Em todo o Estado, a campanha, lan\u00e7ada nesta sexta-feira, prev\u00ea a vacina\u00e7\u00e3o de 1.060.152 c\u00e3es e 592.812 gatos. Tr\u00eas mil postos instalados em pra\u00e7as, locais p\u00fablicos e unidades das secretarias municipais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-25T17:53:11+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1\",\"datePublished\":\"2009-09-25T17:53:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\",\"name\":\"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-09-25T17:53:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Para proteger a sa\u00fade da popula\u00e7\u00e3o e dos animais contra a raiva, donos de c\u00e3es e gatos devem vacinar os bichos no s\u00e1bado, 26. Em todo o Estado, a campanha, lan\u00e7ada nesta sexta-feira, prev\u00ea a vacina\u00e7\u00e3o de 1.060.152 c\u00e3es e 592.812 gatos. Tr\u00eas mil postos instalados em pra\u00e7as, locais p\u00fablicos e unidades das secretarias municipais [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-09-25T17:53:11+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1","datePublished":"2009-09-25T17:53:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/"},"wordCount":368,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/","name":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-09-25T17:53:11+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/09\/25\/16-milhao-de-caes-e-gatos-serao-vacinados-contra-a-raiva-no-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"1,6 milh\u00e3o de c\u00e3es e gatos ser\u00e3o vacinados contra a raiva no Cear\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}