{"id":2073,"date":"2011-10-18T16:45:53","date_gmt":"2011-10-18T19:45:53","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/"},"modified":"2011-10-18T16:45:53","modified_gmt":"2011-10-18T19:45:53","slug":"albert-sabin-atende-200-criancas-com-labio-leporino-por-mes","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/","title":{"rendered":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas"},"content":{"rendered":"<p> Refer\u00eancia para todo o Estado do Cear\u00e1, o Hospital Infantil Albert Sabin promove h\u00e1 15 anos a reabilita\u00e7\u00e3o de crian\u00e7as e adolescentes com fissuras labiopalatais, mais conhecidas como l\u00e1bios leporinos. O servi\u00e7o \u00e9 realizado pelo N\u00facleo de Atendimento Integrado ao Fissurado. Na odontologia, os l\u00e1bios leporinos s\u00e3o considerados o quarto problema de sa\u00fade p\u00fablica. Ficam atr\u00e1s apenas das c\u00e1ries, das doen\u00e7as periodontais (inflama\u00e7\u00f5es na gengiva) e das maloclus\u00f5es (desvio dos dentes).<\/p>\n<p> De acordo com a ortodontista e coordenadora do Naif, L\u00facia Bomfim, as malforma\u00e7\u00f5es ocorrem logo no in\u00edcio da gravidez, entre a quarta e a d\u00e9cima semana de gesta\u00e7\u00e3o. Entre as principais causas est\u00e3o o uso de \u00e1lcool, cigarros, realiza\u00e7\u00e3o de raios X na regi\u00e3o abdominal, defici\u00eancia nutricional, estresse emocional, hereditariedade, dentre outras. O problema atinge um em cada 650 rec\u00e9m-nascidos brasileiros.<\/p>\n<p> <strong>Beb\u00ea Levi<\/strong><\/p>\n<p> Por m\u00eas, o Naif atende cerca de 200 pacientes. A maioria das crian\u00e7as chega logo nos primeiros dias de vida. Esse \u00e9 o caso de Francisco Levi Nascimento, com apenas dois meses de vida. Desde que nasceu, ele vem sendo, regularmente, acompanhado por dentistas e fonoaudi\u00f3logas do hospital. Na \u00faltima segunda-feira, 10, Levi e a m\u00e3e, Edna Nascimento, estiveram no hospital para colocar uma placa acr\u00edlica, moldada especialmente para o c\u00e9u da boca dele. A medida tem a finalidade de vedar a comunica\u00e7\u00e3o entre os canais oral e nasal. &ldquo;Com a placa, o beb\u00ea mama, alimenta-se melhor, ganha peso e se prepara para a cirurgia pl\u00e1stica do l\u00e1bio e da palatoplastia (fechamento do palato)&rdquo;, explica L\u00facia Bomfim.<\/p>\n<p> Al\u00e9m de dentistas, pediatras e geneticista, uma equipe multidisciplinar formada por nutricionista, fonoaudi\u00f3logo, psic\u00f3logos e assistentes sociais deve estar envolvida na reabilita\u00e7\u00e3o do paciente fissurado. Se a crian\u00e7a n\u00e3o for devidamente tratada, as fissuras podem provocar problemas na audi\u00e7\u00e3o, dificuldades no desenvolvimento da linguagem, perda de peso, al\u00e9m de dist\u00farbios no comportamento, pois o paciente passa a ter de enfrentar a barreira do preconceito.<\/p>\n<p> Will Anderson Martins sabe bem o que \u00e9 isso. Ele chegou ao Naif com oito anos. Era um garoto t\u00edmido, que vivia de cabe\u00e7a baixa. &ldquo;Ele tinha uma assimetria facial muito grande. Embora j\u00e1 tivesse feito a cirurgia do l\u00e1bio, foi preparado para receber a cirurgia do palato. Aos 12 anos, fez enxerto \u00f3sseo secund\u00e1rio no processo alveolar. Aos 18 anos, ele se submeteu a uma cirurgia das bases \u00f3sseas (cirurgia ortogn\u00e1tica) para corre\u00e7\u00e3o da assimetria facial e ajuste final da oclus\u00e3o.Mesmo sendo retra\u00eddo, n\u00e3o deixava que ningu\u00e9m tocasse na boca dele. Lembro que cheguei a moldar a boca dele umas oito vezes. Quando tentava, ele vomitava em cima de mim. Mas n\u00e3o desisti&rdquo;, relembra L\u00facia Bomfim.<\/p>\n<p> A coordenadora do Naif contou com o apoio firme e dedica\u00e7\u00e3o da m\u00e3e de Will Anderson, Luiza Martins. &ldquo;Quando soube que o hospital oferecia esse servi\u00e7o, me dediquei totalmente. &ldquo;Lembro que faltava o emprego e saia de madrugada de Pindoretama para ele ser atendido. Muitas pessoas falavam para eu desistir e aceitar que Deus o tinha feito assim. Decidi que ele ia ter um sorriso bonito&rdquo;, diz a m\u00e3e que sempre confiou na equipe do Hias. Hoje, com 19 anos e dentes nivelados, Will fala que o tratamento melhorou muito sua qualidade de vida e que contribuiu para aumentar sua autoestima.<\/p>\n<p> J\u00e1 Mateus Colares procurou o Hias quando tinha 15 anos. Com um ano e meio, ele se submeteu \u00e0 cirurgia para fechar o c\u00e9u da boca, mas os dentes cresceram muito tortos. Foi a\u00ed que soube atrav\u00e9s de uma amiga da m\u00e3e que o hospital tinha um servi\u00e7o de apoio ao fissurado. Durante dois anos, freq\u00fcentou a sala de Odontologia do hospital. Hoje, com sorriso bonito no rosto, Mateus se orgulha de sua conquista. &ldquo;Todo o tratamento foi feito pelo SUS (Sistema \u00danico de Sa\u00fade). No meu caso o SUS funcionou muito bem&rdquo;, diz. As idas e vindas ao Naif fizeram Mateus adquirir uma admira\u00e7\u00e3o pelos profissionais que cuidaram dele. Teve vontade de ser igual a eles. Atualmente, ele cursa o terceiro semestre de Odontologia em uma faculdade particular. E, claro, pretende ser ortodentista.<\/p>\n<p> <b>Etapas do Tratamento Ortod\u00f4ntico<\/b><\/p>\n<p> At\u00e9 os 3 meses de vida &ndash; confec\u00e7\u00e3o e instala\u00e7\u00e3o de placa acr\u00edlica<br \/> 6 meses &ndash; queiloplastia (corre\u00e7\u00e3o do l\u00e1bio)<br \/> 1 ano e 6 meses &ndash; palatoplastia (fechamento do palato)<br \/> At\u00e9 5 anos &ndash; a crian\u00e7a tem alta da ortodontia e fica fazendo preven\u00e7\u00e3o e manuten\u00e7\u00e3o (limpezas, aplica\u00e7\u00e3o de fl\u00faor, tratamento de c\u00e1ries)<br \/> Ap\u00f3s 5 anos at\u00e9 18 anos &ndash; a crian\u00e7a volta a usar aparelhos para corrigir o posicionamento dent\u00e1rio<\/p>\n<p> <b>Mais informa\u00e7\u00f5es:<\/b><br \/> Raquel Mour\u00e3o (CE 1791 JP)<br \/> Assessora de Comunica\u00e7\u00e3o do Hias<br \/> 9925-9444\/3256-1574<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Refer\u00eancia para todo o Estado do Cear\u00e1, o Hospital Infantil Albert Sabin promove h\u00e1 15 anos a reabilita\u00e7\u00e3o de crian\u00e7as e adolescentes com fissuras labiopalatais, mais conhecidas como l\u00e1bios leporinos. O servi\u00e7o \u00e9 realizado pelo N\u00facleo de Atendimento Integrado ao Fissurado. Na odontologia, os l\u00e1bios leporinos s\u00e3o considerados o quarto problema de sa\u00fade p\u00fablica. Ficam [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":2072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Refer\u00eancia para todo o Estado do Cear\u00e1, o Hospital Infantil Albert Sabin promove h\u00e1 15 anos a reabilita\u00e7\u00e3o de crian\u00e7as e adolescentes com fissuras labiopalatais, mais conhecidas como l\u00e1bios leporinos. O servi\u00e7o \u00e9 realizado pelo N\u00facleo de Atendimento Integrado ao Fissurado. Na odontologia, os l\u00e1bios leporinos s\u00e3o considerados o quarto problema de sa\u00fade p\u00fablica. Ficam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-18T19:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"589\" \/>\n\t<meta property=\"og:image:height\" content=\"291\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas\",\"datePublished\":\"2011-10-18T19:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\"},\"wordCount\":843,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\",\"name\":\"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg\",\"datePublished\":\"2011-10-18T19:45:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg\",\"width\":589,\"height\":291,\"caption\":\"alt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/","og_locale":"pt_BR","og_type":"article","og_title":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Refer\u00eancia para todo o Estado do Cear\u00e1, o Hospital Infantil Albert Sabin promove h\u00e1 15 anos a reabilita\u00e7\u00e3o de crian\u00e7as e adolescentes com fissuras labiopalatais, mais conhecidas como l\u00e1bios leporinos. O servi\u00e7o \u00e9 realizado pelo N\u00facleo de Atendimento Integrado ao Fissurado. Na odontologia, os l\u00e1bios leporinos s\u00e3o considerados o quarto problema de sa\u00fade p\u00fablica. Ficam [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-10-18T19:45:53+00:00","og_image":[{"width":589,"height":291,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas","datePublished":"2011-10-18T19:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/"},"wordCount":843,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/","name":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg","datePublished":"2011-10-18T19:45:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_sorriso.jpg","width":589,"height":291,"caption":"alt"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/18\/albert-sabin-atende-200-criancas-com-labio-leporino-por-mes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Albert Sabin atende 200 crian\u00e7as com l\u00e1bio leporino por m\u00eas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=2073"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/2072"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=2073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=2073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=2073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}