{"id":2034,"date":"2011-10-05T18:44:45","date_gmt":"2011-10-05T21:44:45","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/"},"modified":"2011-10-05T18:44:45","modified_gmt":"2011-10-05T21:44:45","slug":"sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/","title":{"rendered":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d"},"content":{"rendered":"<p>O medo do diagn\u00f3stico de c\u00e2ncer de mama \u00e9 um dos fatores que afastam muitas mulheres dos exames de mamografias. Muitas n\u00e3o comparecem \u00e0s unidades de sa\u00fade para realiza\u00e7\u00e3o do exame. Essa realidade pode ser percebida comparando os n\u00fameros de exames realizados e ofertados na Policl\u00ednica Regional em Baturit\u00e9, constru\u00edda pelo governo do Estado para ampliar e facilitar o acesso a servi\u00e7os e exames no interior, entre eles a mamografia. Nos \u00faltimos seis meses foram realizados na policl\u00ednica 880 mamografias, bem abaixo do total de 2.200 ofertadas. <\/p>\n<p>A Secretaria da Sa\u00fade do Estado aproveita o \u201cOutubro Rosa\u201d, campanha feita no mundo inteiro por ONGS, com apoio de institui\u00e7\u00f5es p\u00fablicas, para mobilizar e conscientizar as mulheres sobre a import\u00e2ncia do diagn\u00f3stico precoce de combate ao c\u00e2ncer de mama.<\/p>\n<p>\u201cQuanto mais cedo a descoberta, maiores as possibilidades positivas de tratamentos\u201d, afirma o oncologista Luis Porto, coordenador do Comit\u00ea Estadual de Controle do C\u00e2ncer, criado em 2008 pela Sesa para integrar diferentes institui\u00e7\u00f5es governamentais e civis nas a\u00e7\u00f5es contra a doen\u00e7a. No dia 13, \u00e0s 9 horas, na sede do Comit\u00ea, Rua Papi J\u00fanior, 1511, ser\u00e1 feita uma mobliza\u00e7\u00e3o, com distribui\u00e7\u00e3o de lacinhos rosas, s\u00edmbolo do \u201cOutubro Rosa\u201d e folderes informativos.&nbsp;&nbsp;&nbsp;&nbsp; <br \/>&nbsp;<br \/>H\u00e1 atualmente na rede p\u00fablica 40 mam\u00f3grafos em funcionamento no Cear\u00e1. Esse n\u00famero ser\u00e1 ampliado com os mam\u00f3grafos das policl\u00ednicas regionais que est\u00e3o em constru\u00e7\u00e3o em todas as regionais do interior. Al\u00e9m da policl\u00ednica regional em Baturit\u00e9, mais 21 policl\u00ednicas garantir\u00e3o o acesso e realiza\u00e7\u00e3o da mamografia na pr\u00f3pria regi\u00e3o, perto de onde as mulheres moram. Com os novos mam\u00f3grafos, a Sesa far\u00e1 uma campanha, orientando as mulheres com informa\u00e7\u00f5es objetivas onde realizar o exame e a partir de que idade \u00e9 indicado. Segundo a Sociedade Brasileira de Mastologia, a primeira deve ser feita aos 35 anos. Caso nenhuma altera\u00e7\u00e3o fique constada, a segunda deve ser realizada somente aos 40 anos. <\/p>\n<p>O c\u00e2ncer \u00e9 a segunda doen\u00e7a que mais mata no Cear\u00e1. Fica atr\u00e1s apenas do AVC. No sexo feminino, o c\u00e2ncer que provoca mais mortes entre as mulheres \u00e9 o de mama, seguido de pulm\u00e3o, est\u00f4mago e colo de \u00fatero.&nbsp; Em 2009, o c\u00e2ncer de mama causou a morte de 428 mulheres no Estado. Desse total, 209 tinham mais de 60 anos de idade. <\/p>\n<p><br mce_bogus=\"1\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O medo do diagn\u00f3stico de c\u00e2ncer de mama \u00e9 um dos fatores que afastam muitas mulheres dos exames de mamografias. Muitas n\u00e3o comparecem \u00e0s unidades de sa\u00fade para realiza\u00e7\u00e3o do exame. Essa realidade pode ser percebida comparando os n\u00fameros de exames realizados e ofertados na Policl\u00ednica Regional em Baturit\u00e9, constru\u00edda pelo governo do Estado para [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":2033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O medo do diagn\u00f3stico de c\u00e2ncer de mama \u00e9 um dos fatores que afastam muitas mulheres dos exames de mamografias. Muitas n\u00e3o comparecem \u00e0s unidades de sa\u00fade para realiza\u00e7\u00e3o do exame. Essa realidade pode ser percebida comparando os n\u00fameros de exames realizados e ofertados na Policl\u00ednica Regional em Baturit\u00e9, constru\u00edda pelo governo do Estado para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-05T21:44:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d\",\"datePublished\":\"2011-10-05T21:44:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\"},\"wordCount\":419,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\",\"name\":\"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg\",\"datePublished\":\"2011-10-05T21:44:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg\",\"width\":555,\"height\":274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/","og_locale":"pt_BR","og_type":"article","og_title":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O medo do diagn\u00f3stico de c\u00e2ncer de mama \u00e9 um dos fatores que afastam muitas mulheres dos exames de mamografias. Muitas n\u00e3o comparecem \u00e0s unidades de sa\u00fade para realiza\u00e7\u00e3o do exame. Essa realidade pode ser percebida comparando os n\u00fameros de exames realizados e ofertados na Policl\u00ednica Regional em Baturit\u00e9, constru\u00edda pelo governo do Estado para [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-10-05T21:44:45+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d","datePublished":"2011-10-05T21:44:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/"},"wordCount":419,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/","name":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg","datePublished":"2011-10-05T21:44:45+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/10\/banner_cancer_mama_outubro_rosa.jpg","width":555,"height":274},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/10\/05\/sesa-alerta-sobre-importancia-da-mamografia-no-outubro-rosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Sesa alerta sobre import\u00e2ncia da mamografia no \u201cOutubro Rosa\u201d"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=2034"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/2034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/2033"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=2034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=2034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=2034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}