{"id":1892,"date":"2011-08-10T12:45:53","date_gmt":"2011-08-10T15:45:53","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/"},"modified":"2011-08-10T12:45:53","modified_gmt":"2011-08-10T15:45:53","slug":"cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/","title":{"rendered":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11"},"content":{"rendered":"<p><span style=\"font-size: 12pt;\"><br \/>Com a presen\u00e7a da Presidenta Dilma Rousseff, o Governador Cid Gomes inaugura nesta quinta-feira, 11, a Policl\u00ednica Regional em Pacajus, na Regi\u00e3o Metropolitana de Fortaleza, e o Polo 1 do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU (<span style=\"text-decoration: underline;\"><a href=\"index.php?view=article&amp;catid=14%3Alista-de-noticias&amp;id=1437%3Apolo-i-do-samu-cobre-41-municipios-e-2-milhoes-de-habitantes&amp;option=com_content&amp;Itemid=248\" target=\"_blank\">ver mat\u00e9ria Polo do SAMU I cobre 41 munic\u00edpios e 2 milh\u00f5es de habitantes<\/a>). As inaugura\u00e7\u00f5es ocorrer\u00e3o \u00e0s 14 horas, na Avenida Doca Nogueira, s\/n, pr\u00f3ximo \u00e0 Escola Estadual de Educa\u00e7\u00e3o Profissional, em Pacajus. O ministro da sa\u00fade, Alexandre Padilha, e o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, participam da solenidade.<\/span><\/span><\/p>\n<p>A Policl\u00ednica Regional em Pacajus, que amplia e facilita o acesso aos servi\u00e7os de sa\u00fade para popula\u00e7\u00e3o de 244.747 habitantes de Cascavel, Chorozinho, Horizonte, Ocara, Pindoretama e Pacajus, munic\u00edpios da Regi\u00e3o Metropolitana, recebeu um investimento de R$7.100.000,00 do Tesouro do Estado. Desse total, R$4 milh\u00f5es em obras e R$3.100,00 na aquisi\u00e7\u00e3o de equipamentos. Com a nova policl\u00ednica tipo I a popula\u00e7\u00e3o passa a contar na pr\u00f3pria&nbsp; regi\u00e3o onde mora com assist\u00eancia em dez especialidades m\u00e9dicas: cl\u00ednica geral, cardiologia, ginecologia, mastologia, cirurgia geral, gastroenterologia, urologia, traumato-ortopedia, otorrinolaringologia e oftalmologia. Garantindo aten\u00e7\u00e3o integral, a policl\u00ednica regional realizar\u00e1, em m\u00e9dia, por m\u00eas, 12 mil atendimentos em consultas e exames especializados. Entre os exames, mamografia, endoscopia digestiva, ecocardiograma, eletrocardiograma, ergometria, audiometria, ultrassonografia.<b><\/b><\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1891\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_sevicos_poli.jpg\" alt=\"banner_sevicos_poli\" height=\"247\" width=\"555\" \/><\/b><\/p>\n<p><b>Interioriza\u00e7\u00e3o<\/b><\/p>\n<p>Com a unidade de Pacajus, aumenta para&nbsp; quatro o n\u00famero de policl\u00ednicas regionais j\u00e1 entregues \u00e0 popula\u00e7\u00e3o pelo Governo do Estado. Est\u00e3o em funcionamento as unidades regionais em Baturit\u00e9, Camocim e Tau\u00e1. At\u00e9 o final do pr\u00f3ximo m\u00eas de setembro mais sete policl\u00ednicas ser\u00e3o inauguradas em Campos Sales, na regi\u00e3o do Cariri; Aracati, no litoral leste; Acara\u00fa, na regi\u00e3o Norte, Russas, no Vale do Jaguaribe; Sobral, no Norte do Estado; Itapipoca, regi\u00e3o Norte; Ic\u00f3, na macrorregi\u00e3o do Cariri. H\u00e1 outras 11 unidades em constru\u00e7\u00e3o, al\u00e9m do recente acr\u00e9scimo de mais uma para atender a popula\u00e7\u00e3o da microrregi\u00e3o do Crato, no Cariri.<\/p>\n<p>No total, ser\u00e3o 22 policl\u00ednicas, sendo 10 tipo II e 12 tipo I. Nas unidades tipo II, s\u00e3o agregadas mais tr\u00eas especialidades \u2013 neurologia, endocrinologia e angiologia. Todas integram o Programa de Expans\u00e3o e Melhoria da Assist\u00eancia \u00e0 Sa\u00fade do Governo do Estado em parceria com o Banco Interamericano de Desenvolvimento \u2013 BID. A gest\u00e3o \u00e9 atrav\u00e9s de cons\u00f3rcios p\u00fablicos de sa\u00fade, uma estrat\u00e9gia inovadora no Cear\u00e1 que fortalece a regionaliza\u00e7\u00e3o. A popula\u00e7\u00e3o de todos os munic\u00edpios da microrregi\u00e3o \u00e9 atendida, com os custos de manuten\u00e7\u00e3o compartilhados entre o governo do Estado e os gestores municipais.<\/p>\n<p>A decis\u00e3o de levar para as regi\u00f5es, perto das pessoas assist\u00eancia especializada, inclui ainda 18 Centros de Especialidades Odontol\u00f3gicas, com oito j\u00e1 inaugurados e em funcionamento, e hospitais regionais. O Hospital Regional do Cariri, com 294 leitos, foi inaugurado em abril deste ano para atender a popula\u00e7\u00e3o de 44 munic\u00edpios da macrorregi\u00e3o sul do Estado. Est\u00e1 funcionanco com UTIs, a Unidade de imagem, o centro de cir\u00fargico e a torre de interna\u00e7\u00f5es. A abertura da emerg\u00eancia, \u00faltima etapa do cronograma de funcionamento do HRC, est\u00e1 definida para o dia 22 deste m\u00eas.<\/p>\n<p>No outro lado do Cear\u00e1, o Hospital Regional Norte est\u00e1 com as obras em fase de conclus\u00e3o. A previs\u00e3o \u00e9 de ser inaugurado no in\u00edcio de 2012, com 386 leitos e com uma Unidade de Aten\u00e7\u00e3o \u00e0 Sa\u00fade da Mulher. Na Unidade, ser\u00e3o 32 leitos, sendo 12 leitos para parto normal, 10 leitos para partos cir\u00fargicos, nove para m\u00e3es-canguru e um leito de isolamento.<\/p>\n<p><b>Homenagem<\/b><\/p>\n<p>A quarta policl\u00ednica regional inaugurada recebe o nome de Policl\u00ednica Dra. M\u00e1rcia Moreira de Meneses, uma homenagem a m\u00e9dica neurologista, que apesar de ter a vida abreviada por um c\u00e2ncer, falecendo aos 37 anos de idade em 2006, teve participa\u00e7\u00e3o intensa no meio estudantil, acad\u00eamico e profissional. Aos 14 anos atuou no gr\u00eamio do Col\u00e9gio Cearense. Ainda envolvida na luta do movimento estudantil foi diretora da Uni\u00e3o dos Estudantes Secundaristas entre 1982 e 83. Na defesa da categoria dos m\u00e9dicos, assumiu no in\u00edcio de 2004 a secretaria geral do Sindicato dos M\u00e9dicos do Estado do Cear\u00e1.<\/p>\n<p>M\u00e1rcia Moreira de Meneses esteve \u00e0 frente da refer\u00eancia na neuropediatria em pelo menos quatro munic\u00edpios, Fortaleza, Pacajus, Aquiraz e Eus\u00e9bio. Foi neuropediatra em dois hospitais da rede estadual, o Hospital Geral de Fortaleza e o Hospital Infantil Albert Sabin. No curriculo profissional, destaque para o pioneirismo de ser a primeira m\u00e9dica a realizar laudo de morte encef\u00e1lica para a Central de Transplantes do Estado, no ano de 2000. M\u00e1rcia Moreira de Meneses teve dois filhos, Isabelle Meneses da Ponte, e Carlos Nelton Meneses da Ponte, com o m\u00e9dico nefrologista&nbsp; Carlos Nelton da Ponte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a presen\u00e7a da Presidenta Dilma Rousseff, o Governador Cid Gomes inaugura nesta quinta-feira, 11, a Policl\u00ednica Regional em Pacajus, na Regi\u00e3o Metropolitana de Fortaleza, e o Polo 1 do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU (ver mat\u00e9ria Polo do SAMU I cobre 41 munic\u00edpios e 2 milh\u00f5es de habitantes). As inaugura\u00e7\u00f5es ocorrer\u00e3o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Com a presen\u00e7a da Presidenta Dilma Rousseff, o Governador Cid Gomes inaugura nesta quinta-feira, 11, a Policl\u00ednica Regional em Pacajus, na Regi\u00e3o Metropolitana de Fortaleza, e o Polo 1 do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU (ver mat\u00e9ria Polo do SAMU I cobre 41 munic\u00edpios e 2 milh\u00f5es de habitantes). As inaugura\u00e7\u00f5es ocorrer\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-10T15:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11\",\"datePublished\":\"2011-08-10T15:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\"},\"wordCount\":843,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\",\"name\":\"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\",\"datePublished\":\"2011-08-10T15:45:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_poli_pacajus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/","og_locale":"pt_BR","og_type":"article","og_title":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Com a presen\u00e7a da Presidenta Dilma Rousseff, o Governador Cid Gomes inaugura nesta quinta-feira, 11, a Policl\u00ednica Regional em Pacajus, na Regi\u00e3o Metropolitana de Fortaleza, e o Polo 1 do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU (ver mat\u00e9ria Polo do SAMU I cobre 41 munic\u00edpios e 2 milh\u00f5es de habitantes). As inaugura\u00e7\u00f5es ocorrer\u00e3o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-08-10T15:45:53+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11","datePublished":"2011-08-10T15:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/"},"wordCount":843,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/","name":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg","datePublished":"2011-08-10T15:45:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg","width":555,"height":274,"caption":"banner_poli_pacajus"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/10\/cid-inaugura-com-a-presidenta-dilma-policlinica-e-polo-do-samu-dia-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Cid inaugura, com a presidenta Dilma, policl\u00ednica e Polo do SAMU dia 11"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1892"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1887"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}