{"id":1888,"date":"2011-08-11T23:10:42","date_gmt":"2011-08-12T02:10:42","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/"},"modified":"2011-08-11T23:10:42","modified_gmt":"2011-08-12T02:10:42","slug":"cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/","title":{"rendered":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1"},"content":{"rendered":"<p><\/p>\n<p>Na sua primeira visita ao Cear\u00e1 depois de eleita, a presidente Dilma Rousseff, junto do governador Cid Gomes, do Ministro da Sa\u00fade, Alexandre Padilha, do Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos, e do prefeito Pedro Jos\u00e9 Filomeno Gomes, inaugurou na tarde desta quinta-feira, 11 de agosto, em Pacajus, o Polo 1 do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU Cear\u00e1 192) e a Policl\u00ednica Regional Dra. M\u00e1rcia Moreira de Meneses, primeira unidade da expans\u00e3o da rede de sa\u00fade do Estado a receber o nome de uma mulher. A nova policl\u00ednica, que amplia e facilita o acesso aos servi\u00e7os de sa\u00fade para popula\u00e7\u00e3o de 244.747 habitantes de Cascavel, Chorozinho, Horizonte, Ocara, Pindoretama e Pacajus, munic\u00edpios da Regi\u00e3o Metropolitana de Fortaleza, recebeu investimento de R$ 7,1 milh\u00f5es do Tesouro do Estado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1883\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus6.jpg\" alt=\"banner_poli_pacajus6\" height=\"274\" width=\"555\" \/><\/p>\n<p>\u201cComo a presidente Dilma, em sua juventude M\u00e1rcia foi militante, lutou pelos mais necessitados\u201d, lembrou Isabele Ponte, filha de M\u00e1rcia Meneses, tra\u00e7ando paralelo entre a trajet\u00f3ria da m\u00e9dica que d\u00e1 nome \u00e0 policl\u00ednica, falecida em 2006, aos 37 anos, com a hist\u00f3ria da atual Presidente da Rep\u00fablica. Com a nova policl\u00ednica tipo I, a popula\u00e7\u00e3o passa a contar na pr\u00f3pria&nbsp; regi\u00e3o onde mora com assist\u00eancia em dez especialidades m\u00e9dicas: cl\u00ednica geral, cardiologia, ginecologia, mastologia, cirurgia geral, gastroenterologia, urologia, traumato-ortopedia, otorrinolaringologia e oftalmologia. Garantindo aten\u00e7\u00e3o integral, a policl\u00ednica regional realiza exames especializados. Entre eles, mamografia, endoscopia digestiva, ecocardiograma, eletrocardiograma, ergometria, audiometria, ultrassonografia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1884\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao3.jpg\" alt=\"banner_poli_pacajus_inaugurao3\" height=\"274\" width=\"555\" \/><\/p>\n<p>Em reconhecimento ao esfor\u00e7o do Governo do Estado, a presidente Dilma afirmou que \u201co governador Cid Gomes tem realizado uma pol\u00edtica na sa\u00fade que deve ser refer\u00eancia para o Brasil\u201d, acrescentando que \u201co pa\u00eds precisa de ministros e secret\u00e1rios da sa\u00fade como Alexandre Padilha e Arruda Bastos\u201d. A presidente destacou, ainda, a estrutura da policl\u00ednica regional, que disp\u00f5e de equipamentos de \u00faltima gera\u00e7\u00e3o. \u201cN\u00e3o \u00e9 mais poss\u00edvel ter sa\u00fade para rico e sa\u00fade para pobre\u201d, enfatizou Dilma. Ela felicitou os prefeitos dos munic\u00edpios da regi\u00e3o por aderirem ao modelo de gest\u00e3o da nova unidade proposto pelo Governo do Estado, afirmando que, \u201ccom os cons\u00f3rcios, vejo no Cear\u00e1 uma a\u00e7\u00e3o muito inovadora e revolucion\u00e1ria \u2013 a gente est\u00e1 unindo esfor\u00e7os pelo bem dos munic\u00edpios\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1885\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao1.jpg\" alt=\"banner_poli_pacajus_inaugurao1\" height=\"274\" width=\"555\" \/><\/p>\n<p>Antes da presidente Dilma, o ministro Alexandre Padilha j\u00e1 havia reconhecido que \u201co Cear\u00e1 \u00e9 refer\u00eancia no SUS\u201d para todo o pa\u00eds. \u201cSinto muito orgulho de vir ao Cear\u00e1 e entrar em uma unidade do SUS constru\u00edda pelo Governo do Estado\u201d, confessou o ministro. Em seguida, o governador Cid Gomes disse que o seu desejo \u00e9 que \u201co Cear\u00e1 tenha a melhor rede de sa\u00fade p\u00fablica do Brasil at\u00e9 2012\u201d. Cid Gomes recebeu de Dilma Rousseff, simbolicamente, a chave de uma ambul\u00e2ncia para marcar a inaugura\u00e7\u00e3o do Poli 1 do SAMU Cear\u00e1 192 e, junto com a presidente descerrou a placa de inaugura\u00e7\u00e3o da Policl\u00ednica Regional Dra. M\u00e1rcia Moreira de Meneses, que come\u00e7a a atender na primeira semana de setembro, logo ap\u00f3s o treinamento dos profissionais aprovados em sele\u00e7\u00e3o p\u00fablica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1886\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao4.jpg\" alt=\"banner_poli_pacajus_inaugurao4\" height=\"274\" width=\"555\" \/><\/p>\n<p>O Polo I do SAMU Cear\u00e1 192 inclui 41 munic\u00edpios da Regi\u00e3o Metropolitana, do Maci\u00e7o de Baturit\u00e9 e dos litorais Leste e Oeste, com cobertura de 1,7 milh\u00f5es de habitantes. O servi\u00e7o vai atender com 7 unidades de suporte avan\u00e7ado, com UTIs, e 34 de suporte b\u00e1sico. No total, 41 ambul\u00e2ncias. Vinte e duas foram liberadas este ano pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1887\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus.jpg\" alt=\"banner_poli_pacajus\" height=\"274\" width=\"555\" \/><\/p>\n<p>Com a unidade de Pacajus, aumenta para&nbsp; quatro o n\u00famero de policl\u00ednicas regionais j\u00e1 entregues \u00e0 popula\u00e7\u00e3o pelo Governo do Estado. Est\u00e3o em funcionamento as unidades regionais em Baturit\u00e9, Camocim e Tau\u00e1. At\u00e9 o final do pr\u00f3ximo m\u00eas de setembro mais sete policl\u00ednicas ser\u00e3o inauguradas em Campos Sales, Aracati, Acara\u00fa, Russas, Sobral, Itapipoca e Ic\u00f3. H\u00e1 outras 11 unidades em constru\u00e7\u00e3o, al\u00e9m do recente acr\u00e9scimo de mais uma para atender a popula\u00e7\u00e3o da microrregi\u00e3o do Crato, no Cariri. No total, ser\u00e3o 22 policl\u00ednicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na sua primeira visita ao Cear\u00e1 depois de eleita, a presidente Dilma Rousseff, junto do governador Cid Gomes, do Ministro da Sa\u00fade, Alexandre Padilha, do Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos, e do prefeito Pedro Jos\u00e9 Filomeno Gomes, inaugurou na tarde desta quinta-feira, 11 de agosto, em Pacajus, o Polo 1 do Servi\u00e7o de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Na sua primeira visita ao Cear\u00e1 depois de eleita, a presidente Dilma Rousseff, junto do governador Cid Gomes, do Ministro da Sa\u00fade, Alexandre Padilha, do Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos, e do prefeito Pedro Jos\u00e9 Filomeno Gomes, inaugurou na tarde desta quinta-feira, 11 de agosto, em Pacajus, o Polo 1 do Servi\u00e7o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-12T02:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1\",\"datePublished\":\"2011-08-12T02:10:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\"},\"wordCount\":715,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\",\"name\":\"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg\",\"datePublished\":\"2011-08-12T02:10:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_poli_pacajus_inaugurao7\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Na sua primeira visita ao Cear\u00e1 depois de eleita, a presidente Dilma Rousseff, junto do governador Cid Gomes, do Ministro da Sa\u00fade, Alexandre Padilha, do Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos, e do prefeito Pedro Jos\u00e9 Filomeno Gomes, inaugurou na tarde desta quinta-feira, 11 de agosto, em Pacajus, o Polo 1 do Servi\u00e7o de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-08-12T02:10:42+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1","datePublished":"2011-08-12T02:10:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/"},"wordCount":715,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/","name":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg","datePublished":"2011-08-12T02:10:42+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/08\/banner_poli_pacajus_inaugurao7.jpg","width":555,"height":274,"caption":"banner_poli_pacajus_inaugurao7"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/08\/11\/cid-e-dilma-inauguram-em-pacajus-policlinica-e-polo-1-do-samu-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Cid e Dilma inauguram em Pacajus policl\u00ednica e Polo 1 do SAMU Cear\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1888"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1882"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}