{"id":1860,"date":"2016-01-20T03:00:00","date_gmt":"2016-01-20T06:00:00","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/"},"modified":"2016-01-20T03:00:00","modified_gmt":"2016-01-20T06:00:00","slug":"rede-em-construcao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/","title":{"rendered":"Nova rede"},"content":{"rendered":"<p> \t<span style=\"color: #000000;\"><strong><\/p>\n<p> \tHospitais regionais<\/strong><\/p>\n<p> \tA popula\u00e7\u00e3o do interior passou a receber assist\u00eancia hospitalar de alta complexidade perto de casa, sem necessidade de vir para a capital. A desconcentra\u00e7\u00e3o da assist\u00eancia terci\u00e1ria, com a cria\u00e7\u00e3o de uma rede de unidades de grande porte no interior come\u00e7ou em abril de 2011, com a inaugura\u00e7\u00e3o do Hospital Regional do Cariri (HRC), com 294 leitos. O in\u00edcio do funcionamento foi em 23 de maio, com servi\u00e7os pr\u00e9-cir\u00fargico, coleta de exames e ultrassonografia. Avan\u00e7ando no cronograma de funcionamento, a Unidade de Interna\u00e7\u00e3o recebeu os primeiros pacientes no dia 20 de junho. A UTI logo em seguida, dia 23 do mesmo m\u00eas. No HRC, constru\u00eddo para atender casos de alta complexidade dos 44 munic\u00edpios da macrorregi\u00e3o do Cariri, foram investidos R$ 105 milh\u00f5es em recursos do Tesouro do Estado e do Minist\u00e9rio da Sa\u00fade, que financiou R$ 9,5 milh\u00f5es.<\/p>\n<p> \t<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1857\" alt=\"alt\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hospital_regional_norte.png\" style=\"width: 555px; height: 274px;\" width=\"555\" height=\"274\" \/><\/p>\n<p> \tA expans\u00e3o da rede teve sequ\u00eancia com a inaugura\u00e7\u00e3o do Hospital Regional Norte (HRN), o maior hospital do interior da regi\u00e3o Nordeste, com 57.813,70 metros quadrados de \u00e1rea constru\u00edda. Com 382 leitos, o HRN foi inaugurado em janeiro de 2013 e est\u00e1 localizado em Sobral para atender toda a popula\u00e7\u00e3o da regi\u00e3o Norte, num total de 55 munic\u00edpios. L\u00e1, o diferencial em rela\u00e7\u00e3o ao HRC \u00e9 a unidade de aten\u00e7\u00e3o \u00e0 sa\u00fade da mulher. Em obras e equipamentos foram investidos R$ 229.082.947,73, recursos do governo do Estado e de financiamento com o Banco Interamericano de Desenvolvimento (BID). O HRN \u00e9 uma das principais obras do programa de expans\u00e3o e melhoria da assist\u00eancia \u00e0 sa\u00fade da popula\u00e7\u00e3o que o governo do Estado desenvolve na capital e no interior.<\/p>\n<p> \tOutra unidade est\u00e1 programada. O Hospital Regional do Sert\u00e3o Central (HRSC) ser\u00e1 constru\u00eddo em Quixeramobim. Pela primeira vez na hist\u00f3ria do Cear\u00e1, a localiza\u00e7\u00e3o de um hospital foi definida por vota\u00e7\u00e3o. Votaram conselheiros municipais de sa\u00fade, vereadores e prefeitos de quatro munic\u00edpios que disputavam a localiza\u00e7\u00e3o (Boa Viagem Canind\u00e9, Quixad\u00e1 e Quixeramobim). O hospital regional ter\u00e1 perfil tamb\u00e9m terci\u00e1rio. <\/span><\/p>\n<p> \t<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1858\" alt=\"banner_ceo_brejo\" height=\"274\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_ceo_brejo.jpg\" width=\"555\" \/><\/p>\n<p> \t<span style=\"color: #000000;\"><strong>CEOs regionais<\/strong><\/span><\/p>\n<p> \tTodos os novos Centros de Especialidades Odontol\u00f3gicas (CEOs) regionais, no total de 18 constru\u00eddos pelo Governo do Estado em pleno funcionamento em diferentes regi\u00f5es do Cear\u00e1, \u00e9 assegurado e realizado atendimento integral \u00e0s pessoas com defici\u00eancia e \u00e0s pessoas com necessidades especiais. Os CEOs, no total de 22, como unidades regionais, atendem toda a popula\u00e7\u00e3o da regi\u00e3o de sa\u00fade. Est\u00e3o localizados em Acara\u00fa, Aracati, Baturit\u00e9, Brejo Santo, Camocim, Canind\u00e9, Caucaia, Cascavel, Crate\u00fas, Crato, Ic\u00f3, Iguatu, Itapipoca, Juazeiro do Norte, Limoeiro Norte, Maracana\u00fa, Quixeramobim, Russas, Sobral, S\u00e3o Gon\u00e7alo do Amarante, Tau\u00e1 e Ubajara.<\/p>\n<p> \tCom 11 consult\u00f3rios, cada CEO presta assist\u00eancia nas seguintes especialidades odontol\u00f3gicas: pacientes portadores de necessidades especiais, endodontia, ortodontia, periodontia, cirurgia bucomaxilofacial e pr\u00f3tese.<\/p>\n<p> \t\u00a0<\/p>\n<p> \t<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1859\" alt=\"banner_poli_baturite\" height=\"274\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_poli_baturite.jpg\" width=\"555\" \/><\/p>\n<p> \t<span style=\"color: #000000;\"><strong>Policl\u00ednicas regionais<\/strong><\/span><\/p>\n<p> \tAs policl\u00ednicas regionais est\u00e3o sendo implantadas pelo governo do Estado com infraestrutura adequada para atender as principais especialidades m\u00e9dicas de interesse epidemiol\u00f3gico no Cear\u00e1 e com servi\u00e7os de suporte ao diagn\u00f3stico e reabilita\u00e7\u00e3o dos pacientes atendidos. J\u00e1 s\u00e3o 19 policl\u00ednicas funcionando em Baturit\u00e9, Tau\u00e1, Camocim, Acara\u00fa, Brejo Santo, Aracati, Itapipoca, Russas, Crate\u00fas, Quixad\u00e1, Caucaia, Sobral, Campos Sales, Pacajus, Barbalha, Tiangu\u00e1, Ic\u00f3, Iguatu e Limoeiro do Norte. Outras tr\u00eas est\u00e3o em constru\u00e7\u00e3o em Canind\u00e9, Maracana\u00fa e Crato.<\/p>\n<p> \tA constru\u00e7\u00e3o de 22 policl\u00ednicas faz toda diferen\u00e7a na assist\u00eancia \u00e0 m\u00e9dia complexidade. Al\u00e9m de facilitar o acesso ao especialista em diferentes \u00e1reas, a popula\u00e7\u00e3o realiza na pr\u00f3pria regi\u00e3o onde mora exames oferecidos somente na capital. S\u00e3o 22 policl\u00ednicas regionais com infraestrutura adequada para atender as principais especialidades m\u00e9dicas de interesse epidemiol\u00f3gico no Estado e com servi\u00e7os de suporte ao diagn\u00f3stico e reabilita\u00e7\u00e3o dos pacientes atendidos.<\/p>\n<p> \tNas policl\u00ednicas tipo I, os ambulat\u00f3rios especializados oferecem atendimento em oftalmologia, otorrino, cl\u00ednica geral, cardiologia, ginecologia, mastologia, cirurgia geral, gastroenterologia, urologia, traumato-ortopedia. H\u00e1 apoio t\u00e9cnico de enfermagem, farm\u00e1cia cl\u00ednica, terapia ocupacional, fisioterapia, fonoaudiologia, nutri\u00e7\u00e3o, psicologia e assist\u00eancia social. Os servi\u00e7os de apoio diagn\u00f3stico e terap\u00eautico ser\u00e3o radiologia convencional, mamografia, ultrassonografia, endoscopia digestiva, ecocardiografia, ergometria, eletrocardiograma, audiometria e coleta de patologia cl\u00ednica.<\/p>\n<p> \tAs policl\u00ednicas tipo II, instaladas nas microrregi\u00f5es de maior densidade populacional, oferecem, al\u00e9m de todos os servi\u00e7os das policl\u00ednicas tipo I, atendimento em endocrinologia, angiologia e neurologia e, em destaque, os servi\u00e7os de tomografia computadorizada, eletroencefalograma e endoscopia respirat\u00f3ria.<\/p>\n<p> \tO encaminhamento de pacientes para os CEOs e as policl\u00ednicas \u00e9 feito pelas secretarias municipais de sa\u00fade, a partir da solicita\u00e7\u00e3o de consultas e exames feitos pelos m\u00e9dicos e dentistas da aten\u00e7\u00e3o b\u00e1sica de sa\u00fade. No agendamento, o paciente escolhe data e hor\u00e1rio para a consulta ou exame, de acordo com a disponibilidade de vagas.<\/p>\n<p> \tA distribui\u00e7\u00e3o de vagas para atendimento \u00e9 proporcional \u00e0 popula\u00e7\u00e3o de cada munic\u00edpio. Toda a regula\u00e7\u00e3o \u00e9 feita por computador pelo Sisreg III, sistema on-line criado pelo Minist\u00e9rio da Sa\u00fade para o gerenciamento de todo complexo regulat\u00f3rio indo da rede b\u00e1sica \u00e0 interna\u00e7\u00e3o hospitalar, visando a humaniza\u00e7\u00e3o dos servi\u00e7os, maior controle do fluxo e otimiza\u00e7\u00e3o na utiliza\u00e7\u00e3o dos recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hospitais regionais A popula\u00e7\u00e3o do interior passou a receber assist\u00eancia hospitalar de alta complexidade perto de casa, sem necessidade de vir para a capital. A desconcentra\u00e7\u00e3o da assist\u00eancia terci\u00e1ria, com a cria\u00e7\u00e3o de uma rede de unidades de grande porte no interior come\u00e7ou em abril de 2011, com a inaugura\u00e7\u00e3o do Hospital Regional do Cariri [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sesa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova rede - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova rede - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Hospitais regionais A popula\u00e7\u00e3o do interior passou a receber assist\u00eancia hospitalar de alta complexidade perto de casa, sem necessidade de vir para a capital. A desconcentra\u00e7\u00e3o da assist\u00eancia terci\u00e1ria, com a cria\u00e7\u00e3o de uma rede de unidades de grande porte no interior come\u00e7ou em abril de 2011, com a inaugura\u00e7\u00e3o do Hospital Regional do Cariri [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-20T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"557\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Nova rede\",\"datePublished\":\"2016-01-20T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\"},\"wordCount\":907,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg\",\"articleSection\":[\"Sesa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\",\"name\":\"Nova rede - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg\",\"datePublished\":\"2016-01-20T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg\",\"width\":557,\"height\":277,\"caption\":\"banner_hrc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nova rede\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nova rede - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/","og_locale":"pt_BR","og_type":"article","og_title":"Nova rede - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Hospitais regionais A popula\u00e7\u00e3o do interior passou a receber assist\u00eancia hospitalar de alta complexidade perto de casa, sem necessidade de vir para a capital. A desconcentra\u00e7\u00e3o da assist\u00eancia terci\u00e1ria, com a cria\u00e7\u00e3o de uma rede de unidades de grande porte no interior come\u00e7ou em abril de 2011, com a inaugura\u00e7\u00e3o do Hospital Regional do Cariri [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2016-01-20T06:00:00+00:00","og_image":[{"width":557,"height":277,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Nova rede","datePublished":"2016-01-20T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/"},"wordCount":907,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg","articleSection":["Sesa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/","name":"Nova rede - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg","datePublished":"2016-01-20T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2016\/01\/banner_hrc.jpg","width":557,"height":277,"caption":"banner_hrc"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2016\/01\/20\/rede-em-construcao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Nova rede"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1860"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1856"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}