{"id":1819,"date":"2011-07-25T16:59:58","date_gmt":"2011-07-25T19:59:58","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/"},"modified":"2011-07-25T16:59:58","modified_gmt":"2011-07-25T19:59:58","slug":"modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/","title":{"rendered":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia"},"content":{"rendered":"<\/p>\n<p>O Conselho Nacional de Secret\u00e1rios de Sa\u00fade vai conhecer a experi\u00eancia de cons\u00f3rcios p\u00fablicos de sa\u00fade do Cear\u00e1. A apresenta\u00e7\u00e3o acontecer\u00e1 durante a 6\u00aa Assembleia do Conass, nesta quarta-feira, 27, \u00e0s 9h30min, no audit\u00f3rio da Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade (OPAS), em Bras\u00edlia. Al\u00e9m do secret\u00e1rio da Sa\u00fade do Estado e vice-presidente do Conass na regi\u00e3o Nordeste, Arruda Bastos, participam da apresenta\u00e7\u00e3o do modelo de gest\u00e3o adotado nas policl\u00ednicas e Centros de Especialidades Odontol\u00f3gicas regionais, constru\u00eddos pelo governo do Estado, o secret\u00e1rio adjunto Haroldo Pontes, a secret\u00e1ria executiva Rosa Moraes e a assessora jur\u00eddica F\u00e1tima Nogueira.<\/p>\n<p>O Cear\u00e1 decidiu pela forma\u00e7\u00e3o de cons\u00f3rcios p\u00fablicos em sa\u00fade, tomando por base os munic\u00edpios localizados numa mesma microrregi\u00e3o de sa\u00fade para garantir a&nbsp; estrutura\u00e7\u00e3o de redes de assist\u00eancia e ampliar e facilitar o acesso da popula\u00e7\u00e3o aos servi\u00e7os de sa\u00fade na pr\u00f3pria regi\u00e3o. O Governo do Estado participa dos cons\u00f3rcios em todas as 21 regionais de sa\u00fade, onde&nbsp; est\u00e1 construindo uma das maiores redes de assist\u00eancia do pa\u00eds. Nela est\u00e3o inclu\u00eddas as 22 policl\u00ednicas e 18 CEOs regionais com a gest\u00e3o via cons\u00f3rcios p\u00fablicos. Na manuten\u00e7\u00e3o financeira, o Estado participa com 40% do custeio de cada policl\u00ednica e cada CEO. &nbsp;<\/p>\n<p>Os cons\u00f3rcios s\u00e3o constitu\u00eddos sob a forma de associa\u00e7\u00e3o p\u00fablica, entidade aut\u00e1rquica e interfederativa, para a promo\u00e7\u00e3o de a\u00e7\u00f5es de sa\u00fade p\u00fablica assistenciais e presta\u00e7\u00e3o de servi\u00e7os especializados de m\u00e9dia e alta complexidade. A forma\u00e7\u00e3o dos cons\u00f3rcios compreende uma s\u00e9rie de etapas. Ap\u00f3s a assinatura do Protocolo de Inten\u00e7\u00f5es, o documento dever\u00e1 ser ratificado pelo Poder Legislativo de cada ente consorciado, o que o transforma na Lei do respectivo cons\u00f3rcio. Em seguida s\u00e3o elaborados o Estatuto e o Regimento Interno e feita a pactua\u00e7\u00e3o do Contrato de Programa, obriga\u00e7\u00f5es referentes a encargos, servi\u00e7os e bens necess\u00e1rios \u00e0 implementa\u00e7\u00e3o do cons\u00f3rcio. Na etapa seguinte, o Contrato de Rateio tem a finalidade de estabelecer obriga\u00e7\u00f5es financeiras, os compromissos da aplica\u00e7\u00e3o dos recursos pelos entes consorciados. A partir da\u00ed s\u00e3o definidas a dota\u00e7\u00e3o or\u00e7ament\u00e1ria espec\u00edfica ou cr\u00e9ditos adicionais por cada ente consorciado. Ap\u00f3s organizado e estruturado, o cons\u00f3rcio come\u00e7a a funcionar.<\/p>\n<p>Todas as 21 microrregi\u00f5es de sa\u00fade do Estado j\u00e1 criaram seus cons\u00f3rcios intermunicipais e os onze&nbsp; j\u00e1 implantados administram os CEOs de Juazeiro do Norte, Baturit\u00e9, Acara\u00fa, Sobral, Camocim, Ubajara, Russas, Brejo Santo e as policl\u00ednicas regionais de Tau\u00e1, Baturit\u00e9 e Camocim, todas essas unidades em pleno funcionamento. Em Sobral, a administra\u00e7\u00e3o do CEO tem participa\u00e7\u00e3o da Universidade Federal do Cear\u00e1 (UFC) como ente consorciado. Comitivas dos estados de Alagoas e do Maranh\u00e3o j\u00e1 visitaram o Cear\u00e1 este ano para conhecer a experi\u00eancia local dos cons\u00f3rcios p\u00fablicos de sa\u00fade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Secret\u00e1rios de Sa\u00fade vai conhecer a experi\u00eancia de cons\u00f3rcios p\u00fablicos de sa\u00fade do Cear\u00e1. A apresenta\u00e7\u00e3o acontecer\u00e1 durante a 6\u00aa Assembleia do Conass, nesta quarta-feira, 27, \u00e0s 9h30min, no audit\u00f3rio da Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade (OPAS), em Bras\u00edlia. Al\u00e9m do secret\u00e1rio da Sa\u00fade do Estado e vice-presidente do Conass na regi\u00e3o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Conselho Nacional de Secret\u00e1rios de Sa\u00fade vai conhecer a experi\u00eancia de cons\u00f3rcios p\u00fablicos de sa\u00fade do Cear\u00e1. A apresenta\u00e7\u00e3o acontecer\u00e1 durante a 6\u00aa Assembleia do Conass, nesta quarta-feira, 27, \u00e0s 9h30min, no audit\u00f3rio da Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade (OPAS), em Bras\u00edlia. Al\u00e9m do secret\u00e1rio da Sa\u00fade do Estado e vice-presidente do Conass na regi\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-25T19:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia\",\"datePublished\":\"2011-07-25T19:59:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\"},\"wordCount\":543,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\",\"name\":\"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg\",\"datePublished\":\"2011-07-25T19:59:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_ceo_brejo_poli_taua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/","og_locale":"pt_BR","og_type":"article","og_title":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O Conselho Nacional de Secret\u00e1rios de Sa\u00fade vai conhecer a experi\u00eancia de cons\u00f3rcios p\u00fablicos de sa\u00fade do Cear\u00e1. A apresenta\u00e7\u00e3o acontecer\u00e1 durante a 6\u00aa Assembleia do Conass, nesta quarta-feira, 27, \u00e0s 9h30min, no audit\u00f3rio da Organiza\u00e7\u00e3o Pan-Americana da Sa\u00fade (OPAS), em Bras\u00edlia. Al\u00e9m do secret\u00e1rio da Sa\u00fade do Estado e vice-presidente do Conass na regi\u00e3o [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-07-25T19:59:58+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia","datePublished":"2011-07-25T19:59:58+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/"},"wordCount":543,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/","name":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg","datePublished":"2011-07-25T19:59:58+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_ceo_brejo_poli_taua.jpg","width":555,"height":274,"caption":"banner_ceo_brejo_poli_taua"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/25\/modelo-de-gestao-de-policlinicas-e-ceos-e-apresentado-no-conass-em-brasilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Modelo de gest\u00e3o de policl\u00ednicas e CEOs \u00e9 apresentado no Conass, em Bras\u00edlia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1819"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1818"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}