{"id":1725,"date":"2011-07-12T10:54:53","date_gmt":"2011-07-12T13:54:53","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/"},"modified":"2011-07-12T10:54:53","modified_gmt":"2011-07-12T13:54:53","slug":"vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/","title":{"rendered":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria"},"content":{"rendered":"<p><\/p>\n<p>O vice-presidente do CONASS na regi\u00e3o Nordeste e tamb\u00e9m secret\u00e1rio de estado do Cear\u00e1, Raimundo Arruda Bastos, participou nesta segunda (11) da mesa \u2013 Valoriza\u00e7\u00e3o, qualifica\u00e7\u00e3o e fortalecimento da Aten\u00e7\u00e3o B\u00e1sica &#8211; durante o XXVII Congresso do Conasems. O secret\u00e1rio fez um breve hist\u00f3rico sobre a Aten\u00e7\u00e3o B\u00e1sica, sobre a evolu\u00e7\u00e3o do Programa da Sa\u00fade da Fam\u00edlia (PSF) e falou da import\u00e2ncia dos agentes comunit\u00e1rios da sa\u00fade na Aten\u00e7\u00e3o B\u00e1sica.<\/p>\n<p>Para o secret\u00e1rio, a sa\u00fade vive um momento importante e o encontro \u00e9 uma \u00f3tima oportunidade para debater sobre o fortalecimento da Aten\u00e7\u00e3o B\u00e1sica, al\u00e9m das novas pactua\u00e7\u00f5es junto com Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>Segundo ele, os resultados no Cear\u00e1 s\u00e3o positivos com a Estrat\u00e9gia Sa\u00fade da Fam\u00edlia e a participa\u00e7\u00e3o dos agentes comunit\u00e1rios na Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade. \u201cHouve uma redu\u00e7\u00e3o da mortalidade infantil. Em 1994, quando surgiu o PSF, a Taxa de Mortalidade Infantil no Cear\u00e1 era de 50 por mil crian\u00e7as nascidas vivas. Em 2009 ficou em 15,5\u201d, ressaltou.<\/p>\n<p>Na apresenta\u00e7\u00e3o Bastos destacou o compromisso de valorizar os profissionais da aten\u00e7\u00e3o prim\u00e1ria e promover os agentes comunit\u00e1rios. \u201cDesde abril de 2008 os agentes passaram a ter v\u00ednculo com a Secretaria da Sa\u00fade do Estado e recebem contracheques da Sesa\u201d, destacou.<\/p>\n<p><i><b>Assessoria de Comunica\u00e7\u00e3o do Conass<\/b><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vice-presidente do CONASS na regi\u00e3o Nordeste e tamb\u00e9m secret\u00e1rio de estado do Cear\u00e1, Raimundo Arruda Bastos, participou nesta segunda (11) da mesa \u2013 Valoriza\u00e7\u00e3o, qualifica\u00e7\u00e3o e fortalecimento da Aten\u00e7\u00e3o B\u00e1sica &#8211; durante o XXVII Congresso do Conasems. O secret\u00e1rio fez um breve hist\u00f3rico sobre a Aten\u00e7\u00e3o B\u00e1sica, sobre a evolu\u00e7\u00e3o do Programa da Sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O vice-presidente do CONASS na regi\u00e3o Nordeste e tamb\u00e9m secret\u00e1rio de estado do Cear\u00e1, Raimundo Arruda Bastos, participou nesta segunda (11) da mesa \u2013 Valoriza\u00e7\u00e3o, qualifica\u00e7\u00e3o e fortalecimento da Aten\u00e7\u00e3o B\u00e1sica &#8211; durante o XXVII Congresso do Conasems. O secret\u00e1rio fez um breve hist\u00f3rico sobre a Aten\u00e7\u00e3o B\u00e1sica, sobre a evolu\u00e7\u00e3o do Programa da Sa\u00fade [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-12T13:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria\",\"datePublished\":\"2011-07-12T13:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\",\"name\":\"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg\",\"datePublished\":\"2011-07-12T13:54:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/","og_locale":"pt_BR","og_type":"article","og_title":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O vice-presidente do CONASS na regi\u00e3o Nordeste e tamb\u00e9m secret\u00e1rio de estado do Cear\u00e1, Raimundo Arruda Bastos, participou nesta segunda (11) da mesa \u2013 Valoriza\u00e7\u00e3o, qualifica\u00e7\u00e3o e fortalecimento da Aten\u00e7\u00e3o B\u00e1sica &#8211; durante o XXVII Congresso do Conasems. O secret\u00e1rio fez um breve hist\u00f3rico sobre a Aten\u00e7\u00e3o B\u00e1sica, sobre a evolu\u00e7\u00e3o do Programa da Sa\u00fade [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-07-12T13:54:53+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria","datePublished":"2011-07-12T13:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/"},"wordCount":257,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/","name":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg","datePublished":"2011-07-12T13:54:53+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/07\/banner_.jpg","width":555,"height":274,"caption":"banner_"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/07\/12\/vice-presidente-do-conass-destaca-papel-dos-acss-na-melhoria-da-atencao-primaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Vice-presidente do Conass destaca papel dos ACSs na melhoria da aten\u00e7\u00e3o prim\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1725"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1724"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}