{"id":1608,"date":"2011-06-20T14:20:07","date_gmt":"2011-06-20T17:20:07","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/"},"modified":"2011-06-20T14:20:07","modified_gmt":"2011-06-20T17:20:07","slug":"seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/","title":{"rendered":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1"},"content":{"rendered":"<\/p>\n<p>Entender se realmente faltam profissionais de sa\u00fade p\u00fablica na capital e no interior ou se eles est\u00e3o apenas mal distribu\u00eddos \u00e9 um dos objetivos do Semin\u00e1rio de Planejamento, Monitoramento e Avalia\u00e7\u00e3o da For\u00e7a de Trabalho em Sa\u00fade no Cear\u00e1, promovido pela Secretaria Estadual da Sa\u00fade e pela Escola de Sa\u00fade P\u00fablica, em parceria com a Secretaria de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade do Minist\u00e9rio da Sa\u00fade (SGETS) e a Organiza\u00e7\u00e3o Pan-americana da Sa\u00fade (OPAS). O semin\u00e1rio ser\u00e1 realizado ter\u00e7a e quarta-feira, 21 e 22 de junho, a partir das 8 horas, no Hotel Mareiro, Avenida Beira Mar 2380, Meireles, reunindo representantes de todas as institui\u00e7\u00f5es formadoras de profissionais de sa\u00fade, das secretarias municipais de Sa\u00fade e Educa\u00e7\u00e3o, al\u00e9m de estudantes e pesquisadores de institui\u00e7\u00f5es formadoras da \u00e1rea de sa\u00fade.<\/p>\n<p>Al\u00e9m de mapear a distribui\u00e7\u00e3o de recursos humanos na rede de servi\u00e7os do Cear\u00e1, a realiza\u00e7\u00e3o do Semin\u00e1rio \u00e9 o primeiro passo para a constru\u00e7\u00e3o de ferramentas que possibilitem o acompanhamento da presen\u00e7a e atua\u00e7\u00e3o de profissionais de sa\u00fade em todo o territ\u00f3rio estadual, possibilitando a constru\u00e7\u00e3o de pol\u00edticas p\u00fablicas de sa\u00fade e educa\u00e7\u00e3o eficazes para o funcionamento do Sistema \u00danico de Sa\u00fade.<\/p>\n<p>Ao identificar os pontos cr\u00edticos da for\u00e7a de trabalho, o Semin\u00e1rio pretende construir uma integra\u00e7\u00e3o vi\u00e1vel entre os v\u00e1rios setores que produzem informa\u00e7\u00f5es a respeito da for\u00e7a de trabalho, como as escolas e universidades e as institui\u00e7\u00f5es que, de fato, organizam o mercado, como a Secretaria Estadual e as Secretarias Municipais de Sa\u00fade. Uma vez constru\u00eddos os mecanismos de acompanhamento, ser\u00e1 poss\u00edvel planejar a forma e a quantidade de profissionais necess\u00e1rios para manter os servi\u00e7os em funcionamento.<\/p>\n<p>Durante o Semin\u00e1rio ser\u00e1 apresentado o retrato do setor sa\u00fade no Cear\u00e1, com foco na \u00e1rea t\u00e9cnica, constru\u00eddo pela Coordenadoria de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade no Cear\u00e1, em parceria com o Projeto de Coopera\u00e7\u00e3o T\u00e9cnica Brasil Canad\u00e1. O Observat\u00f3rio de Recursos Humanos em Sa\u00fade (ObservaRH), gerenciado pelo Minist\u00e9rio da Sa\u00fade, apresentar\u00e1 resultados de pesquisas desenvolvidas por sua representa\u00e7\u00e3o no Cear\u00e1 e as experi\u00eancias a partir da cria\u00e7\u00e3o das Salas de Situa\u00e7\u00e3o em todo o Brasil. Tamb\u00e9m ser\u00e3o divulgados os panoramas de vagas na p\u00f3s gradua\u00e7\u00e3o, gradua\u00e7\u00e3o, n\u00edvel t\u00e9cnico e n\u00edvel m\u00e9dio no Cear\u00e1, por institui\u00e7\u00f5es de ensino como a ESP-CE e a Universidade Estadual do Cear\u00e1.<\/p>\n<p>De posse dos dados, os participantes v\u00e3o construir indicadores de acompanhamento da for\u00e7a de trabalho, identificando necessidades de pesquisas nas \u00e1reas da gest\u00e3o do trabalho, da forma\u00e7\u00e3o e da educa\u00e7\u00e3o permanente de recursos humanos.<\/p>\n<p><b>PROGRAMA\u00c7\u00c3O<\/b><\/p>\n<p><b>Dia 21 de Junho (ter\u00e7a-feira):<\/b><\/p>\n<p><b>8 horas<\/b> &#8211; Credenciamento<\/p>\n<p><b>8h30min<\/b> &#8211; Mesa de Abertura:<br \/> Dra. Ana Paula Cerca &#8211; SGTES &#8211; Minist\u00e9rio da Sa\u00fade<br \/> Dr. F\u00e9lix Rigoli &#8211; OPAS<br \/> Dr. Carlile Lavor &#8211; FIOCRUZ<br \/> Dr. Ivo Ferreira Gomes &#8211; Chefe de Gabinete do Governo do Estado<br \/> Dr. Arruda Bastos &#8211; Secret\u00e1rio Estadual de Sa\u00fade do Cear\u00e1<br \/> Dra. L\u00facia Arruda &#8211; Coordenadora de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade<br \/> Dra. Ivana Barreto &#8211; Superintendente da ESP\/CE<\/p>\n<p><b>10 horas<\/b> &#8211; Painel I &#8211; Situa\u00e7\u00e3o atual da For\u00e7a de Trabalho em Sa\u00fade no Cear\u00e1<br \/>Coordenadora: Fernanda Martins &#8211; SESA-CE<\/p>\n<p><b>Tema I &#8211; Retrato do Setor Sa\u00fade no Cear\u00e1<\/b><br \/>Dra. L\u00facia Arruda &#8211; CGTES<\/p>\n<p><b>Tema II &#8211; Observat\u00f3rio de Recursos Humanos em Sa\u00fade:<\/b><br \/><b>Resultados de Pesquisas<\/b><br \/>Dr. Jo\u00e3o Bosco &#8211; ORH<\/p>\n<p><b>Tema III &#8211; Necessidades Sentidas pelos Gestores Municipais<\/b><br \/>Dr. Willames Freire &#8211; COSEMS<\/p>\n<p><b>Tema IV &#8211; Necessidades de Profissionais de Sa\u00fade Consequente \u00e0 Expans\u00e3o da Rede Estadual de Sa\u00fade<\/b><br \/>Dr. Regis S\u00e1 &#8211; SESA\/CE<\/p>\n<p><b>11h30min &#8211; 12h00min<\/b> &#8211; Debate<\/p>\n<p><b>13h30min<\/b> &#8211; Painel II &#8211; Ofertas de Forma\u00e7\u00e3o em Sa\u00fade no Cear\u00e1<br \/>Coordenador: Professor Ricardo Pontes &#8211; UFC-CE<\/p>\n<p><b>Tema I<\/b> &#8211; Oferta de vagas na gradua\u00e7\u00e3o em Sa\u00fade no Estado do Cear\u00e1<br \/>Dra. Ivana Barreto &#8211; ESP\/CE<\/p>\n<p><b>Tema II <\/b>&#8211; Oferta de vagas no n\u00edvel t\u00e9cnico em sa\u00fade no Estado do Cear\u00e1<br \/>Dra Socorro Dias &#8211; EFSFVS<\/p>\n<p><b>Tema III<\/b> &#8211; Oferta de vagas no ensino m\u00e9dio integrado ao ensino t\u00e9cnico em sa\u00fade<br \/>Dra Andrea Rocha &#8211; SEDUC<\/p>\n<p><b>Tema IV<\/b> &#8211; Oferta de vagas na p\u00f3s-gradua\u00e7\u00e3o em sa\u00fade no Estado do Cear\u00e1<br \/>Professor Jackson Sampaio &#8211; UECE<\/p>\n<p><b>15 horas \u00e0s 15h30<\/b> &#8211; Debate<\/p>\n<p><b>16 horas<\/b> &#8211; Painel III &#8211; Sistemas de Informa\u00e7\u00e3o sobre a For\u00e7a de Trabalho em Sa\u00fade no Brasil.<br \/>Coordenador: Newton Kleper de Oliveira &#8211; SESA-CE<\/p>\n<p><b>Tema I &#8211; Sistemas de Informa\u00e7\u00e3o sobre a For\u00e7a de Trabalho em Sa\u00fade no Estado do Cear\u00e1<\/b><br \/>Gotardo Vasconcelos &#8211; COAFI- SESA-CE<\/p>\n<p><b>Tema II &#8211; Plataforma Arouca<\/b><br \/>Dr. Francisco Cardoso &#8211; UnaSUS<\/p>\n<p><b>Tema III &#8211; Sistema de Planejamento de Recursos Humanos para Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade<\/b><br \/>Dr. Rafael Augusto Aguiar &#8211; NESCON\/MG<\/p>\n<p><b>Dia 22 de Junho (quarta-feira):<\/b><\/p>\n<p><b>8h30min<\/b> &#8211; Painel IV &#8211; Modelos de Planejamento, Monitoramento e Avalia\u00e7\u00e3o da For\u00e7a de Trabalho em Sa\u00fade.<br \/>Coordenadora: Dra. Ivana Barreto &#8211; ESP\/CE<\/p>\n<p><b>Tema I<\/b> &#8211; Perspectivas para o Brasil<br \/>Dra. Ana Paula Cerca- SGTES<\/p>\n<p><b>Tema II <\/b>&#8211; Experi\u00eancias da OPAS<br \/>Dr. Marivand Pinto e Augusto Campos &#8211; OPAS<\/p>\n<p><b>10h30min<\/b> &#8211; Apresenta\u00e7\u00e3o das Experi\u00eancias dos Observat\u00f3rios: (30 min)<br \/>Esta\u00e7\u00e3o Observat\u00f3rio &#8211; Dr. S\u00e1bado Girardi &#8211; NESCON\/UFMG<br \/>Observat\u00f3rio dos T\u00e9cnicos em Sa\u00fade &#8211; Dra. M\u00f4nica Vieira -EPSJV\/FIOCRUZ<br \/>Observat\u00f3rio de Recursos Humanos de S\u00e3o Paulo &#8211; Dr. Paulo Seixas<\/p>\n<p><b>11 horas<\/b> &#8211; Grupos de Trabalho<\/p>\n<p><b>GT 1<\/b> &#8211; Constru\u00e7\u00e3o de indicadores de monitoramento e avalia\u00e7\u00e3o da for\u00e7a de trabalho em atividade<\/p>\n<p><b>GT 2<\/b> &#8211; Constru\u00e7\u00e3o de indicadores de monitoramento e avalia\u00e7\u00e3o da forma\u00e7\u00e3o de profissionais em sa\u00fade<\/p>\n<p><b>GT 3<\/b> &#8211; Identificando necessidades de pesquisas na \u00e1rea da gest\u00e3o do trabalho e de educa\u00e7\u00e3o de RH<\/p>\n<p><b>GT 4 <\/b>&#8211; Constru\u00e7\u00e3o de instrumentos de avalia\u00e7\u00e3o dos processos formativos para Educa\u00e7\u00e3o Permanente.<\/p>\n<p><b>12h30min &#8211; 13h30min<\/b> &#8211; Intervalo Almo\u00e7o<\/p>\n<p><b>13h30min<\/b> &#8211; Grupos de Trabalho<\/p>\n<p><b>GT 1<\/b> &#8211; Constru\u00e7\u00e3o de indicadores de monitoramento e avalia\u00e7\u00e3o da for\u00e7a de trabalho em atividade<\/p>\n<p><b>GT 2<\/b> &#8211; Constru\u00e7\u00e3o de indicadores de monitoramento e avalia\u00e7\u00e3o da forma\u00e7\u00e3o de profissionais em sa\u00fade<\/p>\n<p><b>GT 3<\/b> &#8211; Identificando necessidades de pesquisas na \u00e1rea da gest\u00e3o do trabalho e de educa\u00e7\u00e3o de RH<\/p>\n<p><b>GT 4<\/b> &#8211; Constru\u00e7\u00e3o de instrumentos de avalia\u00e7\u00e3o dos processos formativos para Educa\u00e7\u00e3o Permanente.<\/p>\n<p><b>16 horas as 18h00min<\/b> &#8211; Plen\u00e1ria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entender se realmente faltam profissionais de sa\u00fade p\u00fablica na capital e no interior ou se eles est\u00e3o apenas mal distribu\u00eddos \u00e9 um dos objetivos do Semin\u00e1rio de Planejamento, Monitoramento e Avalia\u00e7\u00e3o da For\u00e7a de Trabalho em Sa\u00fade no Cear\u00e1, promovido pela Secretaria Estadual da Sa\u00fade e pela Escola de Sa\u00fade P\u00fablica, em parceria com a [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Entender se realmente faltam profissionais de sa\u00fade p\u00fablica na capital e no interior ou se eles est\u00e3o apenas mal distribu\u00eddos \u00e9 um dos objetivos do Semin\u00e1rio de Planejamento, Monitoramento e Avalia\u00e7\u00e3o da For\u00e7a de Trabalho em Sa\u00fade no Cear\u00e1, promovido pela Secretaria Estadual da Sa\u00fade e pela Escola de Sa\u00fade P\u00fablica, em parceria com a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-20T17:20:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1\",\"datePublished\":\"2011-06-20T17:20:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\"},\"wordCount\":1179,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\",\"name\":\"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg\",\"datePublished\":\"2011-06-20T17:20:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_sus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/","og_locale":"pt_BR","og_type":"article","og_title":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Entender se realmente faltam profissionais de sa\u00fade p\u00fablica na capital e no interior ou se eles est\u00e3o apenas mal distribu\u00eddos \u00e9 um dos objetivos do Semin\u00e1rio de Planejamento, Monitoramento e Avalia\u00e7\u00e3o da For\u00e7a de Trabalho em Sa\u00fade no Cear\u00e1, promovido pela Secretaria Estadual da Sa\u00fade e pela Escola de Sa\u00fade P\u00fablica, em parceria com a [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-06-20T17:20:07+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1","datePublished":"2011-06-20T17:20:07+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/"},"wordCount":1179,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/","name":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1 - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg","datePublished":"2011-06-20T17:20:07+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/06\/banner_sus.jpg","width":555,"height":274,"caption":"banner_sus"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/06\/20\/seminario-vai-mapear-a-forca-de-trabalho-do-sus-no-ceara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Semin\u00e1rio vai mapear a for\u00e7a de trabalho do SUS no Cear\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1608"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1607"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}