{"id":140763,"date":"2025-02-28T08:30:11","date_gmt":"2025-02-28T11:30:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=140763"},"modified":"2025-02-28T17:09:20","modified_gmt":"2025-02-28T20:09:20","slug":"hospitais-regionais-sesa-se-preparam-para-o-carnaval","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/","title":{"rendered":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes"},"content":{"rendered":"<p style=\"text-align: center\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-140767\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia-600x450.jpeg\" alt=\"\" width=\"775\" height=\"581\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia-600x450.jpeg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia-1200x900.jpeg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia-768x576.jpeg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia-1536x1152.jpeg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg 1600w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/>H\u00e1 um aumento na complexidade e na gravidade do paciente admitido durante o Carnaval<\/em><\/p>\n<p>Durante os dias de <strong>Carnaval<\/strong>, o <strong>Hospital Regional Vale do Jaguaribe (HRVJ)<\/strong>, unidade da <strong>Secretaria da Sa\u00fade do Cear\u00e1 (Sesa)<\/strong>, em Limoeiro do Norte, manter\u00e1 uma equipe de prontid\u00e3o nos setores de <strong>urg\u00eancia e emerg\u00eancia<\/strong>, al\u00e9m dos profissionais de plant\u00e3o. A mobiliza\u00e7\u00e3o se faz necess\u00e1ria tendo em vista que o maior Carnaval do estado acontece em Aracati, munic\u00edpio atendido pela unidade.<\/p>\n<p>O diretor-geral, Bergson Moura, pondera que, no per\u00edodo, h\u00e1 um aumento n\u00e3o em n\u00famero de admiss\u00f5es, mas de gravidade dos casos. \u201cComo planejamento para dar suporte nas demandas de urg\u00eancia, a unidade funcionar\u00e1 com seis m\u00e9dicos ortopedistas no plant\u00e3o, tr\u00eas cirurgi\u00f5es gerais se revezando nas urg\u00eancias, cinco m\u00e9dicos anestesistas, dois neurocirurgi\u00f5es, dois cirurgi\u00f5es vasculares, um cirurgi\u00e3o bucomaxilofacial e quatro m\u00e9dicos emergencistas para dar suporte inicial ventilat\u00f3rio e hemodin\u00e2mico. Em caso de cat\u00e1strofe, h\u00e1 tamb\u00e9m o acionamento de profissionais extras para atuar no socorro \u00e0s v\u00edtimas\u201d, explica.<\/p>\n<h3><strong>Uso de capacete diminui mortalidade em acidentes envolvendo moto<\/strong><\/h3>\n<p>De sexta (21) para domingo (23), fim de semana que antecedeu o do Carnaval, foram registradas, no HRVJ, 26 entradas por acidentes de tr\u00e2nsito. Destas, 24 envolviam moto. Dos que relataram uso de capacete, 18 estavam sem usar o item de prote\u00e7\u00e3o e somente um disse usar. Especialistas alertam: al\u00e9m de usar o capacete, \u00e9 importante tamb\u00e9m se atentar ao acionamento da trava, para que ele n\u00e3o saia da cabe\u00e7a ao sofrer impactos.<\/p>\n<p>O crediarista Manoel Aldenes Lira, 37, estava usando capacete no momento do acidente ocorrido na zona rural de Erer\u00ea, ap\u00f3s bater em um cachorro. Ele deu entrada no HRVJ no s\u00e1bado. \u201cO capacete evita muita coisa, como pancadas na cabe\u00e7a, por exemplo, o que \u00e9 pior. Ele me ajudou bastante, porque no que eu ca\u00ed, eu bati o rosto\u201d, explica.<\/p>\n<p style=\"text-align: center\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-140768\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-600x450.jpeg\" alt=\"\" width=\"775\" height=\"581\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-600x450.jpeg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-1200x900.jpeg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-768x576.jpeg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-1536x1152.jpeg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/WhatsApp-Image-2025-02-27-at-10.39.51-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/>&#8220;O capacete evita muita coisa, como pancadas na cabe\u00e7a&#8221;, explica Manoel, internado no HRVJ<\/em><\/p>\n<p>O m\u00e9dico coordenador da emerg\u00eancia do HRVJ, Matheus Henrique, destaca que em feriados e per\u00edodos festivos \u00e9 comum aumentar o n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos. \u201cEnquanto profissional da sa\u00fade, eu fa\u00e7o um alerta \u00e0 comunidade do Vale do Jaguaribe e Litoral Leste no sentido de ado\u00e7\u00e3o de medidas preventivas. O uso do capacete e do cinto de seguran\u00e7a, assim como evitar o consumo de \u00e1lcool por motoristas e condutores s\u00e3o mais que atitudes de seguran\u00e7a e prote\u00e7\u00e3o, s\u00e3o tamb\u00e9m um gesto de amor: amor por nossos familiares que nos aguardam na forma de seu abra\u00e7o e apre\u00e7o pelo nosso papel no gozo da plenitude de nossa condi\u00e7\u00e3o f\u00edsica saud\u00e1vel\u201d, alerta.<\/p>\n<h3><strong>Acidentes no tr\u00e2nsito lideram atendimentos de Emerg\u00eancia no HRSC<\/strong><\/h3>\n<p style=\"text-align: center\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-140769\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA-600x401.jpg\" alt=\"\" width=\"775\" height=\"518\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA-600x401.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA-1200x802.jpg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA-768x513.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA-1536x1027.jpg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/EMERGENCIA-HRSC-FACHADA.jpg 1616w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/>HRSC montou um planejamento de trabalho especial<\/em><\/p>\n<p>Este ser\u00e1 o primeiro Carnaval no qual a Urg\u00eancia e Emerg\u00eancia em politrauma estar\u00e1 funcionando no <strong>Hospital Regional do Sert\u00e3o Central (HRSC)<\/strong>, unidade da Rede Sesa em Quixeramobim. Inaugurado em agosto de 2024, o servi\u00e7o j\u00e1 atendeu 7 mil pacientes e as admiss\u00f5es s\u00e3o, em sua maior parte, por traumas causados em decorr\u00eancia dos acidentes de tr\u00e2nsito. \u201cCerca de 65% das admiss\u00f5es t\u00eam origem em trauma de tr\u00e2nsito, por isso a abertura da emerg\u00eancia politrauma representa um divisor de \u00e1guas no cuidado dos pacientes da regi\u00e3o\u201d, explica o m\u00e9dico Thiago Carvalho, coordenador da Emerg\u00eancia do HRSC.<\/p>\n<p>Apesar do rigor da fiscaliza\u00e7\u00e3o e do aumento do efetivo de policiais nas estradas, neste per\u00edodo o n\u00famero de sinistros nas rodovias costuma aumentar. Por isso o HRSC montou um planejamento de trabalho especial, garantindo que o atendimento em dez diferentes especialidades, com equipe, estrutura e fluxos previamente definidos, esteja dispon\u00edvel 24 horas para os cerca de 600 mil moradores dos 20 munic\u00edpios da regi\u00e3o.<\/p>\n<p>\u201cAl\u00e9m do politrauma, nossa unidade mant\u00e9m sua retaguarda para AVCs, com neurologistas e neurocirurgi\u00f5es de plant\u00e3o, al\u00e9m de UTI referenciada, e j\u00e1 alinhamos o fluxo de atendimento com o Samu 192 Cear\u00e1, para garantir que os pacientes sejam direcionados corretamente, assegurando um atendimento r\u00e1pido e eficaz\u201d, explica o diretor-geral, Cristiano Rabelo.<\/p>\n<h3><strong>No Cariri, HRC \u00e9 refer\u00eancia no atendimento do politrauma<\/strong><\/h3>\n<p>A regionaliza\u00e7\u00e3o desse tipo de atendimento possibilita que pacientes em estado cr\u00edtico recebam assist\u00eancia r\u00e1pida e especializada, j\u00e1 que, em casos graves, cada minuto pode fazer a diferen\u00e7a. O Hospital Regional do Cariri (HRC), unidade da Sesa localizada em Juazeiro do Norte, \u00e9 refer\u00eancia no atendimento a v\u00edtimas de acidentes graves de tr\u00e2nsito, prestando assist\u00eancia a uma popula\u00e7\u00e3o de aproximadamente 1,5 milh\u00e3o de pessoas de 45 munic\u00edpios.<\/p>\n<p style=\"text-align: center\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-140771\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-600x400.jpg\" alt=\"\" width=\"775\" height=\"517\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-600x400.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-1200x800.jpg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-768x512.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-1536x1024.jpg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/HRC-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/>Servi\u00e7o de emerg\u00eancia do HRC funciona 24 horas por dia, sete dias por semana (Foto: Arquivo)<\/em><\/p>\n<p>A unidade foi a primeira do interior do Cear\u00e1 a oferecer o atendimento de urg\u00eancia e emerg\u00eancia para o trauma de m\u00e9dia e alta complexidade. O servi\u00e7o funciona 24 horas, todos os dias. Apenas em janeiro de 2025, a emerg\u00eancia da unidade registrou 199 entradas de pacientes envolvidos em acidentes de tr\u00e2nsito, sendo 179 deles por acidentes de moto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 um aumento na complexidade e na gravidade do paciente admitido durante o Carnaval Durante os dias de Carnaval, o Hospital Regional Vale do Jaguaribe (HRVJ), unidade da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), em Limoeiro do Norte, manter\u00e1 uma equipe de prontid\u00e3o nos setores de urg\u00eancia e emerg\u00eancia, al\u00e9m dos profissionais de plant\u00e3o. A [&hellip;]<\/p>\n","protected":false},"author":767,"featured_media":140767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4175],"tags":[161,799,1520,702,963,658],"class_list":["post-140763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carnaval","tag-carnaval","tag-emergencia","tag-hrc","tag-hrsc","tag-hrvj","tag-urgencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"description\" content=\"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T11:30:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T20:09:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes\",\"datePublished\":\"2025-02-28T11:30:11+00:00\",\"dateModified\":\"2025-02-28T20:09:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\"},\"wordCount\":915,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg\",\"keywords\":[\"Carnaval\",\"Emerg\u00eancia\",\"hrc\",\"HRSC\",\"HRVJ\",\"urg\u00eancia\"],\"articleSection\":[\"Carnaval\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\",\"name\":\"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg\",\"datePublished\":\"2025-02-28T11:30:11+00:00\",\"dateModified\":\"2025-02-28T20:09:20+00:00\",\"description\":\"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1","description":"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2025-02-28T11:30:11+00:00","article_modified_time":"2025-02-28T20:09:20+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/"},"author":{"name":"","@id":""},"headline":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes","datePublished":"2025-02-28T11:30:11+00:00","dateModified":"2025-02-28T20:09:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/"},"wordCount":915,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg","keywords":["Carnaval","Emerg\u00eancia","hrc","HRSC","HRVJ","urg\u00eancia"],"articleSection":["Carnaval"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/","name":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg","datePublished":"2025-02-28T11:30:11+00:00","dateModified":"2025-02-28T20:09:20+00:00","description":"Feriados e per\u00edodos festivos costumam ser de aumento do n\u00famero de acidentes graves com politraumatismos e traumas cranioencef\u00e1licos.","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2025\/02\/Urgencia.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2025\/02\/28\/hospitais-regionais-sesa-se-preparam-para-o-carnaval\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Hospitais regionais da Sesa se preparam para o Carnaval com equipes traumatol\u00f3gicas de prontid\u00e3o; especialistas alertam para preven\u00e7\u00e3o de acidentes"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/140763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/767"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=140763"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/140763\/revisions"}],"predecessor-version":[{"id":140826,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/140763\/revisions\/140826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/140767"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=140763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=140763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=140763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}