{"id":1373,"date":"2010-07-30T19:56:39","date_gmt":"2010-07-30T22:56:39","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/"},"modified":"2010-07-30T19:56:39","modified_gmt":"2010-07-30T22:56:39","slug":"upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/","title":{"rendered":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito"},"content":{"rendered":"<p>\u201cA UPA em S\u00e3o Benedito, assim como as 21 policl\u00ednicas regionais, os 21 Centros de Especialidades Odontol\u00f3gicas e os dois hospitais regionais que o governo do estado est\u00e1 construindo em todas as regi\u00f5es, \u00e9 para aumentar e facilitar o acesso da popula\u00e7\u00e3o aos servi\u00e7os de sa\u00fade\u201d, afirmou o Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos. Na Unidade de Pronto Atendimento, que teve a Ordem de Servi\u00e7o assinada nesta sexta-feira pelo secret\u00e1rio Arruda Bastos, as pessoas ter\u00e3o assist\u00eancia 24 horas. <\/p>\n<p>\u201cHaver\u00e1 m\u00e9dico pediatra e cl\u00ednico geral para atender a popula\u00e7\u00e3o na hora da urg\u00eancia e emerg\u00eancia, durante o dia todo, com servi\u00e7o de Raio X, laborat\u00f3rio para exames e aparelho de eletrocardiograma\u201d, refor\u00e7ou o secret\u00e1rio adjunto da Secretaria da Sa\u00fade, Marcelo Sobreira. Para o prefeito Tomaz Brand\u00e3o Junior, \u201ca UPA 24 horas \u00e9 uma prova de que o governo do estado atende as necessidades da regi\u00e3o e que a parceria governo federal, governo do estado e governo municipal funciona perfeitamente\u201d.<\/p>\n<p>Essa foi a quinta Ordem de Servi\u00e7o assinada pelo secret\u00e1rio Arruda Bastos para a constru\u00e7\u00e3o das UPA 24 horas. J\u00e1 est\u00e3o em constru\u00e7\u00e3o as unidades dos munic\u00edpios de Maranguape e Crate\u00fas e das regionais II e VI, em Fortaleza. O prazo m\u00e1ximo para a conclus\u00e3o das obras \u00e9 de 90 dias.<\/p>\n<p>Em S\u00e3o Benedito, a UPA 24 horas \u00e9 de porte 1, que cobre uma popula\u00e7\u00e3o de at\u00e9 100 mil habitantes, contando com um pediatra e um cl\u00ednico geral para realizar atendimento de 50 a 150 pacientes diariamente e equipada com 5 a 8 leitos. Os investimentos s\u00e3o de R$1.907.500,00 para as obras e de R$ 800.000,00 em equipamentos, em recursos do Governo do Estado e do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>Na UPA 24 horas, a popula\u00e7\u00e3o poder\u00e1 resolver problemas como press\u00e3o alta, febre, cortes, queimaduras, alguns traumas e receber o primeiro atendimento para infarto ou Acidente Vascular Cerebral (AVC), entre outras enfermidades. Quando o paciente chega \u00e0 UPA, os m\u00e9dicos prestam socorro, controlam o problema e detalham o diagn\u00f3stico. Analisam se \u00e9 necess\u00e1rio encaminhar o paciente a um hospital ou mant\u00ea-lo em observa\u00e7\u00e3o por at\u00e9 24 horas.<\/p>\n<p>No Cear\u00e1, ser\u00e3o 32 UPA. Desse total, 11 de 22 que come\u00e7am a ser constru\u00eddas este ano, ficam prontas at\u00e9 dezembro. O prazo de entrega de cada unidade \u00e9 de 60 dias a 90 dias. O investimento nas 22 iniciadas este ano \u00e9 de R$ 77,9 milh\u00f5es, sendo R$ 24.666,000 do Tesouro do Estado e o restante do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA UPA em S\u00e3o Benedito, assim como as 21 policl\u00ednicas regionais, os 21 Centros de Especialidades Odontol\u00f3gicas e os dois hospitais regionais que o governo do estado est\u00e1 construindo em todas as regi\u00f5es, \u00e9 para aumentar e facilitar o acesso da popula\u00e7\u00e3o aos servi\u00e7os de sa\u00fade\u201d, afirmou o Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos. [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1373","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"\u201cA UPA em S\u00e3o Benedito, assim como as 21 policl\u00ednicas regionais, os 21 Centros de Especialidades Odontol\u00f3gicas e os dois hospitais regionais que o governo do estado est\u00e1 construindo em todas as regi\u00f5es, \u00e9 para aumentar e facilitar o acesso da popula\u00e7\u00e3o aos servi\u00e7os de sa\u00fade\u201d, afirmou o Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-30T22:56:39+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito\",\"datePublished\":\"2010-07-30T22:56:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\"},\"wordCount\":442,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\",\"name\":\"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-07-30T22:56:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/","og_locale":"pt_BR","og_type":"article","og_title":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"\u201cA UPA em S\u00e3o Benedito, assim como as 21 policl\u00ednicas regionais, os 21 Centros de Especialidades Odontol\u00f3gicas e os dois hospitais regionais que o governo do estado est\u00e1 construindo em todas as regi\u00f5es, \u00e9 para aumentar e facilitar o acesso da popula\u00e7\u00e3o aos servi\u00e7os de sa\u00fade\u201d, afirmou o Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos. [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-07-30T22:56:39+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito","datePublished":"2010-07-30T22:56:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/"},"wordCount":442,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/","name":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-07-30T22:56:39+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/07\/30\/upa-vai-facilitar-acesso-aos-servicos-de-saude-em-sao-benedito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"UPA vai facilitar acesso aos servi\u00e7os de sa\u00fade em S\u00e3o Benedito"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1373"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1373\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}