{"id":1359,"date":"2010-06-10T18:57:35","date_gmt":"2010-06-10T21:57:35","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/"},"modified":"2010-06-10T18:57:35","modified_gmt":"2010-06-10T21:57:35","slug":"trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/","title":{"rendered":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites"},"content":{"rendered":"<p>Vinte e uma empresas e institui\u00e7\u00f5es integrantes do Conselho Empresarial Estadual de Preven\u00e7\u00e3o \u00e0s DST\/HIV\/Aids ter\u00e3o 34 representantes no Treinamento sobre DST\/Aids e Hepatites Virais que a Secretaria da Sa\u00fade do Estado realiza nesta sexta-feira, 11 de junho, no Hotel Magna, na Avenida Historiador Raimundo Gir\u00e3o, 1002, Meireles, das 8 \u00e0s 17 horas.<\/p>\n<p>O Cear\u00e1 foi o sexto no pa\u00eds a implantar o Conselho Empresarial Estadual, que teve in\u00edcio com 14 empresas e institui\u00e7\u00f5es, em fevereiro de 2006, com o objetivo de ampliar a participa\u00e7\u00e3o do setor empresarial cearense no controle do HIV\/ Aids e da incid\u00eancia de doen\u00e7as sexualmente transmiss\u00edveis no Estado. Nos tr\u00eas primeiros anos, o Conselho Empresarial Estadual realizou campanhas, a\u00e7\u00f5es educativas e distribui\u00e7\u00e3o de preservativos em datas como carnaval, dia dos namorados, dia nacional de combate ao HIV no local de trabalho e dia mundial de luta contra a aids. Tamb\u00e9m promoveu a capacita\u00e7\u00e3o t\u00e9cnica dos membros do conselho e elabora\u00e7\u00e3o da pol\u00edtica interna de preven\u00e7\u00e3o e assist\u00eancia ao HIV\/AIDS no local de trabalho.<\/p>\n<p>Qualquer empresa interessada pode atuar na preven\u00e7\u00e3o das DST\/Aids, realizando a distribui\u00e7\u00e3o de preservativos entre os trabalhadores. Os preservativos s\u00e3o fornecidos pela Secretaria da Sa\u00fade e as solicita\u00e7\u00f5es devem ser encaminhadas \u00e0 Coordenadoria de Promo\u00e7\u00e3o e Prote\u00e7\u00e3o \u00e0 Sa\u00fade (Coprom) ou pelo telefone 3101.5281.<\/p>\n<div align=\"center\"><strong>Empresas participantes do treinamento<\/p>\n<p><\/strong><\/div>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"4\" width=\"467\" height=\"464\" align=\"center\">\n<tbody>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Jornal o    Povo<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Caf\u00e9    Santa Clara<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Termocear\u00e1<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>F\u00e1brica    Fortaleza<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Sest\/Senat<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Unimed <\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>RNP-CE    (Rede de pessoas vivendo com HIV\/Aids)<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Sesi \u2013    Servi\u00e7o Social da Ind\u00fastria<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Sanny    Confec\u00e7\u00f5es Femininas S.A<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Superintend\u00eancia    Regional do Trabalho e Emprego<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Vicunha    T\u00eaxtil<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Bemfam<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Servi\u00e7o    Social do Com\u00e9rcio \u2013 Sesc<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Grupo ABC    Vida de apoio ao Portador de Hepatite <\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Marisol<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Santana    Textiles<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Cagece<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Coelce<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Grendene<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"517\" valign=\"top\">\n<p><strong>Schincariol<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr bgcolor=\"#eaffea\">\n<td width=\"517\" valign=\"top\">\n<p><strong>Vulcabr\u00e1s\/Azaeia<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Vinte e uma empresas e institui\u00e7\u00f5es integrantes do Conselho Empresarial Estadual de Preven\u00e7\u00e3o \u00e0s DST\/HIV\/Aids ter\u00e3o 34 representantes no Treinamento sobre DST\/Aids e Hepatites Virais que a Secretaria da Sa\u00fade do Estado realiza nesta sexta-feira, 11 de junho, no Hotel Magna, na Avenida Historiador Raimundo Gir\u00e3o, 1002, Meireles, das 8 \u00e0s 17 horas. O Cear\u00e1 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1359","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Vinte e uma empresas e institui\u00e7\u00f5es integrantes do Conselho Empresarial Estadual de Preven\u00e7\u00e3o \u00e0s DST\/HIV\/Aids ter\u00e3o 34 representantes no Treinamento sobre DST\/Aids e Hepatites Virais que a Secretaria da Sa\u00fade do Estado realiza nesta sexta-feira, 11 de junho, no Hotel Magna, na Avenida Historiador Raimundo Gir\u00e3o, 1002, Meireles, das 8 \u00e0s 17 horas. O Cear\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-10T21:57:35+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites\",\"datePublished\":\"2010-06-10T21:57:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\"},\"wordCount\":322,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\",\"name\":\"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-06-10T21:57:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/","og_locale":"pt_BR","og_type":"article","og_title":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Vinte e uma empresas e institui\u00e7\u00f5es integrantes do Conselho Empresarial Estadual de Preven\u00e7\u00e3o \u00e0s DST\/HIV\/Aids ter\u00e3o 34 representantes no Treinamento sobre DST\/Aids e Hepatites Virais que a Secretaria da Sa\u00fade do Estado realiza nesta sexta-feira, 11 de junho, no Hotel Magna, na Avenida Historiador Raimundo Gir\u00e3o, 1002, Meireles, das 8 \u00e0s 17 horas. O Cear\u00e1 [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-06-10T21:57:35+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites","datePublished":"2010-06-10T21:57:35+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/"},"wordCount":322,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/","name":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-06-10T21:57:35+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/06\/10\/trabalhadores-de-21-empresas-recebem-informacoes-sobre-aids-e-hepatites-virais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Trabalhadores de 21 empresas recebem informa\u00e7\u00f5es sobre Aids e hepatites"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1359"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1359\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}