{"id":135472,"date":"2024-09-11T16:26:54","date_gmt":"2024-09-11T19:26:54","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=135472"},"modified":"2024-09-11T16:31:39","modified_gmt":"2024-09-11T19:31:39","slug":"mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/","title":{"rendered":"Mais 306 profissionais de concurso da Sa\u00fade s\u00e3o nomeados, anuncia Elmano de Freitas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-135477\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\" alt=\"\" width=\"755\" height=\"505\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-1200x802.jpg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-768x513.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-1536x1027.jpg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762.jpg 1616w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/p>\n<p style=\"text-align: center\"><em>An\u00fancio foi feito durante a live semanal do governador nesta quarta-feira (11)<\/em><\/p>\n<p style=\"text-align: justify\">O governador do Cear\u00e1, Elmano de Freitas, trouxe uma boa not\u00edcia para a Sa\u00fade. \u00c9 que mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para assumir seus cargos. O an\u00fancio foi feito nesta quarta-feira (11), na conversa semanal do gestor com o povo cearense pelas redes sociais.<\/p>\n<p style=\"text-align: justify\">S\u00e3o 187 t\u00e9cnicos de enfermagem, 57 enfermeiros, 20 fisioterapeutas, 10 psic\u00f3logos, 10 assistentes sociais, seis farmac\u00eauticos e um m\u00e9dico para atuar na assist\u00eancia a pacientes em nove equipamentos da rede da Secretaria da Sa\u00fade do Cear\u00e1 (Sesa). J\u00e1 os 15 profissionais administrativos devem ser distribu\u00eddos em quatro setores de gest\u00e3o.<\/p>\n<p style=\"text-align: justify\">\u201cQueria dizer aos que realizaram o concurso da Sesa, que nesta quarta-feira (11) estar\u00e1 publicada no Di\u00e1rio Oficial a nomea\u00e7\u00e3o de mais 306 servidores da Sa\u00fade. N\u00f3s temos o compromisso de chamar, dentro do nosso calend\u00e1rio, e estamos publicando hoje esta nomea\u00e7\u00e3o. Agora j\u00e1 s\u00e3o 2.760 profissionais convocados\u201d, ressaltou o chefe do Executivo Estadual.<\/p>\n<p style=\"text-align: justify\">Estes novos servidores foram aprovados no concurso realizado no ano de 2021. Ao todo, duas mil pessoas foram convocadas em 2023: 600 em maio, 600 em setembro e 800 em dezembro. At\u00e9 dezembro, ser\u00e3o mil nomeados ao longo de 2024. At\u00e9 2026, mais de dois mil profissionais ainda devem ser convocados.<\/p>\n<p style=\"text-align: justify\">A incorpora\u00e7\u00e3o dos concursados como servidores foi poss\u00edvel por meio de projeto de lei aprovado pela Assembleia Legislativa do Cear\u00e1 (Alece) em abril de 2023. Esta \u00e9 a sexta convoca\u00e7\u00e3o desde o in\u00edcio das nomea\u00e7\u00f5es, em maio de 2023, e a terceira convoca\u00e7\u00e3o do concurso da Sa\u00fade em 2024.<\/p>\n<p style=\"text-align: justify\">Se contar s\u00f3 este ano, com os 306 profissionais convocados nesta quarta-feira, s\u00e3o 670 chamados.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-251814 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2024\/09\/DSC1859.jpg\" alt=\"\" width=\"1616\" height=\"1080\" \/><\/p>\n<h3>A\u00e7\u00f5es do Governo<\/h3>\n<p style=\"text-align: justify\">Ainda durante a live, Elmano de Freitas comentou sobre os eventos recentes. Ele destacou a participa\u00e7\u00e3o no Proenergia Summit 2024, na manh\u00e3 desta quarta-feira. \u201c\u00c9 um evento para discutir temas cruciais na \u00e1rea energ\u00e9ticas do Pa\u00eds, os desafios tecnol\u00f3gicos, as pol\u00edticas p\u00fablicas. Muitas quest\u00f5es s\u00e3o importantes neste momento de transi\u00e7\u00e3o energ\u00e9tica do Pa\u00eds\u201d, pontuou.<\/p>\n<p style=\"text-align: justify\">O Plano Safra tamb\u00e9m foi destaque na fala do governador, que ressaltou a destina\u00e7\u00e3o do apoio financeiro para os pequenos produtores, que j\u00e1 apresentar\u00e3o os seus projetos neste segundo semestre de 2024. \u201cO Governo Federal est\u00e1 colocando para o Cear\u00e1 R$ 1,8 bilh\u00e3o\u201d.<\/p>\n<p style=\"text-align: justify\">Elmano de Freitas ainda destacou a inaugura\u00e7\u00e3o da Escola Estadual de Educa\u00e7\u00e3o Profissional para Pessoas Privadas de Liberdade (EEEPPL), em Itaitinga, constru\u00edda pelos pr\u00f3prios detentos e que ser\u00e1 utilizada para a educa\u00e7\u00e3o deles, como forma de reinseri-los na sociedade.<\/p>\n<p style=\"text-align: justify\">O chefe do Executivo Estadual ainda agradeceu ao Senado pela autoriza\u00e7\u00e3o \u00e0 Uni\u00e3o para aprovar empr\u00e9stimo para o Estado do Cear\u00e1. Os recursos vir\u00e3o do Banco Interamericano de Desenvolvimento (BID) e ser\u00e3o destinados ao financiamento do Programa de Apoio \u00e0s Reformas Sociais do Cear\u00e1 (Proares III \u2013 2\u00aa etapa). Com essa verba, est\u00e1 prevista a constru\u00e7\u00e3o de 60 Centros de Educa\u00e7\u00e3o Infantil (CEIs), beneficiando mais de 80 munic\u00edpios.<\/p>\n<p style=\"text-align: justify\">Por fim, ele citou a retomada do Conselho Estadual de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, realizada na \u00faltima segunda-feira (9). A ideia \u00e9 atualizar a pol\u00edtica de inova\u00e7\u00e3o e acesso aos incentivos \u00e0 pesquisa, ao desenvolvimento cient\u00edfico e tecnol\u00f3gico no estado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-251815 size-full\" src=\"https:\/\/www.ceara.gov.br\/wp-content\/uploads\/2024\/09\/DSC1681.jpg\" alt=\"\" width=\"1616\" height=\"1080\" \/><\/p>\n<h3>Conversa com os internautas<\/h3>\n<p style=\"text-align: justify\">O governador tamb\u00e9m respondeu a perguntas dos internautas e prestou contas das a\u00e7\u00f5es do Governo do Cear\u00e1 em diferentes \u00e1reas.<\/p>\n<p style=\"text-align: justify\">A cearense Luciana Martins perguntou sobre cursos de gastronomia oferecidos pelo Estado. \u201cVoc\u00ea est\u00e1 com sorte. Porque n\u00f3s estamos, no momento, com 230 vagas em aberto, selecionando pessoas que querem fazer cursos de gastronomia, na Escola de Gastronomia Social Ivens Dias Branco. Voc\u00ea entra na seguinte p\u00e1gina:\u00a0<a href=\"https:\/\/gastronomiasocial.org.br\/\">gastronomiasocial.org.br<\/a>. L\u00e1, est\u00e3o todas as informa\u00e7\u00f5es do curso de gastronomia. E voc\u00ea pode fazer um curso em uma das melhores escolas de gastronomia do Brasil\u201d.<\/p>\n<p style=\"text-align: justify\">Francisco Levi agradeceu pela cirurgia de c\u00f3rnea que realizou no Hospital Geral de Fortaleza (HGF). Elmano aproveitou para agradecer pelo trabalho dos profissionais e ressaltar o cuidado que o Estado tem com a sa\u00fade da popula\u00e7\u00e3o. \u201cEu quero dizer da minha alegria de voc\u00ea ter feito a sua cirurgia, de voc\u00ea estar com a vista bem melhor. Eu quero parabenizar a todos os profissionais do HGF. Nos d\u00e1 muito orgulho. O Cear\u00e1 \u00e9 o estado que faz mais faz transplantes de c\u00f3rnea no Brasil. E, gra\u00e7as ao programa de cirurgias do Governo Federal e do nosso programa de mutir\u00e3o de cirurgias, n\u00f3s j\u00e1 passamos de 102 mil cirurgias das mais variadas\u201d.<\/p>\n<p style=\"text-align: justify\">Elmano de Freitas ainda lembrou que h\u00e1 novos munic\u00edpios com agendamento aberto para a CNH Popular. A partir da pr\u00f3xima segunda-feira (16), Poranga, Farias Brito, S\u00e3o Lu\u00eds do Curu, Trairi, Momba\u00e7a, Quixeramobim, Pacajus, Pindoretama, Senador Pompeu e Itai\u00e7aba dar\u00e3o in\u00edcios aos atendimentos. Os agendamentos j\u00e1 est\u00e3o abertos no site do Detran:\u00a0<a href=\"https:\/\/www.detran.ce.gov.br\/\">https:\/\/www.detran.ce.gov.br\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An\u00fancio foi feito durante a live semanal do governador nesta quarta-feira (11) O governador do Cear\u00e1, Elmano de Freitas, trouxe uma boa not\u00edcia para a Sa\u00fade. \u00c9 que mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para assumir seus cargos. O an\u00fancio foi feito nesta [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3433],"tags":[2020,1031,4489,1357],"class_list":["post-135472","post","type-post","status-publish","format-standard","hentry","category-com-a-palavra","tag-concurso","tag-inovacao","tag-summit","tag-tecnologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano<\/title>\n<meta name=\"description\" content=\"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano\" \/>\n<meta property=\"og:description\" content=\"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-11T19:26:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T19:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Mais 306 profissionais de concurso da Sa\u00fade s\u00e3o nomeados, anuncia Elmano de Freitas\",\"datePublished\":\"2024-09-11T19:26:54+00:00\",\"dateModified\":\"2024-09-11T19:31:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\"},\"wordCount\":856,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\",\"keywords\":[\"concurso\",\"inova\u00e7\u00e3o\",\"Summit\",\"Tecnologia\"],\"articleSection\":[\"Com a palavra\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\",\"name\":\"Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\",\"datePublished\":\"2024-09-11T19:26:54+00:00\",\"dateModified\":\"2024-09-11T19:31:39+00:00\",\"description\":\"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais 306 profissionais de concurso da Sa\u00fade s\u00e3o nomeados, anuncia Elmano de Freitas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano","description":"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano","og_description":"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2024-09-11T19:26:54+00:00","article_modified_time":"2024-09-11T19:31:39+00:00","og_image":[{"url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Mais 306 profissionais de concurso da Sa\u00fade s\u00e3o nomeados, anuncia Elmano de Freitas","datePublished":"2024-09-11T19:26:54+00:00","dateModified":"2024-09-11T19:31:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/"},"wordCount":856,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg","keywords":["concurso","inova\u00e7\u00e3o","Summit","Tecnologia"],"articleSection":["Com a palavra"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/","name":"Mais profissionais de concurso s\u00e3o nomeados, anuncia Elmano","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg","datePublished":"2024-09-11T19:26:54+00:00","dateModified":"2024-09-11T19:31:39+00:00","description":"Mais 306 profissionais \u2013 15 administrativos e 291 assistenciais \u2013 aprovados no \u00faltimo concurso da \u00e1rea ser\u00e3o nomeados para a Sesa.","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#primaryimage","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/09\/DSC1762-600x401.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/09\/11\/mais-306-profissionais-de-concurso-da-saude-sao-nomeados-anuncia-elmano-de-freitas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Mais 306 profissionais de concurso da Sa\u00fade s\u00e3o nomeados, anuncia Elmano de Freitas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/135472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=135472"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/135472\/revisions"}],"predecessor-version":[{"id":135481,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/135472\/revisions\/135481"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=135472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=135472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=135472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}