{"id":134852,"date":"2024-08-23T12:15:06","date_gmt":"2024-08-23T15:15:06","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=134852"},"modified":"2024-08-26T10:00:10","modified_gmt":"2024-08-26T13:00:10","slug":"sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/","title":{"rendered":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames preventivos de c\u00e2ncer de mama e colo do \u00fatero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-134857\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia-600x494.jpg\" alt=\"\" width=\"775\" height=\"637\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia-600x494.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia-768x632.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg 1200w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p style=\"text-align: center\"><em>Mamografia detecta cerca de 95% de altera\u00e7\u00f5es na mama\u00a0<\/em><\/p>\n<p style=\"text-align: justify\">A <strong>Secretaria da Sa\u00fade do Cear\u00e1 (Sesa)<\/strong>, por meio da <strong>Secretaria Executiva da Aten\u00e7\u00e3o Prim\u00e1ria e Pol\u00edticas de Sa\u00fade (Seaps)<\/strong> e da <strong>Secretaria Executiva de Aten\u00e7\u00e3o \u00e0 Sa\u00fade e Desenvolvimento Regional (Seade)<\/strong>, realiza entre 27 e 30 de agosto, um ciclo de webin\u00e1rios para mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o <strong>c\u00e2ncer de mama<\/strong> e de <strong>colo do \u00fatero<\/strong>. O objetivo \u00e9 potencializar a atua\u00e7\u00e3o da <strong>Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade (APS)<\/strong> e o rastreamento do p\u00fablico que utiliza o <strong>Sistema \u00danico de Sa\u00fade (SUS)<\/strong> pelas equipes de sa\u00fade da fam\u00edlia nos munic\u00edpios.<\/p>\n<p style=\"text-align: justify\">A iniciativa, que conta com o apoio do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems-CE), envolve agentes comunit\u00e1rios de sa\u00fade e demais profissionais da Estrat\u00e9gia de Sa\u00fade da Fam\u00edlia. Participam coordenadores municipais de Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade, secret\u00e1rios municipais de sa\u00fade e diretores das Policl\u00ednicas Regionais.<\/p>\n<p style=\"text-align: justify\">\u201cN\u00f3s sabemos do potencial que a APS tem, por ser a porta de entrada do SUS. Ent\u00e3o, n\u00f3s precisamos mobilizar as popula\u00e7\u00f5es dos territ\u00f3rios para que os exames de mamografia e papanicolau sejam realizados periodicamente\u201d, destaca a coordenadora da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade (Coaps), Tha\u00eds Fac\u00f3. Segundo a coordenadora, o perfil do p\u00fablico a ser mobilizado inclui, prioritariamente, pessoas entre 50 e 69 anos ou fora desta faixa et\u00e1ria, caso haja indica\u00e7\u00e3o cl\u00ednica para o exame de mamografia. J\u00e1 o perfil para rastreio do c\u00e2ncer de colo do \u00fatero inclui, prioritariamente, pessoas de 25 a 64 anos ou fora dessa faixa et\u00e1ria, caso tenham vida sexual ativa.<\/p>\n<h3>Programa\u00e7\u00e3o<\/h3>\n<p style=\"text-align: justify\">Ao todo, ser\u00e3o realizados cinco webin\u00e1rios, um para cada regi\u00e3o de sa\u00fade do Cear\u00e1. Os eventos ser\u00e3o abertos na pr\u00f3xima ter\u00e7a-feira (27), \u00e0s 9h, com o webin\u00e1rio para os profissionais da Regi\u00e3o de Sa\u00fade Litoral Leste\/Jaguaribe que contar\u00e1, na abertura, com a participa\u00e7\u00e3o da secret\u00e1ria executiva da Aten\u00e7\u00e3o Prim\u00e1ria e Pol\u00edticas de Sa\u00fade, Vaudelice Mota, e do secret\u00e1rio executivo de Aten\u00e7\u00e3o \u00e0 Sa\u00fade e Desenvolvimento Regional, Lauro Perdig\u00e3o.<\/p>\n<p style=\"text-align: justify\">A programa\u00e7\u00e3o inclui ainda a apresenta\u00e7\u00e3o do cen\u00e1rio do c\u00e2ncer de mama nas regi\u00f5es, que ser\u00e1 feita pela coordenadora de Redes de Aten\u00e7\u00e3o \u00e0 Sa\u00fade da Sesa, Rianna Nobre. J\u00e1 as estrat\u00e9gias de atua\u00e7\u00e3o da aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade contra o c\u00e2ncer de mama e colo de \u00fatero ser\u00e3o apresentadas pela orientadora da C\u00e9lula de Aten\u00e7\u00e3o Prim\u00e1ria e Promo\u00e7\u00e3o da Sa\u00fade (Cepri), Juliana Borges.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-134885\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/webinario_-_feed-1-600x847.jpg\" alt=\"\" width=\"775\" height=\"1094\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/webinario_-_feed-1-600x847.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/webinario_-_feed-1-768x1084.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/webinario_-_feed-1.jpg 1081w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mamografia detecta cerca de 95% de altera\u00e7\u00f5es na mama\u00a0 A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), por meio da Secretaria Executiva da Aten\u00e7\u00e3o Prim\u00e1ria e Pol\u00edticas de Sa\u00fade (Seaps) e da Secretaria Executiva de Aten\u00e7\u00e3o \u00e0 Sa\u00fade e Desenvolvimento Regional (Seade), realiza entre 27 e 30 de agosto, um ciclo de webin\u00e1rios para mobilizar a [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":134857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4340],"tags":[4472,3935,3012,170],"class_list":["post-134852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-webinar","tag-aps","tag-busca-ativa","tag-cancer-de-colo-do-utero","tag-cancer-de-mama"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames<\/title>\n<meta name=\"description\" content=\"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames\" \/>\n<meta property=\"og:description\" content=\"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-23T15:15:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T13:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"987\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames preventivos de c\u00e2ncer de mama e colo do \u00fatero\",\"datePublished\":\"2024-08-23T15:15:06+00:00\",\"dateModified\":\"2024-08-26T13:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg\",\"keywords\":[\"APS\",\"busca ativa\",\"c\u00e2ncer de colo do \u00fatero\",\"C\u00e2ncer de mama\"],\"articleSection\":[\"Webinar\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\",\"name\":\"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg\",\"datePublished\":\"2024-08-23T15:15:06+00:00\",\"dateModified\":\"2024-08-26T13:00:10+00:00\",\"description\":\"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg\",\"width\":1200,\"height\":987},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames preventivos de c\u00e2ncer de mama e colo do \u00fatero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames","description":"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/","og_locale":"pt_BR","og_type":"article","og_title":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames","og_description":"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2024-08-23T15:15:06+00:00","article_modified_time":"2024-08-26T13:00:10+00:00","og_image":[{"width":1200,"height":987,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames preventivos de c\u00e2ncer de mama e colo do \u00fatero","datePublished":"2024-08-23T15:15:06+00:00","dateModified":"2024-08-26T13:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/"},"wordCount":492,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg","keywords":["APS","busca ativa","c\u00e2ncer de colo do \u00fatero","C\u00e2ncer de mama"],"articleSection":["Webinar"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/","name":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg","datePublished":"2024-08-23T15:15:06+00:00","dateModified":"2024-08-26T13:00:10+00:00","description":"O ciclo de webin\u00e1rios quer mobilizar a busca ativa de pessoas que ainda n\u00e3o realizaram exames preventivos para o c\u00e2ncer de mama e de colo do \u00fatero.","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/08\/mamografia.jpg","width":1200,"height":987},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/08\/23\/sesa-webinarios-busca-ativa-pessoas-perfil-exames-preventivos-cancer-mama-colo-utero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Sesa realiza webin\u00e1rios para busca ativa de pessoas com perfil para exames preventivos de c\u00e2ncer de mama e colo do \u00fatero"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/134852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=134852"}],"version-history":[{"count":9,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/134852\/revisions"}],"predecessor-version":[{"id":134886,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/134852\/revisions\/134886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/134857"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=134852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=134852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=134852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}