{"id":1343,"date":"2009-06-15T20:44:45","date_gmt":"2009-06-15T23:44:45","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/"},"modified":"2009-06-15T20:44:45","modified_gmt":"2009-06-15T23:44:45","slug":"teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/","title":{"rendered":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue"},"content":{"rendered":"<p>At\u00e9 o dia 12 de junho, a Secretaria da Sa\u00fade do Estado havia confirmado 3.375 casos de dengue em 93 munic\u00edpios do Cear\u00e1, 12 casos de dengue hemorr\u00e1gica, com dois \u00f3bitos, e sete casos de dengue com complica\u00e7\u00e3o e 1 um \u00f3bito. O n\u00famero de casos confirmados \u00e9 o menor dos \u00faltimos cinco anos e a taxa de incid\u00eancia, que mede o risco de se adoecer de dengue, \u00e9 a mais baixa em 13 anos. O n\u00famero de munic\u00edpios com infesta\u00e7\u00e3o pelo Aedes aegypti, mosquito transmissor da dengue, tamb\u00e9m \u00e9 o menor desde 2001. Mesmo com os n\u00fameros em queda, o combate ao mosquito n\u00e3o pode parar. Para refor\u00e7ar as a\u00e7\u00f5es de mobiliza\u00e7\u00e3o social e controle da doen\u00e7a, a Secretaria da Sa\u00fade do Estado iniciou este m\u00eas as apresenta\u00e7\u00f5es da pe\u00e7a \u201cRomeu e Julieta no tempo da dengue\u201d, de autoria de Jos\u00e9 Mapurunga, com a Cia. de Teatro &#8220;Os Cara da Arte&#8221;. Amanh\u00e3, 16 de junho, a pe\u00e7a de teatro ir\u00e1 para tr\u00eas escolas. <\/p>\n<p>\u00c0s 11 horas ser\u00e1 na escola Marwin, na Avenida Monsenhor H\u00e9lio Campos, s\/n, bairro Cristo Redentor. \u00c0s 12h30min a pe\u00e7a ser\u00e1 apresentada na escola Presidente Roosevelt, na Avenida Bezerra de Menezes, 438, bairro Parque Arax\u00e1. \u00c1s 13h30min quem assistir\u00e1 a pe\u00e7a s\u00e3o os alunos da escola Paulo Petrola, na Travessa Castelo, s\/n, no bairro Goiabeiras. O pr\u00f3ximo destino do teatro de rua ser\u00e1 a regi\u00e3o do Cariri.\u00a0 A Secretaria da Sa\u00fade do Estado utiliza o teatro para apoiar os munic\u00edpios na mobiliza\u00e7\u00e3o social, apostando no poder da arte para provocar atitudes da popula\u00e7\u00e3o para os cuidados com os dep\u00f3sitos de \u00e1gua, locais onde o mosquito Aedes aegypti se multiplica. <\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 o dia 12 de junho, a Secretaria da Sa\u00fade do Estado havia confirmado 3.375 casos de dengue em 93 munic\u00edpios do Cear\u00e1, 12 casos de dengue hemorr\u00e1gica, com dois \u00f3bitos, e sete casos de dengue com complica\u00e7\u00e3o e 1 um \u00f3bito. O n\u00famero de casos confirmados \u00e9 o menor dos \u00faltimos cinco anos e [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1343","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"At\u00e9 o dia 12 de junho, a Secretaria da Sa\u00fade do Estado havia confirmado 3.375 casos de dengue em 93 munic\u00edpios do Cear\u00e1, 12 casos de dengue hemorr\u00e1gica, com dois \u00f3bitos, e sete casos de dengue com complica\u00e7\u00e3o e 1 um \u00f3bito. O n\u00famero de casos confirmados \u00e9 o menor dos \u00faltimos cinco anos e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-15T23:44:45+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue\",\"datePublished\":\"2009-06-15T23:44:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\",\"name\":\"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-06-15T23:44:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"At\u00e9 o dia 12 de junho, a Secretaria da Sa\u00fade do Estado havia confirmado 3.375 casos de dengue em 93 munic\u00edpios do Cear\u00e1, 12 casos de dengue hemorr\u00e1gica, com dois \u00f3bitos, e sete casos de dengue com complica\u00e7\u00e3o e 1 um \u00f3bito. O n\u00famero de casos confirmados \u00e9 o menor dos \u00faltimos cinco anos e [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-06-15T23:44:45+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue","datePublished":"2009-06-15T23:44:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/"},"wordCount":307,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/","name":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-06-15T23:44:45+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/15\/teatro-ajuda-municipios-na-mobilizacao-contra-a-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Teatro ajuda munic\u00edpios na mobiliza\u00e7\u00e3o contra a dengue"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}