{"id":133989,"date":"2024-07-23T08:36:33","date_gmt":"2024-07-23T11:36:33","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=133989"},"modified":"2024-07-23T08:36:33","modified_gmt":"2024-07-23T11:36:33","slug":"profissionais-voz-trabalho-cuidados-basicos-saude-vocal","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/","title":{"rendered":"Profissionais que usam a voz no trabalho precisam ter cuidados b\u00e1sicos com a sa\u00fade vocal"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-133991\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest-600x450.jpg\" alt=\"\" width=\"775\" height=\"581\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest-600x450.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest-768x576.jpg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg 1200w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><em>Recepcionistas e teleoperadores s\u00e3o exemplos de profissionais que utilizam a voz como ferramenta de trabalho <\/em><\/p>\n<p style=\"text-align: justify\">Mais que um <strong>instrumento de comunica\u00e7\u00e3o<\/strong>, para muitos profissionais a <strong>voz<\/strong> \u00e9 <strong>ferramenta de trabalho<\/strong>. E principalmente nesses casos, ela precisa de <strong>cuidados<\/strong> para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. <strong>Professores, teleoperadores, cantores e radialistas<\/strong> s\u00e3o apenas alguns exemplos de trabalhadores que dependem do <strong>recurso da voz<\/strong> diariamente e por um longo per\u00edodo.<\/p>\n<p style=\"text-align: justify\">De acordo com Maria do Socorro T\u00e1vora, <strong>fonoaudi\u00f3loga<\/strong> do <strong>Centro Estadual de Refer\u00eancia em Sa\u00fade do Trabalhador e da Trabalhadora (Cerest\/CE) Manuel Jacar\u00e9<\/strong>, da <strong>Secretaria da Sa\u00fade do Cear\u00e1 (Sesa)<\/strong>, a queixa mais comum entre as pessoas que fazem muito uso da voz no dia a dia \u00e9 a <strong>disfonia<\/strong>, mais conhecida como <strong>rouquid\u00e3o<\/strong>. Ela alerta que o problema tem diversas causas \u201cdesde porque a pessoa n\u00e3o consegue usar de forma adequada seu aparelho fonador, as suas cordas vocais, at\u00e9 problemas org\u00e2nicos, como n\u00f3dulos, p\u00f3lipos, que podem ser provocados pelo uso inadequado da voz, mas n\u00e3o necessariamente s\u00f3 por isso\u201d, diz.<\/p>\n<p style=\"text-align: justify\">Ao perceber qualquer altera\u00e7\u00e3o na voz ou inc\u00f4modo ao falar, a orienta\u00e7\u00e3o da fonoaudi\u00f3loga \u00e9 buscar por atendimento m\u00e9dico nas unidades de sa\u00fade prim\u00e1ria. Caso haja algum problema que precise de aten\u00e7\u00e3o espec\u00edfica, o paciente ser\u00e1 encaminhado para um servi\u00e7o especializado, como as policl\u00ednicas, que contam com profissionais otorrinolaringologistas e fonoaudi\u00f3logos.<\/p>\n<p style=\"text-align: justify\">Mas o ideal \u00e9 prevenir o surgimento de doen\u00e7as. Para isso, a fonoaudi\u00f3loga d\u00e1 algumas dicas de cuidados com a voz: \u201c\u00e9 recomendado que as pessoas procurem fazer pequenas pausas quando estiverem falando e se hidratar, ter sempre um copo de \u00e1gua pr\u00f3ximo. Quando for para muita gente, procurar falar usando algum tipo de recurso que amplie o volume da voz, normalmente um microfone\u201d.<\/p>\n<h2 style=\"text-align: justify\">Cerest lan\u00e7a grupo de promo\u00e7\u00e3o da sa\u00fade de profissionais que utilizam a voz no trabalho<\/h2>\n<p style=\"text-align: justify\">No dia 30 de julho, \u00e0s 14h, o Cerest ir\u00e1 lan\u00e7ar o \u201c<strong>Grupo de promo\u00e7\u00e3o da sa\u00fade vocal dos(as) trabalhadores(as) que utilizam a voz como instrumento de trabalho<\/strong>\u201d, com o objetivo de promover a <strong>sa\u00fade vocal<\/strong>, incentivar a participa\u00e7\u00e3o ativa, a autonomia sobre o autocuidado e prevenir os dist\u00farbios vocais por meio de a\u00e7\u00e3o educativa.<\/p>\n<p style=\"text-align: justify\">Segundo Mara Tavares, titular do Cerest, os encontros ser\u00e3o quinzenais e n\u00e3o h\u00e1 necessidade de inscri\u00e7\u00e3o pr\u00e9via. \u201cEsse grupo vem nessa perspectiva, que essas pessoas, trabalhador e trabalhadora, que v\u00e3o participar dessa atividade educativa, possam, minimamente, reconhecer sintomas de alerta, como enfrentar, como se preparar realmente, quais as estrat\u00e9gias de autocuidado que possam ser potencializadas para que isso n\u00e3o acometa a sua sa\u00fade vocal\u201d, diz.<\/p>\n<h3 style=\"text-align: justify\"><strong>Servi\u00e7o<\/strong><\/h3>\n<p>Grupo de promo\u00e7\u00e3o da sa\u00fade vocal dos(as) trabalhadores(as) que utilizam a voz como instrumento de trabalho<br \/>\nQuando: 30 de julho de 2024, \u00e0s 14 horas<br \/>\nLocal: Audit\u00f3rio do Cerest, Rua dos Tabajaras, 268, Praia de Iracema<br \/>\nInforma\u00e7\u00f5es: (85)3101.5343\/ cerest@saude.ce.gov.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recepcionistas e teleoperadores s\u00e3o exemplos de profissionais que utilizam a voz como ferramenta de trabalho Mais que um instrumento de comunica\u00e7\u00e3o, para muitos profissionais a voz \u00e9 ferramenta de trabalho. E principalmente nesses casos, ela precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Professores, teleoperadores, cantores [&hellip;]<\/p>\n","protected":false},"author":767,"featured_media":133991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3904],"tags":[2124,3236,3180,181,3203],"class_list":["post-133989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-do-trabalhador","tag-cerest","tag-cerest-ce","tag-saude-do-trabalhador-e-trabalhadora","tag-sesa","tag-voz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profissionais que usam a voz no trabalho precisam ter cuidados<\/title>\n<meta name=\"description\" content=\"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profissionais que usam a voz no trabalho precisam ter cuidados\" \/>\n<meta property=\"og:description\" content=\"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T11:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Profissionais que usam a voz no trabalho precisam ter cuidados b\u00e1sicos com a sa\u00fade vocal\",\"datePublished\":\"2024-07-23T11:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\"},\"wordCount\":535,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg\",\"keywords\":[\"Cerest\",\"Cerest\/CE\",\"sa\u00fade do trabalhador e trabalhadora\",\"Sesa\",\"voz\"],\"articleSection\":[\"Sa\u00fade do trabalhador\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\",\"name\":\"Profissionais que usam a voz no trabalho precisam ter cuidados\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg\",\"datePublished\":\"2024-07-23T11:36:33+00:00\",\"description\":\"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profissionais que usam a voz no trabalho precisam ter cuidados b\u00e1sicos com a sa\u00fade vocal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profissionais que usam a voz no trabalho precisam ter cuidados","description":"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/","og_locale":"pt_BR","og_type":"article","og_title":"Profissionais que usam a voz no trabalho precisam ter cuidados","og_description":"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2024-07-23T11:36:33+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/"},"author":{"name":"","@id":""},"headline":"Profissionais que usam a voz no trabalho precisam ter cuidados b\u00e1sicos com a sa\u00fade vocal","datePublished":"2024-07-23T11:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/"},"wordCount":535,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg","keywords":["Cerest","Cerest\/CE","sa\u00fade do trabalhador e trabalhadora","Sesa","voz"],"articleSection":["Sa\u00fade do trabalhador"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/","name":"Profissionais que usam a voz no trabalho precisam ter cuidados","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg","datePublished":"2024-07-23T11:36:33+00:00","description":"A voz precisa de cuidados para que seja utilizada em sua plenitude e n\u00e3o tenha problemas a longo prazo. Leia na reportagem.","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2024\/07\/saude-vocal-cerest.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2024\/07\/23\/profissionais-voz-trabalho-cuidados-basicos-saude-vocal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Profissionais que usam a voz no trabalho precisam ter cuidados b\u00e1sicos com a sa\u00fade vocal"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/133989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/767"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=133989"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/133989\/revisions"}],"predecessor-version":[{"id":133992,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/133989\/revisions\/133992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/133991"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=133989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=133989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=133989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}