{"id":1331,"date":"2010-02-22T03:00:00","date_gmt":"2010-02-22T06:00:00","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/"},"modified":"2010-02-22T03:00:00","modified_gmt":"2010-02-22T06:00:00","slug":"sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/","title":{"rendered":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF"},"content":{"rendered":"<p>A Secretaria da Sa\u00fade do Estado est\u00e1 realizando o mais completo levantamento sobre as qualifica\u00e7\u00f5es profissionais dos m\u00e9dicos, enfermeiros e dentistas que trabalham no Programa Sa\u00fade da Fam\u00edlia no Cear\u00e1. Desde o \u00faltimo dia 2 de fevereiro de 2010, todos os profissionais do PSF podem preencher question\u00e1rios individuais para a forma\u00e7\u00e3o de um banco de dados que permitir\u00e1 a Sesa a ter o perfil das necessidades de educa\u00e7\u00e3o permanente dos trabalhadores, como especializa\u00e7\u00e3o em sa\u00fade da fam\u00edlia e mestrado profissional em sa\u00fade da fam\u00edlia. Para preencher o question\u00e1rio, <a href=\"https:\/\/spreadsheets3.google.com\/viewform?formkey=dF9QRVNYdXFEV2JWcTI3UV9jZGpXUXc6MA\" target=\"_blank\"><u><strong>clique aqui<\/strong><\/u><\/a>. O prazo para preenchimento vai at\u00e9 o dia 10 de mar\u00e7o de 2010.<\/p>\n<p>Com base nas informa\u00e7\u00f5es obtidas atrav\u00e9s dos question\u00e1rios, a Sesa definir\u00e1 prioridades, cursos, treinamentos a serem ofertados e o n\u00famero de vagas necess\u00e1rias na Universidade Aberta do Sistema \u00danico de Sa\u00fade (UNA-SUS). No levantamento, ser\u00e3o consultados aproximadamente 6.970 profissionais do PFS de 2.133 equipes de sa\u00fade da fam\u00edlia cadastradas. Desse total, 1.736 est\u00e3o implantadas. <\/p>\n<p>No \u00faltimo dia 25 a Coordenadoria de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o em Sa\u00fade da Sesa realizou uma oficina de prepara\u00e7\u00e3o para a consulta. A oficina reuniu os coordenadores da aten\u00e7\u00e3o prim\u00e1ria dos munic\u00edpios cearenses. O coordenador da Rede Universidade Aberta do SUS, Vin\u00edcius de Ara\u00fajo Oliveira, apresentou durante a oficina o planejamento da UNA-SUS para 2010. A UNA-SUS foi lan\u00e7ada em 2008 com a meta de qualificar, at\u00e9 2011, cerca de 52 mil especialistas em sa\u00fade da fam\u00edlia e oferecer capacita\u00e7\u00e3o gerencial a outros 100 mil em todo o Brasil. Estrat\u00e9gia proposta pelo Minist\u00e9rio da Sa\u00fade, em coopera\u00e7\u00e3o com a Organiza\u00e7\u00e3o Pan-Americana de Sa\u00fade (OPAS-OMS), a UMA-SUS agrega o trabalho de institui\u00e7\u00f5es acad\u00eamicas com os servi\u00e7os de sa\u00fade para responder a necessidade de forma\u00e7\u00e3o dos profissionais do SUS.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Sa\u00fade do Estado est\u00e1 realizando o mais completo levantamento sobre as qualifica\u00e7\u00f5es profissionais dos m\u00e9dicos, enfermeiros e dentistas que trabalham no Programa Sa\u00fade da Fam\u00edlia no Cear\u00e1. Desde o \u00faltimo dia 2 de fevereiro de 2010, todos os profissionais do PSF podem preencher question\u00e1rios individuais para a forma\u00e7\u00e3o de um banco de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1331","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Secretaria da Sa\u00fade do Estado est\u00e1 realizando o mais completo levantamento sobre as qualifica\u00e7\u00f5es profissionais dos m\u00e9dicos, enfermeiros e dentistas que trabalham no Programa Sa\u00fade da Fam\u00edlia no Cear\u00e1. Desde o \u00faltimo dia 2 de fevereiro de 2010, todos os profissionais do PSF podem preencher question\u00e1rios individuais para a forma\u00e7\u00e3o de um banco de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-22T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF\",\"datePublished\":\"2010-02-22T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\",\"name\":\"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-02-22T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/","og_locale":"pt_BR","og_type":"article","og_title":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Secretaria da Sa\u00fade do Estado est\u00e1 realizando o mais completo levantamento sobre as qualifica\u00e7\u00f5es profissionais dos m\u00e9dicos, enfermeiros e dentistas que trabalham no Programa Sa\u00fade da Fam\u00edlia no Cear\u00e1. Desde o \u00faltimo dia 2 de fevereiro de 2010, todos os profissionais do PSF podem preencher question\u00e1rios individuais para a forma\u00e7\u00e3o de um banco de [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-02-22T06:00:00+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF","datePublished":"2010-02-22T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/"},"wordCount":337,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/","name":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-02-22T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/02\/22\/sesa-tera-o-perfil-das-necessidades-de-qualificacao-dos-profissionais-do-psf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Vai at\u00e9 10 de mar\u00e7o prazo para preencher formul\u00e1rio de qualifica\u00e7\u00e3o do PSF"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1331"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1331\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}