{"id":125894,"date":"2023-12-11T12:11:55","date_gmt":"2023-12-11T15:11:55","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=125894"},"modified":"2023-12-12T12:07:38","modified_gmt":"2023-12-12T15:07:38","slug":"saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/","title":{"rendered":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-125896 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2-600x375.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2-768x481.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/p>\n<p style=\"text-align: center\"><em>A fonoaudi\u00f3loga e assessora t\u00e9cnica da Coordenadoria de Pol\u00edticas da Gest\u00e3o do Cuidado Integral \u00e0 Sa\u00fade (Cogec), Juliana Donato, representou a Sesa nessa premia\u00e7\u00e3o<\/em><\/p>\n<p style=\"text-align: justify\">A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), desde dezembro de 2020, desenvolve o Projeto de Acessibilidade Comunicacional e de Informa\u00e7\u00e3o em Sa\u00fade \u00e0 Pessoa com Defici\u00eancia e Pessoas Surdas, por meio do Sa\u00fade Inclusiva: Programa de Aten\u00e7\u00e3o \u00e0 Pessoa com Defici\u00eancia. O objetivo do programa, idealizado pela Secretaria Executiva da Aten\u00e7\u00e3o Prim\u00e1ria e Pol\u00edticas de Sa\u00fade (Sepos) \u00e9 buscar garantir uma assist\u00eancia pautada pela comunica\u00e7\u00e3o igualit\u00e1ria entre os profissionais da rede e o cidad\u00e3o, alcan\u00e7ando, dessa forma, os usu\u00e1rios do Sistema \u00danico de Sa\u00fade (SUS), respeitando as suas respectivas particularidades.<\/p>\n<p style=\"text-align: justify\">A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia, entre os dias 30 de novembro e 2 de dezembro. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.<\/p>\n<h3 style=\"text-align: justify\"><strong>Acessibilidade<\/strong><\/h3>\n<p style=\"text-align: justify\">A proposta premiada, o Projeto de Acessibilidade Comunicacional, contempla, atualmente, os atendimentos nas Unidades B\u00e1sicas de Sa\u00fade e nos equipamentos de sa\u00fade da Rede Sesa dos 184 munic\u00edpios cearenses, independentemente de sua natureza. Por meio do telefone (85) 3101.5287, os int\u00e9rpretes ficam, virtualmente, \u00e0 disposi\u00e7\u00e3o, de segunda a sexta-feira, das 8h \u00e0s 17h. Atrav\u00e9s desse programa, s\u00e3o desenvolvidos v\u00e1rios projetos que garantem o acesso da popula\u00e7\u00e3o surda e com defici\u00eancia auditiva \u00e0 informa\u00e7\u00e3o e ao atendimento m\u00e9dico.<\/p>\n<p style=\"text-align: justify\">Segundo a fonoaudi\u00f3loga e assessora t\u00e9cnica da Coordenadoria de Pol\u00edticas da Gest\u00e3o do Cuidado Integral \u00e0 Sa\u00fade (Cogec), Juliana Donato, que representou a Sesa nessa premia\u00e7\u00e3o, esse trabalho tem um grande impacto na sa\u00fade do Estado, porque beneficia essa popula\u00e7\u00e3o surda, usu\u00e1ria de Libras de forma direta.<\/p>\n<p style=\"text-align: justify\">\u201cEssa premia\u00e7\u00e3o traz com ela um impacto enorme, por conta da import\u00e2ncia desse projeto. H\u00e1 tr\u00eas anos, o Estado oferece a media\u00e7\u00e3o comunicativa com int\u00e9rprete para as pessoas surdas, atrav\u00e9s de um n\u00famero de telefone, para o atendimento nas Unidades B\u00e1sicas de Sa\u00fade. Isso facilita a comunica\u00e7\u00e3o com os profissionais de sa\u00fade. Al\u00e9m desse atendimento, tamb\u00e9m foi desenvolvido um cadastro com informa\u00e7\u00f5es sobre as pessoas surdas, o que favorece a organiza\u00e7\u00e3o dos servi\u00e7os de sa\u00fade para esse p\u00fablico\u201d, afirma.<\/p>\n<h3 style=\"text-align: justify\"><strong>Maior inclus\u00e3o<\/strong><\/h3>\n<p style=\"text-align: justify\">Entre as a\u00e7\u00f5es desenvolvidas pela Secretaria da Sa\u00fade do Cear\u00e1 est\u00e1 ainda o perfil do Instagram em L\u00edngua de Sinais da Sesa, @saudecearalibras, que disponibiliza informa\u00e7\u00f5es atualizadas, not\u00edcias e tudo o que diz respeito \u00e0 sa\u00fade no Estado.<\/p>\n<p style=\"text-align: justify\">Outro produto que contribui nesse sentido \u00e9 o Guia de Acessibilidade para Pessoas Surdas ou com Defici\u00eancia Auditiva, gloss\u00e1rio com a tradu\u00e7\u00e3o do portugu\u00eas para Libras das palavras mais utilizadas nos atendimentos de sa\u00fade, como febre, dor e outras. O guia est\u00e1 dispon\u00edvel no site da Sesa para download em vers\u00f5es digital e para impress\u00e3o, al\u00e9m dos v\u00eddeos de cada tradu\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">A equipe da Sesa tamb\u00e9m executa a grava\u00e7\u00e3o das janelas de Libras e outros materiais. Alguns eventos presenciais tamb\u00e9m contam com a tradu\u00e7\u00e3o e interpreta\u00e7\u00e3o em Libras. Os int\u00e9rpretes possibilitam que a informa\u00e7\u00e3o chegue \u00e0 pessoa surda na sua integralidade, fazendo com que seja poss\u00edvel uma compreens\u00e3o clara do que est\u00e1 sendo abordado. O projeto conta com o apoio de surdos e profissionais atuantes na comunidade surda.<\/p>\n<p>Confira o conte\u00fado desta mat\u00e9ria em l\u00edngua de sinais:<\/p>\n<div style=\"width: 1280px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-125894-1\" width=\"1280\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/PremioLIBRAS.mp4?_=1\" \/><a href=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/PremioLIBRAS.mp4\">https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/PremioLIBRAS.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A fonoaudi\u00f3loga e assessora t\u00e9cnica da Coordenadoria de Pol\u00edticas da Gest\u00e3o do Cuidado Integral \u00e0 Sa\u00fade (Cogec), Juliana Donato, representou a Sesa nessa premia\u00e7\u00e3o A Secretaria da Sa\u00fade do Cear\u00e1 (Sesa), desde dezembro de 2020, desenvolve o Projeto de Acessibilidade Comunicacional e de Informa\u00e7\u00e3o em Sa\u00fade \u00e0 Pessoa com Defici\u00eancia e Pessoas Surdas, por meio [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":125896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3731],"tags":[1222,2075],"class_list":["post-125894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acessibilidade","tag-acessibilidade","tag-libras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas<\/title>\n<meta name=\"description\" content=\"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas\" \/>\n<meta property=\"og:description\" content=\"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-11T15:11:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-12T15:07:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas\",\"datePublished\":\"2023-12-11T15:11:55+00:00\",\"dateModified\":\"2023-12-12T15:07:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\"},\"wordCount\":684,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\",\"keywords\":[\"acessibilidade\",\"Libras\"],\"articleSection\":[\"Acessibilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\",\"name\":\"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\",\"datePublished\":\"2023-12-11T15:11:55+00:00\",\"dateModified\":\"2023-12-12T15:07:38+00:00\",\"description\":\"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas","description":"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/","og_locale":"pt_BR","og_type":"article","og_title":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas","og_description":"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2023-12-11T15:11:55+00:00","article_modified_time":"2023-12-12T15:07:38+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png","type":"image\/png"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas","datePublished":"2023-12-11T15:11:55+00:00","dateModified":"2023-12-12T15:07:38+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/"},"wordCount":684,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png","keywords":["acessibilidade","Libras"],"articleSection":["Acessibilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/","name":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png","datePublished":"2023-12-11T15:11:55+00:00","dateModified":"2023-12-12T15:07:38+00:00","description":"A iniciativa foi premiada no \u00faltimo Congresso Brasileiro Sa\u00fade em Libras, realizado na Universidade Federal do Vale do S\u00e3o Francisco, em Juazeiro, na Bahia. O projeto, de autoria da Sa\u00fade do Cear\u00e1, venceu o Pr\u00eamio Brasileiro de Sa\u00fade em Libras, sendo uma das cinco escolhidas na competi\u00e7\u00e3o, selecionada entre 136 projetos, vindos de todo o Brasil. A premia\u00e7\u00e3o foi entregue durante o evento.","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2023\/12\/image-2.png","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2023\/12\/11\/saude-do-ceara-ganha-premio-nacional-com-trabalho-de-inclusao-de-pessoas-surdas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade do Cear\u00e1 ganha pr\u00eamio nacional com trabalho de inclus\u00e3o de pessoas surdas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/125894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=125894"}],"version-history":[{"count":5,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/125894\/revisions"}],"predecessor-version":[{"id":126009,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/125894\/revisions\/126009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/125896"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=125894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=125894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=125894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}