{"id":1220,"date":"2011-04-19T22:11:03","date_gmt":"2011-04-20T01:11:03","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/"},"modified":"2011-04-19T22:11:03","modified_gmt":"2011-04-20T01:11:03","slug":"selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/","title":{"rendered":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos"},"content":{"rendered":"<p> <\/p>\n<div align=\"justify\">\n<div align=\"justify\">\n<div align=\"justify\">\n<table style=\"background-color: #99cccc; width: 540px; height: 30px;\" border=\"0\">\n<tbody>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong> <a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=105:provas-e-gabarito&amp;download=862:gabarito-seleo-ceos-2011-ps-recursos&amp;Itemid=15\">GABARITO (<em>P\u00d3S-RECURSOS<\/em>)<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p align=\"justify\">&nbsp;<\/p>\n<div>\n<div>\n<div>\n<table style=\"background-color: #99cccc; width: 540px; height: 64px;\" border=\"0\">\n<tbody>\n<tr align=\"center\">\n<td><strong>RESULTADO DA PROVA OBJETIVA<br \/><\/strong><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=99:cpsmbs-ceo-brejo-santo&amp;download=856:cpsmbs-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMBS &#8211; CEO Brejo Santo<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=100:cpsmcas-ceo-cascavel&amp;download=857:cpsmcas-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMCAS &#8211; CEO Cascavel<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=101:cpsmscr-ceo-crates&amp;download=858:cpsmscr-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMSCR &#8211; CEO Crate\u00fas<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=102:cpsmit-ceo-itapipoca&amp;download=859:cpsmit-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMIT &#8211; CEO Itapipoca<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=103:cpsmm-ceo-maracana&amp;download=860:cpsmm-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMM &#8211; CEO Maracana\u00fa<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=104:cpsmt-ceo-tau&amp;download=861:cpsmt-resultado-da-prova-objetiva&amp;Itemid=15\"><strong><strong>CPSMT &#8211; CEO Tau\u00e1<\/strong><\/strong><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE)<strong> divulga o resultado da Prova Objetiva p\u00f3s-recursos e convoca para entrega de t\u00edtulos pelos aprovados na primera fase<\/strong> do processo seletivo dos<strong> Cons\u00f3rcios P\u00fablicos de Sa\u00fade das Microrregi\u00f5es de Brejo Santo, Cascavel, Crate\u00fas, <\/strong><strong>Itapipoca, <\/strong><strong>Maracana\u00fa&nbsp; e Tau\u00e1<\/strong> para preenchimento de vagas para os <strong>Centros de Especialidades Odontol\u00f3gicas (CEOs)<\/strong>. Est\u00e3o sendo oferecidas vagas para cirurgi\u00e3o-dentista, auxiliar em sa\u00fade bucal, t\u00e9cnico em sa\u00fade bucal, auxiliar de pr\u00f3tese e t\u00e9cnico em pr\u00f3tese dental. S\u00e3o 42 vagas, sendo 20 para n\u00edvel m\u00e9dio e 22 para n\u00edvel superior. J\u00e1 o CEO de Tau\u00e1 oferece apenas 10 vagas. <\/p>\n<p><strong>A entrega dos t\u00edtulos dever\u00e1 ser efetuada nos dias 20, 25 e 26 de abril<\/strong>, no hor\u00e1rio de 8h \u00e0s 12h e de 13h \u00e0s 17h, na Escola de Sa\u00fade P\u00fablica do Cear\u00e1\/Coordenadoria de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o em Sa\u00fade, situada \u00e0 Av. Ant\u00f4nio Justa, 3161, Meireles.<\/p>\n<p>De acordo com os editais, a convoca\u00e7\u00e3o para a Prova de T\u00edtulos obedece ao limite de at\u00e9 05 (cinco) vezes o n\u00famero de vagas para cada cargo. Os empregos cuja lista ultrapassam tal limite se referem a empates ocorridos.<\/p>\n<p><strong>Etapas<br \/><\/strong><br \/>Coordenada pela ESP-CE, atrav\u00e9s da Coordenadoria de P\u00f3s-Gradua\u00e7\u00e3o em Gest\u00e3o em Sa\u00fade, a sele\u00e7\u00e3o constar\u00e1 de duas etapas (prova objetiva e prova de t\u00edtulos). <\/p>\n<p>De car\u00e1ter eliminat\u00f3rio, a prova objetiva de conhecimentos espec\u00edficos constar\u00e1 de 20 quest\u00f5es de m\u00faltipla escolha e ter\u00e1 valor total de 100&nbsp; pontos. Nota inferior a 50 (cinquenta) pontos implicar\u00e1 na elimina\u00e7\u00e3o do candidato.<\/p>\n<p>De car\u00e1ter classificat\u00f3rio, na prova de t\u00edtulos ser\u00e3o computados os pontos relativos \u00e0 Prova de T\u00edtulos do candidato que tenha atingido o perfil m\u00ednimo de aprova\u00e7\u00e3o na Prova Objetiva referente ao emprego e especialidade de sua op\u00e7\u00e3o.<\/p>\n<p><strong>Mais informa\u00e7\u00f5es: (85) 3101.1402\/1429<br \/><\/strong> <\/p>\n<div align=\"justify\">\n<div align=\"justify\">\n<div align=\"justify\">\n<table style=\"background-color: #99cccc; width: 540px; height: 64px;\" border=\"0\">\n<tbody>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=840:01-2011-cpsmbs-reenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-de-brejo-santo-ce-ceo-r-de-brejo-santo.&amp;Itemid=15\"><strong>Edital &#8211; CPSMBS &#8211; CEO Brejo Santo<\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=835:01-2011-cpsmcas-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-de-cascavel-ceo-rcas.&amp;Itemid=15\"><strong>Ed<\/strong><strong>i<\/strong><strong>t<\/strong><strong>a<\/strong><strong>l &#8211; CPSMCAS &#8211; CEO Cascavel<\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=836:01-2011-cpsmscr-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-de-crates-ceo-r.&amp;Itemid=15\"><strong>Edital &#8211; CPSMSCR &#8211; CEO Crate\u00fas<\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=837:01-2011-cpsmit-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-6.-ceo-6-regional-de-sade.&amp;Itemid=15\"> <\/a><\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=837:01-2011-cpsmit-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-6.-ceo-6-regional-de-sade.&amp;Itemid=15\"><strong>Edital &#8211; CPSMIT &#8211; CEO Itapipoca<\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=838:01-2011-cpsmm-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-de-maracana-ceo-r-maracana.&amp;Itemid=15\"><strong>Ed<\/strong><strong>i<\/strong><strong>t<\/strong><strong>a<\/strong><strong>l &#8211; CPSMM &#8211; CEO Maracana\u00fa<\/strong><\/a><\/td>\n<\/tr>\n<tr style=\"background-color: #ffffff;\">\n<td><strong> :: <\/strong><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" alt=\" \" height=\"16\" width=\"16\" border=\"0\" \/> <\/strong><a href=\"https:\/\/www.esp.ce.gov.br\/index.php?option=com_phocadownload&amp;view=category&amp;id=95:editais-2011&amp;download=839:01-2011-cpsmt-preenchimento-de-emprego-pblico-no-centro-de-especialidades-odontolgicas-regional-elizabete-gonalves-rgo-ceo-r-tau.&amp;Itemid=15\"><strong>Ed<\/strong><strong>i<\/strong><strong>t<\/strong><strong>a<\/strong><strong>l &#8211; CPSMT &#8211; CEO Tau\u00e1<\/strong><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p align=\"justify\">&nbsp;<\/p>\n<p><em><strong>Instru\u00e7\u00f5es:<\/strong> para visualizar os editais voc\u00ea precisa ter o Adobe Acrobat Reader instalado. <\/em><\/p>\n<div align=\"justify\">\n<p><a href=\"https:\/\/www.adobe.com\/br\/products\/acrobat\/readstep2.html\" target=\"_blank\"><em><img decoding=\"async\" src=\"https:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/get_adobe_reader.gif\" alt=\" \" border=\"0\" \/><br \/><\/em><\/a><em> <\/em><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>:: GABARITO (P\u00d3S-RECURSOS) &nbsp; RESULTADO DA PROVA OBJETIVA :: CPSMBS &#8211; CEO Brejo Santo :: CPSMCAS &#8211; CEO Cascavel :: CPSMSCR &#8211; CEO Crate\u00fas :: CPSMIT &#8211; CEO Itapipoca :: CPSMM &#8211; CEO Maracana\u00fa :: CPSMT &#8211; CEO Tau\u00e1 A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE) divulga o resultado da Prova Objetiva p\u00f3s-recursos e [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1220","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\":: GABARITO (P\u00d3S-RECURSOS) &nbsp; RESULTADO DA PROVA OBJETIVA :: CPSMBS &#8211; CEO Brejo Santo :: CPSMCAS &#8211; CEO Cascavel :: CPSMSCR &#8211; CEO Crate\u00fas :: CPSMIT &#8211; CEO Itapipoca :: CPSMM &#8211; CEO Maracana\u00fa :: CPSMT &#8211; CEO Tau\u00e1 A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE) divulga o resultado da Prova Objetiva p\u00f3s-recursos e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-20T01:11:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos\",\"datePublished\":\"2011-04-20T01:11:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\",\"name\":\"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\",\"datePublished\":\"2011-04-20T01:11:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage\",\"url\":\"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\",\"contentUrl\":\"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/","og_locale":"pt_BR","og_type":"article","og_title":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1","og_description":":: GABARITO (P\u00d3S-RECURSOS) &nbsp; RESULTADO DA PROVA OBJETIVA :: CPSMBS &#8211; CEO Brejo Santo :: CPSMCAS &#8211; CEO Cascavel :: CPSMSCR &#8211; CEO Crate\u00fas :: CPSMIT &#8211; CEO Itapipoca :: CPSMM &#8211; CEO Maracana\u00fa :: CPSMT &#8211; CEO Tau\u00e1 A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE) divulga o resultado da Prova Objetiva p\u00f3s-recursos e [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-04-20T01:11:03+00:00","og_image":[{"url":"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos","datePublished":"2011-04-20T01:11:03+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/"},"wordCount":444,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage"},"thumbnailUrl":"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/","name":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage"},"thumbnailUrl":"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png","datePublished":"2011-04-20T01:11:03+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#primaryimage","url":"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png","contentUrl":"http:\/\/www.esp.ce.gov.br\/images\/stories\/artigos\/pdf_button.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/19\/selecao-ceos-resultado-da-prova-objetiva-pos-recursos-e-convocacao-para-entrega-de-titulos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Sele\u00e7\u00e3o CEOs: resultado da Prova Objetiva p\u00f3s-recursos e convoca\u00e7\u00e3o para entrega de t\u00edtulos"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1220\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}