{"id":1124,"date":"2011-02-09T17:55:39","date_gmt":"2011-02-09T20:55:39","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/"},"modified":"2011-02-09T17:55:39","modified_gmt":"2011-02-09T20:55:39","slug":"rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/","title":{"rendered":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue"},"content":{"rendered":"<\/p>\n<p>A rede de assist\u00eancia do Cear\u00e1 est\u00e1 mais estruturada para uma poss\u00edvel epidemia de dengue em 2011 do que estava em 2008, quando o Estado registrou 44.508 casos da doen\u00e7a, com 23 mortes por dengue hemorr\u00e1gica. A opini\u00e3o foi consensual entre gestores de hospitais e das secretarias da Sa\u00fade do Estado e de Fortaleza, reunidos na manh\u00e3 desta quarta-feira, 9 de fevereiro, no audit\u00f3rio Waldir Arcoverde, da Sesa, com o objetivo de refor\u00e7ar a assist\u00eancia aos pacientes com dengue na capital e no interior. \u00a8 Isso n\u00e3o significa dizer que a rede, incluindo hospitais e unidades p\u00fablicas e privadas,&nbsp; n\u00e3o precisem se preparar ainda mais para oferecer diagn\u00f3stico precoce e assist\u00eancia de qualidade, evitando \u00f3bitos\u00a8, observou o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/p>\n<p><strong>UPAs e Hospital da PM<\/strong><\/p>\n<p>Ele destacou que a rede p\u00fablica de assist\u00eancia ser\u00e1 refor\u00e7ada com as quatro Unidades de Pronto Atendimento (UPAs 24 Horas), que est\u00e3o prontas para serem inauguradas em Maranguape e nas Regionais III, V e VI, em Fortaleza, com um total de 48 leitos, e ainda com a integra\u00e7\u00e3o do Hospital da Pol\u00edcia Militar, com 100 leitos, \u00e0 rede de unidades da Sesa. No interior do Estado, o Hospital Regional do Cariri (HRC), com inaugura\u00e7\u00e3o prevista para o pr\u00f3ximo m\u00eas, garantir\u00e1 mais 294 leitos para a regi\u00e3o sul do Estado, que, em parte, podem ser utilizados para acolher e tratar pacientes com dengue em situa\u00e7\u00f5es mais grave. <\/p>\n<p><strong>Alerta \u00e0 pediatria<\/strong><\/p>\n<p>No Cear\u00e1, h\u00e1 uma tend\u00eancia persistente de aumento proporcional do n\u00famero de casos de dengue em menores de 15 anos. Por essa raz\u00e3o, o coordenador de Promo\u00e7\u00e3o e Prote\u00e7\u00e3o \u00e0 Sa\u00fade da Sesa, Manoel Fonseca, orientou os hospitais particulares da rede complementar a atualizarem os pediatras no manejo dos pacientes. Ele lembrou que na epidemia de 2008 a Secretaria da Sa\u00fade lan\u00e7ou nota t\u00e9cnica orientado que todos os casos de virose sejam tratados como dengue e recomendou que os hospitais particulares formem estoques de soro oral, fundamental para a hidrata\u00e7\u00e3o dos pacientes. Arruda Bastos garantiu que soro n\u00e3o ser\u00e1 problema. O abastecimento est\u00e1 garantido.<\/p>\n<p><strong>Preven\u00e7\u00e3o<\/strong><\/p>\n<p>Ao mesmo tempo em que alerta os diretores de hospitais sobre a necessidade de refor\u00e7ar a estrutura de assist\u00eancia aos pacientes com dengue, os gestores da sa\u00fade p\u00fablica incrementam as a\u00e7\u00f5es de preven\u00e7\u00e3o para reduzir os \u00edndices de infesta\u00e7\u00e3o do mosquito. Afinal, \u00e9 recorrente a frase entre os especialistas em dengue de que \u00a8s\u00f3 existe a doen\u00e7a porque existe o mosquito\u00a8. Ciente disso, a Sesa, como gestora da sa\u00fade p\u00fablica estadual, avan\u00e7a nas mobiliza\u00e7\u00f5es para atingir o m\u00e1ximo de donas de casa, trabalhadores, professores, empres\u00e1rios comprometidos em evitar a mutiplica\u00e7\u00e3o do Aedes aegypti, que transmite a doen\u00e7a. A mais nova mobiliza\u00e7\u00e3o \u00e9 com a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Cear\u00e1. De 28 deste m\u00eas a 4 de fevereiro a FIEC, com apoio da Sesa e da Secretaria de Sa\u00fade de Fortaleza, far\u00e1 mobiliza\u00e7\u00f5es contra a dengue nas ind\u00fastrias localizadas em Fortaleza, Maracana\u00fa, Horizonte, Juazeiro do Norte e Sobral. Os trabalhadores ir\u00e3o trabalhar durante os cinco dias com adesivos, aventais, capacetes trazendo o tema da campanha &#8220;Ind\u00fastria sem dengue&#8221;. Nos canteiros de obras tapumes exibir\u00e3o adesivos gigantes para alertar, al\u00e9m dos oper\u00e1rios os pedestres e motoristas que circularem nas imedia\u00e7\u00f5es.<\/p>\n<p>\u00a0<\/p>\n<p>Ver mat\u00e9ria &#8220;<span style=\"text-decoration: underline;\"><a href=\"index.php?option=com_content&amp;view=article&amp;id=1153&amp;catid=1153&amp;Itemid=76\">FIEC assume responsabilidade social e faz campanha contra a dengue<\/a><\/span>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A rede de assist\u00eancia do Cear\u00e1 est\u00e1 mais estruturada para uma poss\u00edvel epidemia de dengue em 2011 do que estava em 2008, quando o Estado registrou 44.508 casos da doen\u00e7a, com 23 mortes por dengue hemorr\u00e1gica. A opini\u00e3o foi consensual entre gestores de hospitais e das secretarias da Sa\u00fade do Estado e de Fortaleza, reunidos [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1124","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A rede de assist\u00eancia do Cear\u00e1 est\u00e1 mais estruturada para uma poss\u00edvel epidemia de dengue em 2011 do que estava em 2008, quando o Estado registrou 44.508 casos da doen\u00e7a, com 23 mortes por dengue hemorr\u00e1gica. A opini\u00e3o foi consensual entre gestores de hospitais e das secretarias da Sa\u00fade do Estado e de Fortaleza, reunidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-09T20:55:39+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue\",\"datePublished\":\"2011-02-09T20:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\",\"name\":\"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2011-02-09T20:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A rede de assist\u00eancia do Cear\u00e1 est\u00e1 mais estruturada para uma poss\u00edvel epidemia de dengue em 2011 do que estava em 2008, quando o Estado registrou 44.508 casos da doen\u00e7a, com 23 mortes por dengue hemorr\u00e1gica. A opini\u00e3o foi consensual entre gestores de hospitais e das secretarias da Sa\u00fade do Estado e de Fortaleza, reunidos [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-02-09T20:55:39+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue","datePublished":"2011-02-09T20:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/"},"wordCount":615,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/","name":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2011-02-09T20:55:39+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/02\/09\/rede-de-assistencia-aos-pacientes-se-prepara-para-epidemia-de-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Rede de assist\u00eancia aos pacientes se prepara para epidemia de dengue"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1124"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1124\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}