{"id":112154,"date":"2022-11-04T10:22:14","date_gmt":"2022-11-04T13:22:14","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=112154"},"modified":"2022-11-04T10:22:14","modified_gmt":"2022-11-04T13:22:14","slug":"viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/","title":{"rendered":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99196 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_inovacao.png\" alt=\"\" width=\"198\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-112157 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\" alt=\"\" width=\"777\" height=\"487\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png 777w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1-768x481.png 768w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><br \/>\nCom o tema <em>Construindo um Sistema de Sa\u00fade Inteligente<\/em>, a <strong>VIII ExpoESP<\/strong> reunir\u00e1, de 17 a 19 de novembro, no <strong>Centro de Eventos do Cear\u00e1<\/strong>, pesquisadores, estudiosos, residentes, profissionais e trabalhadores da Sa\u00fade cearense. O evento \u00e9 uma realiza\u00e7\u00e3o da<strong> Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>, vinculada \u00e0 <strong>Secretaria da Sa\u00fade do Estado (Sesa)<\/strong>. A programa\u00e7\u00e3o inclui mesas redondas para debates, exposi\u00e7\u00f5es e apresenta\u00e7\u00f5es culturais, como a Feirinha Zen de artesanato e gastronomia.<\/p>\n<p><strong>A ExpoESP soma nove eventos simult\u00e2neos e integrados<\/strong>. No eixo da <strong>Educa\u00e7\u00e3o em Sa\u00fade<\/strong>, a iniciativa contar\u00e1 com apresenta\u00e7\u00f5es da Educa\u00e7\u00e3o Profissional em Sa\u00fade, Educa\u00e7\u00e3o Permanente em Sa\u00fade, Extens\u00e3o em Sa\u00fade e P\u00f3s-Gradua\u00e7\u00e3o em Sa\u00fade.<\/p>\n<p><strong> LEIA TAMB\u00c9M:<\/strong> <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/10\/27\/expoesp-em-novembro-congresso-de-saude-reune-ciencia-inovacao-e-arte-no-centro-de-eventos-do-ceara\/\" target=\"_blank\" rel=\"noopener\"><strong>Em novembro, congresso de sa\u00fade re\u00fane ci\u00eancia, inova\u00e7\u00e3o e arte no Centro de Eventos do Cear\u00e1<\/strong><\/a><\/p>\n<p>Dentro da <em>VII Mostra de Saberes da Educa\u00e7\u00e3o Profissional da ESP\/CE<\/em>, a Ger\u00eancia de Educa\u00e7\u00e3o Profissional em Sa\u00fade (Gepro) compartilhar\u00e1 experi\u00eancias na \u00e1rea da Enfermagem, no controle de endemias e arboviroses; no campo da prote\u00e7\u00e3o \u00e0 inf\u00e2ncia e adolesc\u00eancia; e na forma\u00e7\u00e3o de auxiliares de laborat\u00f3rio de vetores, reservat\u00f3rios e animais pe\u00e7onhentos.<\/p>\n<p>J\u00e1 a Ger\u00eancia de Educa\u00e7\u00e3o Permanente em Sa\u00fade (Geduc) da autarquia estar\u00e1 respons\u00e1vel pela realiza\u00e7\u00e3o do<em> I Semin\u00e1rio de Educa\u00e7\u00e3o Permanente do Estado do Cear\u00e1<\/em>; do <em>II Encontro da Rede Estadual Sa\u00fade Escola<\/em>; da <em>II Mostra de Vigil\u00e2ncia em Sa\u00fade<\/em>; da<em> II Mostra de Experi\u00eancias em Educa\u00e7\u00e3o Permanente em Sa\u00fade<\/em>; da <em>III Mostra de Experi\u00eancias Exitosas dos Observat\u00f3rios Municipais de Causas Externas<\/em> e da <em>IV Mostra de Resid\u00eancias em Sa\u00fade<\/em>.<\/p>\n<p>De 17 a 19 de novembro, a equipe da Escola promover\u00e1 um conjunto de a\u00e7\u00f5es que incluem oficinas de forma\u00e7\u00e3o; palestras sobre as pr\u00e1ticas da Educa\u00e7\u00e3o Permanente em Sa\u00fade no Cear\u00e1; apresenta\u00e7\u00f5es ligadas \u00e0 Pol\u00edtica Estadual de <a href=\"https:\/\/ww16.ce.gov.br\/saude\/principal-2-2-2-2\/servico\/ensinoepesquisa\/educacaopermanente\/\" target=\"_blank\" rel=\"noopener\"><strong>Educa\u00e7\u00e3o Permanente em Sa\u00fade<\/strong><\/a> e \u00e0 <a href=\"https:\/\/ppp.esp.ce.gov.br\/principais-projetos-estruturantes-da-esp\/projeto-rede-estadual-saude-escola\/\" target=\"_blank\" rel=\"noopener\"><strong>Rede Sa\u00fade Escola<\/strong><\/a>; e mesas redondas sobre os impactos da Educa\u00e7\u00e3o Permanente em transplantes.<\/p>\n<p>A ESP\/CE realizar\u00e1 atividades relacionadas \u00e0s pr\u00e1ticas da p\u00f3s-gradua\u00e7\u00e3o em Sa\u00fade durante o evento. A programa\u00e7\u00e3o contemplar\u00e1 mesas redondas sobre o curso de Especializa\u00e7\u00e3o em Vigil\u00e2ncia Sanit\u00e1ria da Escola e a Pesquisa Nacional de Egressos de Resid\u00eancias em Sa\u00fade, al\u00e9m de pain\u00e9is tem\u00e1ticos focados nos temas de lideran\u00e7a e gest\u00e3o nos programas de resid\u00eancia em Sa\u00fade e na proposta do <a href=\"https:\/\/www.esp.ce.gov.br\/2022\/03\/02\/residencia-medica-programa-ampliares-oferta-mais-69-vagas-para-2022\/\" target=\"_blank\" rel=\"noopener\"><strong>Programa Ampliares<\/strong><\/a>.<\/p>\n<h3><strong>O evento<\/strong><\/h3>\n<p>A ExpoESP \u00e9 o principal evento da autarquia vinculada \u00e0 Sesa. Em anos anteriores, o congresso cient\u00edfico era realizado na pr\u00f3pria sede da ESP\/CE, no bairro Meireles, em Fortaleza. Com a amplia\u00e7\u00e3o das atividades, das diversas pesquisas desenvolvidas e do reconhecimento da Escola como uma <strong>Institui\u00e7\u00e3o Cient\u00edfica, Tecnol\u00f3gica e de Inova\u00e7\u00e3o (ICT)<\/strong>, foi necess\u00e1rio estender toda a programa\u00e7\u00e3o.<\/p>\n<h3><strong>Servi\u00e7o<\/strong><\/h3>\n<p><strong>ExpoESP<\/strong><br \/>\n<strong>Quando:<\/strong> de 17 a 19 de novembro<br \/>\n<strong>Onde:<\/strong> Centro de Eventos do Cear\u00e1 (avenida Washington Soares, 999, Edson Queiroz) \u2013 port\u00e3o C, Mezanino 2<br \/>\n<a href=\"https:\/\/www.even3.com.br\/expoesp\/\" target=\"_blank\" rel=\"noopener\"><strong>Inscreva-se e acesse a programa\u00e7\u00e3o<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o tema Construindo um Sistema de Sa\u00fade Inteligente, a VIII ExpoESP reunir\u00e1, de 17 a 19 de novembro, no Centro de Eventos do Cear\u00e1, pesquisadores, estudiosos, residentes, profissionais e trabalhadores da Sa\u00fade cearense. O evento \u00e9 uma realiza\u00e7\u00e3o da Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":112157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,1039,3423,135],"class_list":["post-112154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-congresso","tag-expoesp","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Com o tema Construindo um Sistema de Sa\u00fade Inteligente, a VIII ExpoESP reunir\u00e1, de 17 a 19 de novembro, no Centro de Eventos do Cear\u00e1, pesquisadores, estudiosos, residentes, profissionais e trabalhadores da Sa\u00fade cearense. O evento \u00e9 uma realiza\u00e7\u00e3o da Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-04T13:22:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso\",\"datePublished\":\"2022-11-04T13:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\",\"keywords\":[\"Cear\u00e1\",\"congresso\",\"ExpoESP\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\",\"name\":\"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\",\"datePublished\":\"2022-11-04T13:22:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png\",\"width\":777,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/","og_locale":"pt_BR","og_type":"article","og_title":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Com o tema Construindo um Sistema de Sa\u00fade Inteligente, a VIII ExpoESP reunir\u00e1, de 17 a 19 de novembro, no Centro de Eventos do Cear\u00e1, pesquisadores, estudiosos, residentes, profissionais e trabalhadores da Sa\u00fade cearense. O evento \u00e9 uma realiza\u00e7\u00e3o da Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-11-04T13:22:14+00:00","og_image":[{"width":777,"height":487,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/"},"author":{"name":"","@id":""},"headline":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso","datePublished":"2022-11-04T13:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/"},"wordCount":560,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png","keywords":["Cear\u00e1","congresso","ExpoESP","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/","name":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png","datePublished":"2022-11-04T13:22:14+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/Banner-site-1.png","width":777,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/04\/viii-expoesp-educacao-em-saude-sera-discutida-em-tres-dias-de-congresso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"VIII ExpoESP: Educa\u00e7\u00e3o em Sa\u00fade ser\u00e1 discutida em tr\u00eas dias de congresso"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=112154"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112154\/revisions"}],"predecessor-version":[{"id":112158,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112154\/revisions\/112158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/112157"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=112154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=112154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=112154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}