{"id":112096,"date":"2022-11-03T10:44:57","date_gmt":"2022-11-03T13:44:57","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=112096"},"modified":"2022-11-03T10:47:59","modified_gmt":"2022-11-03T13:47:59","slug":"onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/","title":{"rendered":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &#8220;Ih! Nova Live&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99197 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude.png\" alt=\"\" width=\"181\" height=\"69\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude.png 181w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude-120x46.png 120w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-112097 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109-600x375.jpeg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109-768x481.jpeg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nConsiderados uns dos maiores desafios das sociedades contempor\u00e2neas em todo o mundo, <strong>a desinforma\u00e7\u00e3o e o compartilhamento de informa\u00e7\u00f5es falsas tamb\u00e9m afetam negativamente a \u00e1rea da Sa\u00fade<\/strong>. Onde os profissionais podem encontrar conte\u00fados seguros num contexto de <em>fake news<\/em>?<\/p>\n<p>Ap\u00f3s o fim das restri\u00e7\u00f5es do per\u00edodo eleitoral, a <em>Ih! Nova Live<\/em> retorna nesta quinta-feira (3), a partir das 19h, no <a href=\"https:\/\/www.instagram.com\/espceara\/?hl=pt-br\" target=\"_blank\" rel=\"noopener\"><strong>perfil oficial da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE) no Instagram<\/strong><\/a>.<\/p>\n<p>Participam do bate-papo virtual a enfermeira, epidemiologista e secret\u00e1ria executiva de Vigil\u00e2ncia em Sa\u00fade do Cear\u00e1, <strong>Sarah Mendes<\/strong>; e a jornalista e colaboradora do Laborat\u00f3rio de Inova\u00e7\u00e3o do SUS no Estado,<strong> \u00c9rica Pinho<\/strong>.<\/p>\n<p>No decorrer da transmiss\u00e3o, o p\u00fablico poder\u00e1 tirar d\u00favidas e fazer apontamentos relacionados ao assunto.<\/p>\n<p>Na <em>live<\/em>, ser\u00e3o debatidas as poss\u00edveis formas de integra\u00e7\u00e3o de informa\u00e7\u00f5es no ambiente on-line, a import\u00e2ncia de o profissional procurar fontes pautadas em evid\u00eancias cient\u00edficas e como checar not\u00edcias. Al\u00e9m disso, o encontro vai sublinhar <strong>o papel da transforma\u00e7\u00e3o digital na promo\u00e7\u00e3o de pol\u00edticas p\u00fablicas<\/strong>.<\/p>\n<h3><strong>&#8220;Ih! Nova Live&#8221;<\/strong><\/h3>\n<p>Produzida pela equipe do <strong>Laborat\u00f3rio de Inova\u00e7\u00e3o no SUS do Cear\u00e1 (Felicilab)<\/strong>, a <em>Ih! Nova Live<\/em> \u00e9 realizada semanalmente com o objetivo de apresentar e discutir iniciativas de <strong>inova\u00e7\u00e3o em sa\u00fade<\/strong>.<\/p>\n<h3><strong>Servi\u00e7o<\/strong><\/h3>\n<p><strong>Live: Onde achar informa\u00e7\u00e3o confi\u00e1vel na era das fake news?<\/strong><br \/>\n<strong>Quando:<\/strong> quinta-feira (3), a partir das 19h<br \/>\n<strong>Convidadas:<\/strong><br \/>\nSarah Mendes: Secret\u00e1ria executiva de Vigil\u00e2ncia em Sa\u00fade da Secretaria da Sa\u00fade do Cear\u00e1<br \/>\nErica Pinho: jornalista e colaboradora do Laborat\u00f3rio de Inova\u00e7\u00e3o do SUS no Cear\u00e1<br \/>\n<a href=\"https:\/\/www.instagram.com\/espceara\/?hl=pt-br\" target=\"_blank\" rel=\"noopener\"><strong>Acompanhe no perfil da ESP\/CE no Instagram (@espceara)<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerados uns dos maiores desafios das sociedades contempor\u00e2neas em todo o mundo, a desinforma\u00e7\u00e3o e o compartilhamento de informa\u00e7\u00f5es falsas tamb\u00e9m afetam negativamente a \u00e1rea da Sa\u00fade. Onde os profissionais podem encontrar conte\u00fados seguros num contexto de fake news? Ap\u00f3s o fim das restri\u00e7\u00f5es do per\u00edodo eleitoral, a Ih! Nova Live retorna nesta quinta-feira (3), [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":112097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,3431,2133,1640,1031,135],"class_list":["post-112096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-desinformacao","tag-escola-de-saude-publica","tag-fake-news","tag-inovacao","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &quot;Ih! Nova Live&quot; - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &quot;Ih! Nova Live&quot; - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Considerados uns dos maiores desafios das sociedades contempor\u00e2neas em todo o mundo, a desinforma\u00e7\u00e3o e o compartilhamento de informa\u00e7\u00f5es falsas tamb\u00e9m afetam negativamente a \u00e1rea da Sa\u00fade. Onde os profissionais podem encontrar conte\u00fados seguros num contexto de fake news? Ap\u00f3s o fim das restri\u00e7\u00f5es do per\u00edodo eleitoral, a Ih! Nova Live retorna nesta quinta-feira (3), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T13:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-03T13:47:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &#8220;Ih! Nova Live&#8221;\",\"datePublished\":\"2022-11-03T13:44:57+00:00\",\"dateModified\":\"2022-11-03T13:47:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\",\"keywords\":[\"Cear\u00e1\",\"desinforma\u00e7\u00e3o\",\"Escola de Sa\u00fade P\u00fablica\",\"Fake News\",\"inova\u00e7\u00e3o\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\",\"name\":\"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na \\\"Ih! Nova Live\\\" - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\",\"datePublished\":\"2022-11-03T13:44:57+00:00\",\"dateModified\":\"2022-11-03T13:47:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &#8220;Ih! Nova Live&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na \"Ih! Nova Live\" - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/","og_locale":"pt_BR","og_type":"article","og_title":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na \"Ih! Nova Live\" - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Considerados uns dos maiores desafios das sociedades contempor\u00e2neas em todo o mundo, a desinforma\u00e7\u00e3o e o compartilhamento de informa\u00e7\u00f5es falsas tamb\u00e9m afetam negativamente a \u00e1rea da Sa\u00fade. Onde os profissionais podem encontrar conte\u00fados seguros num contexto de fake news? Ap\u00f3s o fim das restri\u00e7\u00f5es do per\u00edodo eleitoral, a Ih! Nova Live retorna nesta quinta-feira (3), [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-11-03T13:44:57+00:00","article_modified_time":"2022-11-03T13:47:59+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/"},"author":{"name":"","@id":""},"headline":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &#8220;Ih! Nova Live&#8221;","datePublished":"2022-11-03T13:44:57+00:00","dateModified":"2022-11-03T13:47:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/"},"wordCount":318,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg","keywords":["Cear\u00e1","desinforma\u00e7\u00e3o","Escola de Sa\u00fade P\u00fablica","Fake News","inova\u00e7\u00e3o","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/","name":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na \"Ih! Nova Live\" - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg","datePublished":"2022-11-03T13:44:57+00:00","dateModified":"2022-11-03T13:47:59+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/11\/photo1667482109.jpeg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/11\/03\/onde-encontrar-informacoes-confiaveis-sobre-saude-esp-ce-discute-tema-na-ih-nova-live\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Onde encontrar informa\u00e7\u00f5es confi\u00e1veis sobre sa\u00fade? ESP\/CE discute tema na &#8220;Ih! Nova Live&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=112096"}],"version-history":[{"count":3,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112096\/revisions"}],"predecessor-version":[{"id":112101,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/112096\/revisions\/112101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/112097"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=112096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=112096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=112096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}