{"id":110200,"date":"2022-06-23T12:06:17","date_gmt":"2022-06-23T15:06:17","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=110200"},"modified":"2022-06-23T12:06:17","modified_gmt":"2022-06-23T15:06:17","slug":"centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/","title":{"rendered":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99196 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_inovacao.png\" alt=\"\" width=\"198\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-110201 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>Solenidade de lan\u00e7amento do equipamento ocorreu na sede da Escola, em Fortaleza<\/em><\/p>\n<p>A <strong>Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>, vinculada \u00e0<strong> Secretaria da Sa\u00fade do Estado (Sesa)<\/strong>, come\u00e7ou a escrever, nessa quarta-feira (22), mais um importante cap\u00edtulo na hist\u00f3ria da sa\u00fade p\u00fablica cearense. Em solenidade realizada para gestores, acad\u00eamicos e trabalhadores da Sa\u00fade, a autarquia lan\u00e7ou o projeto de implanta\u00e7\u00e3o do <strong>Centro de Simula\u00e7\u00e3o em Sa\u00fade (CSS)<\/strong>. O equipamento, que contar\u00e1 com consultoria do <strong>Ensino Einstein<\/strong>, projeta <strong>ampliar as capacita\u00e7\u00f5es ofertadas e atender at\u00e9 9.600 profissionais anualmente<\/strong>, impactando diretamente na melhoria de servi\u00e7os da rede de sa\u00fade.<\/p>\n<p><strong>O acordo firmado entre a ESP\/CE e o Hospital Israelita Albert Einstein tem dura\u00e7\u00e3o de um ano<\/strong> e engloba a realiza\u00e7\u00e3o de um acompanhamento especializado com foco no aperfei\u00e7oamento dos cursos oferecidos e do espa\u00e7o f\u00edsico do CSS, localizado no pr\u00e9dio anexo \u00e0 Escola, em Fortaleza. <strong>O investimento \u00e9 da ordem de R$ 690 mil e j\u00e1 consta em publica\u00e7\u00e3o no Di\u00e1rio Oficial<\/strong>.<\/p>\n<p>Durante o evento, o superintendente da entidade cearense, Marcelo Alcantara, destacou o alinhamento da cria\u00e7\u00e3o do Centro com a miss\u00e3o da Escola de<strong> qualificar a for\u00e7a de trabalho no sistema de sa\u00fade estadual<\/strong>. \u201cCom isso, a ESP\/CE vai poder agregar as melhores pr\u00e1ticas dessa \u00e1rea [simula\u00e7\u00e3o real\u00edstica], trazendo a possibilidade de fortalecer ainda mais seus cursos, seus projetos de capacita\u00e7\u00e3o e recursos humanos\u201d, refor\u00e7ou o gestor.<\/p>\n<p>A expectativa \u00e9 de que o CSS se torne uma <strong>refer\u00eancia no ensino com pr\u00e1ticas tecnol\u00f3gicas real\u00edsticas voltadas para especialistas da \u00e1rea da sa\u00fade<\/strong>, por meio da consultoria do <strong>Centro de Simula\u00e7\u00e3o Real\u00edstica Albert Einstein<\/strong>. \u201cA simula\u00e7\u00e3o \u00e9 uma estrat\u00e9gia moderna e contempor\u00e2nea que melhora a forma\u00e7\u00e3o dos nossos profissionais, pois ela possibilita o erro sem causar danos e tamb\u00e9m traz mais seguran\u00e7a ao paciente\u201d, explica Jos\u00e9 Batista Tomaz, diretor de Desenvolvimento Educacional da ESP\/CE.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-110202 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S57-2-1.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S57-2-1.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S57-2-1-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S57-2-1-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>J\u00falio Monte (\u00e0 esquerda), coordenador do curso de Medicina da Faculdade de Ci\u00eancias da Sa\u00fade Albert Einstein, e Thomaz Bittencourt (ao centro), m\u00e9dico especialista do Centro de Simula\u00e7\u00e3o do Hospital Albert Einstein, visitam exposi\u00e7\u00f5es de cen\u00e1rios de simula\u00e7\u00e3o na ESP\/CE<\/em><\/p>\n<p>A meta agora \u00e9 que sejam realizadas v\u00e1rias<strong> oficinas para se tra\u00e7ar o escopo do projeto<\/strong> e <strong>capacitar a equipe em simula\u00e7\u00e3o que vai estar \u00e0 frente do equipamento durante os 12 meses de parceria<\/strong>, al\u00e9m de consolidar o plano de implanta\u00e7\u00e3o com toda a reestrutura\u00e7\u00e3o da parte f\u00edsica e arquitet\u00f4nica do local e dos equipamentos. <strong>Inicialmente, ser\u00e3o priorizadas as resid\u00eancias Multiprofissional e M\u00e9dica, mas a proje\u00e7\u00e3o \u00e9 de que todas as \u00e1reas sejam contempladas com as capacita\u00e7\u00f5es<\/strong>.<\/p>\n<p>\u201cEsse Centro vir\u00e1 para fortalecer o processo de aprendizado, diminuir dist\u00e2ncias e contribuir com o fortalecimento de pol\u00edtica de sa\u00fade, proporcionando seguran\u00e7a ao profissional da Sa\u00fade e ao paciente nessa constru\u00e7\u00e3o da assist\u00eancia\u201d, afirmou o assessor especial da Sesa, Severino Alexandre.<\/p>\n<h3><strong>O evento<\/strong><\/h3>\n<p>A programa\u00e7\u00e3o do lan\u00e7amento do CSS contou com a realiza\u00e7\u00e3o de uma s\u00e9rie de palestras sobre a atua\u00e7\u00e3o da ESP\/CE no uso da simula\u00e7\u00e3o no ensino da Sa\u00fade; o contexto das pr\u00e1tica de ensino da simula\u00e7\u00e3o em sa\u00fade pela Sociedade Israelita Brasileira Albert Einstein; as atualiza\u00e7\u00f5es e as evid\u00eancias no contexto da simula\u00e7\u00e3o em sa\u00fade; al\u00e9m de uma s\u00e9rie de exposi\u00e7\u00f5es de cen\u00e1rios de simula\u00e7\u00e3o utilizados pelos profissionais nos treinamentos que j\u00e1 ocorrem na autarquia.<\/p>\n<h3><strong>Assista \u00e0 \u00edntegra do lan\u00e7amento do CSS<\/strong><\/h3>\n<p><iframe loading=\"lazy\" title=\"Projeto de Implanta\u00e7\u00e3o do Centro de Simula\u00e7\u00e3o em Sa\u00fade (CSS) da ESP\/CE\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/USlxPXjFRiY?start=118&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>A ideia em qualificar o CSS surgiu em 2020, durante o <em>Encontro Internacional de Simula\u00e7\u00e3o em Sa\u00fade<\/em>, em San Diego, na Calif\u00f3rnia. Os m\u00e9dicos Marcelo Alcantara e Jos\u00e9 Batista Tomaz participavam do evento quando tiveram a iniciativa de buscar parcerias com institui\u00e7\u00f5es que j\u00e1 tivessem experi\u00eancia na implanta\u00e7\u00e3o de centros especializados em simula\u00e7\u00f5es real\u00edsticas. Encontraram no Einstein a melhor alternativa para a proposta. \u201c<strong>O Centro de Simula\u00e7\u00e3o Albert Einstein \u00e9 o \u00fanico acreditado internacionalmente. Ent\u00e3o, fechar parceria com eles, que j\u00e1 t\u00eam expertise no assunto, vai trazer muitos ganhos para os profissionais da Sa\u00fade do nosso Estado<\/strong>\u201d, pontua Batista.<\/p>\n<p><a href=\"https:\/\/saude.us20.list-manage.com\/subscribe?u=27773083a42c64d82a696d91b&amp;id=db7ba72e9c\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109860 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2.png\" alt=\"\" width=\"776\" height=\"103\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2.png 776w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2-600x80.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2-768x102.png 768w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><\/a><\/p>\n<p>\u201cA gente fica muito feliz em trabalhar com a Escola de Sa\u00fade P\u00fablica do Cear\u00e1 para desenvolver o Programa de Simula\u00e7\u00e3o Real\u00edstica. <strong>O Einstein tem como um de seus objetivos e pilares estrat\u00e9gicos o ensino e a necessidade de expandir nosso conhecimento para cada local do Pa\u00eds<\/strong>\u201d, acrescenta o m\u00e9dico especialista do Centro de Simula\u00e7\u00e3o Real\u00edstica Albert Einstein e professor da Faculdade Israelita de Ci\u00eancias da Sa\u00fade Albert Einstein, Thomaz Bittencourt Couto.<\/p>\n<h3><strong>Consultorias<\/strong><\/h3>\n<p>Para al\u00e9m de capacitar os profissionais do <strong>Sistema \u00danico de Sa\u00fade (SUS)<\/strong>, a ideia \u00e9 fazer do Centro de Simula\u00e7\u00e3o tamb\u00e9m um <strong>plano de neg\u00f3cios autossustent\u00e1vel<\/strong>, com a venda dos servi\u00e7os ligados \u00e0 \u00e1rea de simula\u00e7\u00e3o, em hor\u00e1rios alternativos, para o setor privado.<\/p>\n<ul class=\"ListaEst\">\n<li><a href=\"https:\/\/www.flickr.com\/photos\/espceara\/sets\/72177720300002720\/\" target=\"_blank\" rel=\"noopener noreferrer\">Confira as fotos do evento<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Solenidade de lan\u00e7amento do equipamento ocorreu na sede da Escola, em Fortaleza A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), come\u00e7ou a escrever, nessa quarta-feira (22), mais um importante cap\u00edtulo na hist\u00f3ria da sa\u00fade p\u00fablica cearense. Em solenidade realizada para gestores, acad\u00eamicos e [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":110201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,3356,2133,3354,135],"class_list":["post-110200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-centro-de-simulacao-realistica","tag-escola-de-saude-publica","tag-hospital-israelita-albert-einstein","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Solenidade de lan\u00e7amento do equipamento ocorreu na sede da Escola, em Fortaleza A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), come\u00e7ou a escrever, nessa quarta-feira (22), mais um importante cap\u00edtulo na hist\u00f3ria da sa\u00fade p\u00fablica cearense. Em solenidade realizada para gestores, acad\u00eamicos e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T15:06:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano\",\"datePublished\":\"2022-06-23T15:06:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\"},\"wordCount\":918,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\",\"keywords\":[\"Cear\u00e1\",\"Centro de Simula\u00e7\u00e3o Real\u00edstica\",\"Escola de Sa\u00fade P\u00fablica\",\"Hospital Israelita Albert Einstein\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\",\"name\":\"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\",\"datePublished\":\"2022-06-23T15:06:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/","og_locale":"pt_BR","og_type":"article","og_title":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Solenidade de lan\u00e7amento do equipamento ocorreu na sede da Escola, em Fortaleza A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), come\u00e7ou a escrever, nessa quarta-feira (22), mais um importante cap\u00edtulo na hist\u00f3ria da sa\u00fade p\u00fablica cearense. Em solenidade realizada para gestores, acad\u00eamicos e [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-06-23T15:06:17+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/"},"author":{"name":"","@id":""},"headline":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano","datePublished":"2022-06-23T15:06:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/"},"wordCount":918,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg","keywords":["Cear\u00e1","Centro de Simula\u00e7\u00e3o Real\u00edstica","Escola de Sa\u00fade P\u00fablica","Hospital Israelita Albert Einstein","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/","name":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg","datePublished":"2022-06-23T15:06:17+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/S18-1.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/23\/centro-de-simulacao-em-saude-da-esp-ce-projeta-realizar-cerca-de-dez-mil-capacitacoes-por-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Centro de Simula\u00e7\u00e3o em Sa\u00fade da ESP\/CE projeta realizar cerca de dez mil capacita\u00e7\u00f5es por ano"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/110200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=110200"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/110200\/revisions"}],"predecessor-version":[{"id":110210,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/110200\/revisions\/110210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/110201"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=110200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=110200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=110200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}