{"id":109990,"date":"2022-06-10T16:04:11","date_gmt":"2022-06-10T19:04:11","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=109990"},"modified":"2022-06-10T16:06:23","modified_gmt":"2022-06-10T19:06:23","slug":"visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/","title":{"rendered":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99196 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_inovacao.png\" alt=\"\" width=\"198\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109992\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1-600x316.png\" alt=\"\" width=\"775\" height=\"408\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1-600x316.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1-768x404.png 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png 1090w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nAmpliar o acesso a informa\u00e7\u00f5es sobre o<strong> capacete Elmo<\/strong> foi a principal raz\u00e3o que levou a equipe do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) da <strong>Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>, autarquia vinculada \u00e0<strong> Secretaria da Sa\u00fade do Estado (Sesa)<\/strong>, a iniciar o processo de<strong> tradu\u00e7\u00e3o para o ingl\u00eas<\/strong> do <a href=\"https:\/\/sus.ce.gov.br\/elmo\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>site Elmo Capacete de Respira\u00e7\u00e3o Assistida<\/strong><\/a>.<\/p>\n<p><strong>&gt;&gt;<\/strong> <strong>LEIA TAMB\u00c9M:<\/strong> <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/esp-ce-inicia-processo-para-incorporacao-do-capacete-elmo-ao-sus\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ESP\/CE inicia processo para incorpora\u00e7\u00e3o do capacete Elmo ao SUS<\/strong><\/a><\/p>\n<p>A plataforma j\u00e1 despertava o interesse de pessoas de v\u00e1rias partes do mundo e recebia acessos de outros pa\u00edses, mesmo estando, at\u00e9 ent\u00e3o, somente na l\u00edngua portuguesa. Al\u00e9m disso, <strong>a inven\u00e7\u00e3o genuinamente cearense e que salvou milhares de vidas no auge da pandemia de covid-19<\/strong> vem ganhando notoriedade em pa\u00edses da Europa e da Am\u00e9rica do Sul, sendo apresentado em congressos de Medicina e cursos internacionais.<\/p>\n<p>\u201cPriorizamos essa atividade com o apoio do Laborat\u00f3rio de Inova\u00e7\u00e3o (Felicilab) e da Ger\u00eancia de Pesquisa da ESP\/CE. Estamos nesse processo h\u00e1 quase dois meses e, at\u00e9 o momento, as informa\u00e7\u00f5es gerais do site j\u00e1 foram traduzidas. O pr\u00f3ximo passo \u00e9 fazer a vers\u00e3o em ingl\u00eas de conte\u00fados mais espec\u00edficos como os v\u00eddeos\u201d, explica a diretora de Inova\u00e7\u00e3o e Tecnologias da institui\u00e7\u00e3o, Alice Pequeno.<\/p>\n<p><a href=\"https:\/\/saude.us20.list-manage.com\/subscribe?u=27773083a42c64d82a696d91b&amp;id=db7ba72e9c\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109860 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2.png\" alt=\"\" width=\"776\" height=\"103\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2.png 776w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2-600x80.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/teste2-768x102.png 768w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><\/a><\/p>\n<p>Idealizado pelo m\u00e9dico pneumointensivista e superintendente da Escola, Marcelo Alcantara, o capacete Elmo tem <strong>efic\u00e1cia comprovada e bons resultados obtidos entre pacientes com a doen\u00e7a respirat\u00f3ria<\/strong>. O projeto tamb\u00e9m foi considerado o <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/03\/11\/capacete-elmo-e-eleito-melhor-case-de-inovacao-do-brasil-em-votacao-popular\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>melhor case de inova\u00e7\u00e3o do Pa\u00eds<\/strong><\/a>, ap\u00f3s vota\u00e7\u00e3o popular no \u00faltimo m\u00eas de mar\u00e7o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampliar o acesso a informa\u00e7\u00f5es sobre o capacete Elmo foi a principal raz\u00e3o que levou a equipe do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), autarquia vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), a iniciar o processo de tradu\u00e7\u00e3o para o ingl\u00eas do site [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":109992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,1857,135,3341],"class_list":["post-109990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-elmo","tag-saude","tag-traducao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Ampliar o acesso a informa\u00e7\u00f5es sobre o capacete Elmo foi a principal raz\u00e3o que levou a equipe do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), autarquia vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), a iniciar o processo de tradu\u00e7\u00e3o para o ingl\u00eas do site [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-10T19:04:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-10T19:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1090\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas\",\"datePublished\":\"2022-06-10T19:04:11+00:00\",\"dateModified\":\"2022-06-10T19:06:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\"},\"wordCount\":310,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png\",\"keywords\":[\"Cear\u00e1\",\"Elmo\",\"sa\u00fade\",\"Tradu\u00e7\u00e3o\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\",\"name\":\"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png\",\"datePublished\":\"2022-06-10T19:04:11+00:00\",\"dateModified\":\"2022-06-10T19:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png\",\"width\":1090,\"height\":574},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/","og_locale":"pt_BR","og_type":"article","og_title":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Ampliar o acesso a informa\u00e7\u00f5es sobre o capacete Elmo foi a principal raz\u00e3o que levou a equipe do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE), autarquia vinculada \u00e0 Secretaria da Sa\u00fade do Estado (Sesa), a iniciar o processo de tradu\u00e7\u00e3o para o ingl\u00eas do site [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-06-10T19:04:11+00:00","article_modified_time":"2022-06-10T19:06:23+00:00","og_image":[{"width":1090,"height":574,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/"},"author":{"name":"","@id":""},"headline":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas","datePublished":"2022-06-10T19:04:11+00:00","dateModified":"2022-06-10T19:06:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/"},"wordCount":310,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png","keywords":["Cear\u00e1","Elmo","sa\u00fade","Tradu\u00e7\u00e3o"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/","name":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png","datePublished":"2022-06-10T19:04:11+00:00","dateModified":"2022-06-10T19:06:23+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/06\/sssssss-1.png","width":1090,"height":574},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/06\/10\/visando-a-internacionalizacao-do-capacete-elmo-site-do-dispositivo-ganha-versao-em-ingles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Visando \u00e0 internacionaliza\u00e7\u00e3o do capacete Elmo, site do dispositivo ganha vers\u00e3o em ingl\u00eas"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=109990"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109990\/revisions"}],"predecessor-version":[{"id":109996,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109990\/revisions\/109996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/109992"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=109990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=109990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=109990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}