{"id":109679,"date":"2022-05-31T14:31:25","date_gmt":"2022-05-31T17:31:25","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=109679"},"modified":"2022-05-31T14:31:25","modified_gmt":"2022-05-31T17:31:25","slug":"forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/","title":{"rendered":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99197 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude.png\" alt=\"\" width=\"181\" height=\"69\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude.png 181w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Acesso-a-saude-120x46.png 120w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109680\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1-600x376.png\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nSeguem abertas at\u00e9 as 00h desta ter\u00e7a-feira (31) as<strong> inscri\u00e7\u00f5es para a submiss\u00e3o de trabalhos cient\u00edficos e produ\u00e7\u00f5es art\u00edsticas<\/strong> para o <em>I F\u00f3rum Cient\u00edfico de Sa\u00fade Mental e Aten\u00e7\u00e3o Psicossocial do Cear\u00e1<\/em>. O evento ser\u00e1 realizado em 1\u00ba de julho de forma h\u00edbrida (presencial e on-line) e ter\u00e1 como tema<em> Caminhos para o Fortalecimento da Pol\u00edtica Estadual de Sa\u00fade Mental, \u00c1lcool e outras Drogas<\/em>. Trabalhadores da Sa\u00fade, docentes, pesquisadores e estudantes da \u00e1rea poder\u00e3o compartilhar suas produ\u00e7\u00f5es cient\u00edficas.<\/p>\n<p>Os interessados em participar devem se inscrever pela <a href=\"https:\/\/manutencao.dev.org.br\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>plataforma Mapa da Sa\u00fade<\/strong><\/a>. <strong>Quem quiser acompanhar o evento como ouvinte, n\u00e3o apresentando trabalhos cient\u00edficos ou art\u00edsticos, tem at\u00e9 o pr\u00f3ximo dia 30 de junho para realizar a inscri\u00e7\u00e3o<\/strong>.<\/p>\n<p>O f\u00f3rum \u00e9 idealizado pela <strong>Secretaria da Sa\u00fade do Cear\u00e1 (Sesa)<\/strong>, por meio da Coordenadoria de Pol\u00edticas de Sa\u00fade Mental, \u00c1lcool e outras Drogas (Copom), e tem parceria da<strong> Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>.<\/p>\n<p>De acordo com a equipe organizadora do evento, a iniciativa foi pensada para <strong>partilhar e proporcionar um ambiente de integra\u00e7\u00e3o entre os trabalhos desenvolvidos na \u00e1rea da sa\u00fade mental no Estado<\/strong>, focando, especialmente, nos egressos das forma\u00e7\u00f5es da ESP\/CE neste campo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109681\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Corpo-da-Materia-2-768x465-1-600x363.png\" alt=\"\" width=\"775\" height=\"469\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Corpo-da-Materia-2-768x465-1-600x363.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Corpo-da-Materia-2-768x465-1.png 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nAs atividades ocorrer\u00e3o a partir das 8 horas da manh\u00e3 na modalidade h\u00edbrida, ou seja, com apresenta\u00e7\u00f5es presenciais na sede da autarquia e \u00e0 dist\u00e2ncia, em ambiente virtual. De acordo com o edital de submiss\u00e3o, ser\u00e3o convidados para participar presencialmente apenas os autores das produ\u00e7\u00f5es com melhor avalia\u00e7\u00e3o. <strong>A divulga\u00e7\u00e3o da programa\u00e7\u00e3o oficial completa do f\u00f3rum est\u00e1 prevista para a segunda semana de junho<\/strong>.<\/p>\n<h3>Trabalhos cient\u00edficos<\/h3>\n<p>Os trabalhos cient\u00edficos estar\u00e3o divididos em duas categorias. A primeira, ligada a <strong>resumos simples<\/strong>, contempla relatos de pesquisa com estudos realizados no campo da sa\u00fade mental e da aten\u00e7\u00e3o psicossocial; al\u00e9m de depoimentos de experi\u00eancia relacionados \u00e0s pr\u00e1ticas desenvolvidas pelos servi\u00e7os de sa\u00fade, de educa\u00e7\u00e3o e pela comunidade. As propostas selecionadas ser\u00e3o compartilhadas como <em>e-p\u00f4ster<\/em>\u00a0ou apresenta\u00e7\u00e3o oral.<\/p>\n<p>A segunda categoria abrange <strong>produ\u00e7\u00f5es art\u00edsticas, <\/strong>que ser\u00e3o apresentadas a partir da proposta da <em>Expo Smaps \u2013 Arte S\u00e3 e Salva<\/em>. Os participantes poder\u00e3o mostrar m\u00faltiplas pr\u00e1ticas e reflex\u00f5es em diferentes linguagens art\u00edsticas, como produ\u00e7\u00f5es textuais, fotos, v\u00eddeos e outras formas de express\u00e3o (pinturas, desenhos, dan\u00e7a, teatro, performances e interven\u00e7\u00f5es, por exemplo).<\/p>\n<p>Os trabalhos submetidos ter\u00e3o formato de apresenta\u00e7\u00e3o livre e ficar\u00e3o expostos na ESP\/CE durante uma semana, a partir da data de abertura do evento.<\/p>\n<h3>Servi\u00e7o<\/h3>\n<p><strong>I F\u00f3rum Cient\u00edfico de Sa\u00fade Mental e Aten\u00e7\u00e3o Psicossocial do Cear\u00e1<\/strong><br \/>\n<strong>Quando:<\/strong> 1\u00ba de julho de 2022<br \/>\n<strong>Inscri\u00e7\u00f5es para ouvintes:<\/strong> at\u00e9 30 de junho de 2022<br \/>\n<strong>Inscri\u00e7\u00f5es para submiss\u00e3o de trabalhos:<\/strong> 31 de maio de 2022<br \/>\n<a href=\"https:\/\/manutencao.dev.org.br\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Inscreva-se pela plataforma Mapa da Sa\u00fade<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguem abertas at\u00e9 as 00h desta ter\u00e7a-feira (31) as inscri\u00e7\u00f5es para a submiss\u00e3o de trabalhos cient\u00edficos e produ\u00e7\u00f5es art\u00edsticas para o I F\u00f3rum Cient\u00edfico de Sa\u00fade Mental e Aten\u00e7\u00e3o Psicossocial do Cear\u00e1. O evento ser\u00e1 realizado em 1\u00ba de julho de forma h\u00edbrida (presencial e on-line) e ter\u00e1 como tema Caminhos para o Fortalecimento da [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":109680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[2133,453,82],"class_list":["post-109679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-escola-de-saude-publica","tag-forum","tag-saude-mental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Seguem abertas at\u00e9 as 00h desta ter\u00e7a-feira (31) as inscri\u00e7\u00f5es para a submiss\u00e3o de trabalhos cient\u00edficos e produ\u00e7\u00f5es art\u00edsticas para o I F\u00f3rum Cient\u00edfico de Sa\u00fade Mental e Aten\u00e7\u00e3o Psicossocial do Cear\u00e1. O evento ser\u00e1 realizado em 1\u00ba de julho de forma h\u00edbrida (presencial e on-line) e ter\u00e1 como tema Caminhos para o Fortalecimento da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T17:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho\",\"datePublished\":\"2022-05-31T17:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\"},\"wordCount\":535,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png\",\"keywords\":[\"Escola de Sa\u00fade P\u00fablica\",\"F\u00f3rum\",\"sa\u00fade mental\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\",\"name\":\"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png\",\"datePublished\":\"2022-05-31T17:31:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png\",\"width\":768,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/","og_locale":"pt_BR","og_type":"article","og_title":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Seguem abertas at\u00e9 as 00h desta ter\u00e7a-feira (31) as inscri\u00e7\u00f5es para a submiss\u00e3o de trabalhos cient\u00edficos e produ\u00e7\u00f5es art\u00edsticas para o I F\u00f3rum Cient\u00edfico de Sa\u00fade Mental e Aten\u00e7\u00e3o Psicossocial do Cear\u00e1. O evento ser\u00e1 realizado em 1\u00ba de julho de forma h\u00edbrida (presencial e on-line) e ter\u00e1 como tema Caminhos para o Fortalecimento da [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-05-31T17:31:25+00:00","og_image":[{"width":768,"height":481,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/"},"author":{"name":"","@id":""},"headline":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho","datePublished":"2022-05-31T17:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/"},"wordCount":535,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png","keywords":["Escola de Sa\u00fade P\u00fablica","F\u00f3rum","sa\u00fade mental"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/","name":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png","datePublished":"2022-05-31T17:31:25+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Banner-materia-5-768x481-1.png","width":768,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/31\/forum-de-saude-mental-do-ceara-submissao-de-trabalhos-pode-ser-feita-ate-esta-terca-31-ouvintes-podem-se-inscrever-ate-30-de-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"F\u00f3rum de Sa\u00fade Mental do Cear\u00e1: submiss\u00e3o de trabalhos pode ser feita at\u00e9 esta ter\u00e7a (31); ouvintes podem se inscrever at\u00e9 30 de junho"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=109679"}],"version-history":[{"count":1,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109679\/revisions"}],"predecessor-version":[{"id":109682,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109679\/revisions\/109682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/109680"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=109679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=109679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=109679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}