{"id":109625,"date":"2022-05-30T12:27:42","date_gmt":"2022-05-30T15:27:42","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=109625"},"modified":"2022-05-30T13:11:31","modified_gmt":"2022-05-30T16:11:31","slug":"esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/","title":{"rendered":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99194 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Valorizacao-de-pessoas.png\" alt=\"\" width=\"235\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109627 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>A autarquia apresentar\u00e1 aos convidados alguns trabalhos e resultados desenvolvidos ao longo dos \u00faltimos anos, como o capacete Elmo<\/em><\/p>\n<p>A <strong>Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong>, em parceria com a <strong>Secretaria da Sa\u00fade do Estado (Sesa)<\/strong>, estar\u00e1 presente no <em>XIX Congresso do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE)<\/em>, ros pr\u00f3ximos dias 2 a 4 de junho, no <strong>Centro de Conven\u00e7\u00f5es do Cariri<\/strong>, situado no munic\u00edpio de Crato. O evento ter\u00e1 como tema principal <em>Aten\u00e7\u00e3o Prim\u00e1ria e Vigil\u00e2ncia: Caminhos para Integra\u00e7\u00e3o nos Territ\u00f3rios<\/em> e dever\u00e1 reunir cerca de <strong>500 participante<\/strong>s.<\/p>\n<p>Com um stand de exposi\u00e7\u00e3o de seus produtos e servi\u00e7os, a autarquia apresentar\u00e1 aos convidados alguns trabalhos e resultados desenvolvidos ao longo dos \u00faltimos anos. Dentre eles, o <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/23\/capacete-elmo-cruza-o-atlantico-e-e-apresentado-em-universidade-de-portugal\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>capacete de respira\u00e7\u00e3o assistida Elmo<\/strong><\/a>, equipamento n\u00e3o invasivo que foi desenvolvido em meio \u00e0 <strong>pandemia de covid-19<\/strong>. Estima-se que <strong>40 mil vidas foram salvas<\/strong> com o uso do dispositivo.<\/p>\n<p>Ser\u00e3o apresentados na ocasi\u00e3o, tamb\u00e9m, a <em>CadernosEsp<\/em>, revista cient\u00edfica da Escola com acesso aberto e gratuito, e os treinamentos \u00e0 dist\u00e2ncia realizados pelo Centro de Simula\u00e7\u00e3o Real\u00edstica, da Diretoria de Desenvolvimento Educacional, dentre outros servi\u00e7os.<\/p>\n<p>Al\u00e9m disso, diretores e o superintendente da ESP\/CE, Marcelo Alcantara, v\u00e3o dialogar com os congressistas em uma programa\u00e7\u00e3o que ocorrer\u00e1 no lounge ao lado do stand.<\/p>\n<h3>Confira a programa\u00e7\u00e3o no stand da ESP\/CE:<\/h3>\n<p><strong>2 de junho (quinta-feira)<\/strong><br \/>\n<strong>10h15:<\/strong> Projeto Ampliares e seu poder transformador nos territ\u00f3rios (Resid\u00eancias M\u00e9dica e Multiprofissional) &#8211; Ol\u00edvia Bessa (diretora de de Educa\u00e7\u00e3o e Extens\u00e3o da ESP\/CE)<br \/>\n<strong>11h45:<\/strong> Momento Elmo: capacete de respira\u00e7\u00e3o assistida salvador de vidas &#8211; Marcelo Alcantara (superintendente da ESP\/CE)<br \/>\n<strong>13H45:<\/strong> Nova ESP como ICT: vem nos conhecer! &#8211; Alice Pequeno (diretora de Inova\u00e7\u00e3o e Tecnologias da ESP\/CE)<\/p>\n<p><strong>3 de junho (sexta-feira)<\/strong><br \/>\n<strong>10h15:<\/strong> Centro de Intelig\u00eancia em Sa\u00fade &#8211; An\u00e1lise de dados a favor da gest\u00e3o p\u00fablica em Sa\u00fade &#8211; Roberta Albano (gerente de Intelig\u00eancia em Sa\u00fade da ESP\/CE)<br \/>\n<strong>11h45:<\/strong> Treinamentos \u00e0 dist\u00e2ncia e Centro de Simula\u00e7\u00e3o Real\u00edstica: capacita\u00e7\u00e3o para profissionais de sa\u00fade &#8211; Jos\u00e9 Batista Tomaz (diretor de Desenvolvimento Educacional)<br \/>\n<strong>13h45:<\/strong> Momento Elmo: capacete de respira\u00e7\u00e3o assistida salvador de vidas &#8211; Marcelo Alcantara (superintendente da ESP\/CE)<br \/>\n<strong>15h30:<\/strong> Promovendo a Ci\u00eancia &#8211; Produ\u00e7\u00e3o e dissemina\u00e7\u00e3o do conhecimento &#8211; Jadson Franco (gerente de Pesquisa em Sa\u00fade da ESP\/CE)<br \/>\nApresenta\u00e7\u00e3o do e-book <em>Enfrentamento \u00e0 Covid-19: a constru\u00e7\u00e3o da coragem coletiva<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109626 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Stand-banner-materia.png\" alt=\"\" width=\"776\" height=\"486\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Stand-banner-materia.png 776w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Stand-banner-materia-600x376.png 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/Stand-banner-materia-768x481.png 768w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><br \/>\nA programa\u00e7\u00e3o geral do congresso ser\u00e1 dedicada ao debate do tema central nas suas diversas perspectivas, contando com seis mesas tem\u00e1ticas e a participa\u00e7\u00e3o de palestrantes do Minist\u00e9rio da Sa\u00fade, da Sesa, al\u00e9m de membros de outros conselhos de classe.<\/p>\n<h3>Servi\u00e7o<\/h3>\n<p><strong>ESP\/CE no XIX Congresso do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE)<\/strong><br \/>\n<strong>Quando:<\/strong> 2 a 4 de junho<br \/>\n<strong>Local:<\/strong> Centro de Conven\u00e7\u00f5es do Cariri (Endere\u00e7o: Av. Padre C\u00edcero, 4400 &#8211; Muriti, Crato)<br \/>\n<a href=\"https:\/\/www.congressocosemsce.com.br\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Inscreva-se para participar<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A autarquia apresentar\u00e1 aos convidados alguns trabalhos e resultados desenvolvidos ao longo dos \u00faltimos anos, como o capacete Elmo A Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), em parceria com a Secretaria da Sa\u00fade do Estado (Sesa), estar\u00e1 presente no XIX Congresso do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE), ros [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":109627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,1039,2898,1857,2133,135],"class_list":["post-109625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-congresso","tag-cosems","tag-elmo","tag-escola-de-saude-publica","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A autarquia apresentar\u00e1 aos convidados alguns trabalhos e resultados desenvolvidos ao longo dos \u00faltimos anos, como o capacete Elmo A Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), em parceria com a Secretaria da Sa\u00fade do Estado (Sesa), estar\u00e1 presente no XIX Congresso do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE), ros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T15:27:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-30T16:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o\",\"datePublished\":\"2022-05-30T15:27:42+00:00\",\"dateModified\":\"2022-05-30T16:11:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\"},\"wordCount\":545,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\",\"keywords\":[\"Cear\u00e1\",\"congresso\",\"Cosems\",\"Elmo\",\"Escola de Sa\u00fade P\u00fablica\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\",\"name\":\"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\",\"datePublished\":\"2022-05-30T15:27:42+00:00\",\"dateModified\":\"2022-05-30T16:11:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/","og_locale":"pt_BR","og_type":"article","og_title":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A autarquia apresentar\u00e1 aos convidados alguns trabalhos e resultados desenvolvidos ao longo dos \u00faltimos anos, como o capacete Elmo A Escola de Sa\u00fade P\u00fablica Paulo Marcelo Martins Rodrigues (ESP\/CE), em parceria com a Secretaria da Sa\u00fade do Estado (Sesa), estar\u00e1 presente no XIX Congresso do Conselho das Secretarias Municipais de Sa\u00fade do Cear\u00e1 (Cosems\/CE), ros [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-05-30T15:27:42+00:00","article_modified_time":"2022-05-30T16:11:31+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/"},"author":{"name":"","@id":""},"headline":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o","datePublished":"2022-05-30T15:27:42+00:00","dateModified":"2022-05-30T16:11:31+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/"},"wordCount":545,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg","keywords":["Cear\u00e1","congresso","Cosems","Elmo","Escola de Sa\u00fade P\u00fablica","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/","name":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg","datePublished":"2022-05-30T15:27:42+00:00","dateModified":"2022-05-30T16:11:31+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/05\/photo1653328316.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/05\/30\/esp-ce-apresenta-produtos-e-servicos-em-xix-congresso-do-cosems-ce-no-crato-elmo-estara-em-exposicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"ESP\/CE apresenta produtos e servi\u00e7os em XIX Congresso do Cosems-CE, no Crato; Elmo estar\u00e1 em exposi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=109625"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109625\/revisions"}],"predecessor-version":[{"id":109631,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/109625\/revisions\/109631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/109627"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=109625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=109625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=109625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}