{"id":1092,"date":"2010-04-27T21:42:44","date_gmt":"2010-04-28T00:42:44","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/"},"modified":"2010-04-27T21:42:44","modified_gmt":"2010-04-28T00:42:44","slug":"prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/","title":{"rendered":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias"},"content":{"rendered":"<p><a href=\"images\/stories\/artigos\/banner_aprece_4dd694850258a.jpg\" onclick=\"window.open('images\/stories\/artigos\/banner_aprece_4dd694850258a.jpg','','width=821,height=402');return false;\"><\/a><br \/>Uma comiss\u00e3o de prefeitos de munic\u00edpios da Regi\u00e3o Metropolitana de Fortaleza (RMF), com a participa\u00e7\u00e3o de representante da Secretaria da Sa\u00fade do Estado, vai se encontrar com o Secret\u00e1rio Executivo da Regional II da Prefeitura de Fortaleza, Francisco Humberto de Carvalho Junior, para conhecer as pend\u00eancias para a libera\u00e7\u00e3o do alvar\u00e1 de funcionamento do Hospital Boghos Boyadjian, a fim de que o estabelecimento seja adquirido pelo Governo do Estado para a instala\u00e7\u00e3o do Hospital Metropolitano. Essa foi um dos encaminhamentos aprovados pelo N\u00facleo da Regi\u00e3o Metropolitana de Fortaleza, criado na Associa\u00e7\u00e3o dos Munic\u00edpios e Prefeitos do Estado do Cear\u00e1 (Aprece), que em sua primeira reuni\u00e3o, realizada na tarde desta ter\u00e7a-feira, 27, recebeu o Secret\u00e1rio da Sa\u00fade do Estado, Arruda Bastos. <\/p>\n<p>O futuro Hospital Metropolitano, que j\u00e1 est\u00e1 pronto, tem capacidade para atendimentos cl\u00ednicos e cir\u00fargicos com 220 leitos, 100 apartamentos e cinco salas de cirurgia. J\u00e1 acertado que as despesas de custeio, que podem chegar a R$ 4 milh\u00f5es, ser\u00e3o repartidas entre Estado (25%), munic\u00edpios da RMF (25%) e Governo Federal (50%). Arruda Bastos informou durante a reuni\u00e3o de prefeitos e secret\u00e1rios de sa\u00fade dos 15 munic\u00edpios da RMF que o recurso para a compra do hospital, no valor de R$ 53 milh\u00f5es, est\u00e1 garantido. <\/p>\n<p><a href=\"images\/stories\/artigos\/banner_aprece2_4dd6948525806.jpg\" onclick=\"window.open('images\/stories\/artigos\/banner_aprece2_4dd6948525806.jpg','','width=821,height=402');return false;\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/artigos\/banner_aprece2_4dd6948525806.jpg\" border=\"0\" width=\"268\" height=\"131\" align=\"left\" \/><\/a>Ficou acertada tamb\u00e9m a forma\u00e7\u00e3o de outra comiss\u00e3o de prefeitos para definir com a Secretaria da Sa\u00fade o perfil, a localiza\u00e7\u00e3o e o financiamento do novo hospital de urg\u00eancia e emerg\u00eancia que ser\u00e1 constru\u00eddo pelo Governo do Estado para a Copa do Mundo de Futebol de 2014, que ter\u00e1 Fortaleza como uma das subsedes. De acordo com o Secret\u00e1rio Arruda Bastos, para a constru\u00e7\u00e3o do novo hospital ser\u00e3o investidos R$ 150 milh\u00f5es e o equipamento dever\u00e1 ser instalado em um raio de 20 quil\u00f4metros do est\u00e1dio Castel\u00e3o, que abrigar\u00e1 os jogos da Copa em Fortaleza, possivelmente entre a Avenida Perimetral e o Anel Vi\u00e1rio da capital. <\/p>\n<p>Arruda Bastos informou sobre a cria\u00e7\u00e3o da Assessoria Especial da Regi\u00e3o Metropolitana de Fortaleza, ligada ao Gabinete do Secret\u00e1rio da Sa\u00fade, e convocou o representante da Aprece para a reuni\u00e3o do Comit\u00ea Cearense de Urg\u00eancia e Emerg\u00eancia, que acontecer\u00e1 na sexta-feira, \u00e0s 9 horas, na Sesa. A id\u00e9ia do Secret\u00e1rio \u00e9 melhorar os perfis das emerg\u00eancias terci\u00e1rias dos hospitais localizados na Capital e definir propostas para fortalecer os hospitais-polos para evitar transfer\u00eancias evit\u00e1veis de pacientes para Fortaleza. <\/p>\n<p><a href=\"images\/stories\/artigos\/banner_aprece3_4dd694852e4a5.jpg\" onclick=\"window.open('images\/stories\/artigos\/banner_aprece3_4dd694852e4a5.jpg','','width=821,height=402');return false;\"><img loading=\"lazy\" decoding=\"async\" src=\"images\/stories\/artigos\/banner_aprece3_4dd694852e4a5.jpg\" border=\"0\" width=\"266\" height=\"130\" align=\"right\" \/><\/a>O Secret\u00e1rio da Sa\u00fade anunciou, ainda, sete novas ambul\u00e2ncias j\u00e1 garantidas pelo Governo federal para a implanta\u00e7\u00e3o do Servi\u00e7o M\u00f3vel de Atendimento de Urg\u00eancia (SAMU) nas regi\u00f5es Litoral Oeste e Metropolitana Leste. Com esses novos servi\u00e7os, somados ao SAMU Litoral Leste, 50 munic\u00edpios estar\u00e3o cobertos. Sobre as sete Unidades de Pronto Atendimento (UPAs) que ser\u00e3o constru\u00eddas na RMF \u2013 em Maranguape, Caucaia, S\u00e3o Gon\u00e7alo do Amarante e quatro em Fortaleza \u2013, Arruda Bastos disse que s\u00f3 precisa os munic\u00edpios garantirem o terreno para o in\u00edcio das obras.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma comiss\u00e3o de prefeitos de munic\u00edpios da Regi\u00e3o Metropolitana de Fortaleza (RMF), com a participa\u00e7\u00e3o de representante da Secretaria da Sa\u00fade do Estado, vai se encontrar com o Secret\u00e1rio Executivo da Regional II da Prefeitura de Fortaleza, Francisco Humberto de Carvalho Junior, para conhecer as pend\u00eancias para a libera\u00e7\u00e3o do alvar\u00e1 de funcionamento do Hospital [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1092","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Uma comiss\u00e3o de prefeitos de munic\u00edpios da Regi\u00e3o Metropolitana de Fortaleza (RMF), com a participa\u00e7\u00e3o de representante da Secretaria da Sa\u00fade do Estado, vai se encontrar com o Secret\u00e1rio Executivo da Regional II da Prefeitura de Fortaleza, Francisco Humberto de Carvalho Junior, para conhecer as pend\u00eancias para a libera\u00e7\u00e3o do alvar\u00e1 de funcionamento do Hospital [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-28T00:42:44+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias\",\"datePublished\":\"2010-04-28T00:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\",\"name\":\"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-04-28T00:42:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Uma comiss\u00e3o de prefeitos de munic\u00edpios da Regi\u00e3o Metropolitana de Fortaleza (RMF), com a participa\u00e7\u00e3o de representante da Secretaria da Sa\u00fade do Estado, vai se encontrar com o Secret\u00e1rio Executivo da Regional II da Prefeitura de Fortaleza, Francisco Humberto de Carvalho Junior, para conhecer as pend\u00eancias para a libera\u00e7\u00e3o do alvar\u00e1 de funcionamento do Hospital [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-04-28T00:42:44+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias","datePublished":"2010-04-28T00:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/"},"wordCount":544,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/","name":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-04-28T00:42:44+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/04\/27\/prefeitos-da-rmf-se-reunem-com-arruda-bastos-e-encaminham-providencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Prefeitos da RMF se re\u00fanem com Arruda Bastos e encaminham provid\u00eancias"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1092"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1092\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}