{"id":1079,"date":"2009-04-22T18:55:02","date_gmt":"2009-04-22T21:55:02","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/"},"modified":"2009-04-22T18:55:02","modified_gmt":"2009-04-22T21:55:02","slug":"policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/","title":{"rendered":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental"},"content":{"rendered":"<p>A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE), respons\u00e1vel pela sele\u00e7\u00e3o e capacita\u00e7\u00e3o dos diretores de Policl\u00ednicas e Centros de Especialidades Odontol\u00f3gicas, divulga a rela\u00e7\u00e3o dos habilitados para a Avalia\u00e7\u00e3o Comportamental (fase II da segunda etapa do processo seletivo).<\/p>\n<p>A rela\u00e7\u00e3o dos nomes est\u00e1 de acordo com a classifica\u00e7\u00e3o por fun\u00e7\u00e3o de dire\u00e7\u00e3o. O candidato que quiser informa\u00e7\u00f5es mais detalhadas sobre a pontua\u00e7\u00e3o deve acessar o sistema com o n\u00famero do seu CPF. Todas as informa\u00e7\u00f5es est\u00e3o dispon\u00edveis no site <a href=\"https:\/\/www.esp.ce.gov.br\" target=\"_blank\">www.esp.ce.gov.br<\/a>.<\/p>\n<p>Os candidatos aprovados nessa fase ser\u00e3o submetidos \u00e0 Avalia\u00e7\u00e3o Comportamental, que consiste em quatro momentos: integra\u00e7\u00e3o e nivelamento conceitual; realiza\u00e7\u00e3o de provas situacionais &#8211; onde ser\u00e3o observadas atitudes e comportamento dos candidatos atrav\u00e9s de jogos, din\u00e2micas de grupo e situa\u00e7\u00f5es-problemas &#8211; entrevista individual e entrevista devolutiva (feedback obrigat\u00f3rio para candidatos aprovados), conforme os editais do processo seletivo.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 integra\u00e7\u00e3o e nivelamento, os candidatos far\u00e3o, nos dias 23, 24 e 25 de abril, das 8h \u00e0s 17h no audit\u00f3rio Ciro Gomes da ESP-CE (Avenida Ant\u00f4nio Justa, 3161, Meireles), o Curso sobre Novos Paradigmas para Gest\u00e3o e Lideran\u00e7a. O objetivo \u00e9 nivelar os candidatos acerca do perfil necess\u00e1rio para o desempenho das atividades como gestor.<\/p>\n<p>De 27 de abril a 06 de maio acontecer\u00e3o as din\u00e2micas e provas situacionais, sempre no per\u00edodo da manh\u00e3 (08h \u00e0s 12h). As entrevistas ser\u00e3o realizadas de 07 a 14 de maio, de acordo com cronograma divulgado posteriormente.<\/p>\n<p>Na avalia\u00e7\u00e3o comportamental n\u00e3o ser\u00e1 atribu\u00edda nota. O candidato ser\u00e1 considerado indicado para o perfil do cargo se, conforme processo avaliativo, demonstrar possuir perfil compat\u00edvel com as atividades inerentes \u00e0 fun\u00e7\u00e3o. O candidato considerado n\u00e3o-indicado ser\u00e1 eliminado da sele\u00e7\u00e3o p\u00fablica.<\/p>\n<p>A lista definitiva dos aprovados na Avalia\u00e7\u00e3o Comportamental ser\u00e1 divulgada dia 18 de maio.\u00a0 O Curso de Especializa\u00e7\u00e3o em Gest\u00e3o de Servi\u00e7os de Sa\u00fade, terceira e \u00faltima etapa do processo seletivo, acontecer\u00e1 de 22 de maio a 24 de novembro. O resultado final da sele\u00e7\u00e3o ser\u00e1 divulgado em 27 de novembro.<\/p>\n<p>&nbsp;<\/p>\n<p>Escola de Sa\u00fade P\u00fablica do Cear\u00e1<br \/>Assessoria de Comunica\u00e7\u00e3o e Marketing<br \/>Jornalista Sheila Raquel <br \/>Fone: (85) 3101.1412 &#8211; 9619.1828 \u2013 8877.8389<br \/><a href=\"https:\/\/www.esp.ce.gov.br\" target=\"_blank\">www.esp.ce.gov.br<\/a> | ascom@esp.ce.gov.br<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE), respons\u00e1vel pela sele\u00e7\u00e3o e capacita\u00e7\u00e3o dos diretores de Policl\u00ednicas e Centros de Especialidades Odontol\u00f3gicas, divulga a rela\u00e7\u00e3o dos habilitados para a Avalia\u00e7\u00e3o Comportamental (fase II da segunda etapa do processo seletivo). A rela\u00e7\u00e3o dos nomes est\u00e1 de acordo com a classifica\u00e7\u00e3o por fun\u00e7\u00e3o de dire\u00e7\u00e3o. O candidato [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1079","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE), respons\u00e1vel pela sele\u00e7\u00e3o e capacita\u00e7\u00e3o dos diretores de Policl\u00ednicas e Centros de Especialidades Odontol\u00f3gicas, divulga a rela\u00e7\u00e3o dos habilitados para a Avalia\u00e7\u00e3o Comportamental (fase II da segunda etapa do processo seletivo). A rela\u00e7\u00e3o dos nomes est\u00e1 de acordo com a classifica\u00e7\u00e3o por fun\u00e7\u00e3o de dire\u00e7\u00e3o. O candidato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T21:55:02+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental\",\"datePublished\":\"2009-04-22T21:55:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\"},\"wordCount\":411,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\",\"name\":\"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-04-22T21:55:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/","og_locale":"pt_BR","og_type":"article","og_title":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP-CE), respons\u00e1vel pela sele\u00e7\u00e3o e capacita\u00e7\u00e3o dos diretores de Policl\u00ednicas e Centros de Especialidades Odontol\u00f3gicas, divulga a rela\u00e7\u00e3o dos habilitados para a Avalia\u00e7\u00e3o Comportamental (fase II da segunda etapa do processo seletivo). A rela\u00e7\u00e3o dos nomes est\u00e1 de acordo com a classifica\u00e7\u00e3o por fun\u00e7\u00e3o de dire\u00e7\u00e3o. O candidato [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-04-22T21:55:02+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental","datePublished":"2009-04-22T21:55:02+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/"},"wordCount":411,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/","name":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-04-22T21:55:02+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/22\/policlinicas-e-ceos-comeca-convocacao-dos-aprovados-para-avaliacao-comportamental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Policl\u00ednicas e CEOS: come\u00e7a convoca\u00e7\u00e3o dos aprovados para Avalia\u00e7\u00e3o Comportamental"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1079"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1079\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}