{"id":1074,"date":"2009-04-23T19:45:56","date_gmt":"2009-04-23T22:45:56","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/"},"modified":"2009-04-23T19:45:56","modified_gmt":"2009-04-23T22:45:56","slug":"policlinica-de-russas-vai-atender-populacao-de-cinco-municipios","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/","title":{"rendered":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios"},"content":{"rendered":"<p>A popula\u00e7\u00e3o dos munic\u00edpios de Russas, Jaguaretama, Jaguaruana, Morada Nova e Palhano ser\u00e3o atendidos, com acesso a exames atualmente realizados\u00a0 apenas na capital, na nova policl\u00ednica que o Governo do Estado come\u00e7a a construir neste s\u00e1bado, 24. O Governador Cid Gomes e o Secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias, far\u00e3o a assinatura da ordem de servi\u00e7os \u00e0s 9 horas, na pra\u00e7a matriz de Russas. <br \/>A policl\u00ednica aumentar\u00e1 a oferta de exames no Interior do Estado, com ambulat\u00f3rios especializados em diferentes \u00e1reas. J\u00e1 tem policl\u00ednicas em constru\u00e7\u00e3o em Pacajus e Baturit\u00e9. Nas tr\u00eas policl\u00ednicas, incluindo a de Russas, os recursos s\u00e3o exclusivamente do Tesouro do Estado. Al\u00e9m dessas tr\u00eas, est\u00e1 definida a constru\u00e7\u00e3o de mais 18 policl\u00ednicas no Programa de Expans\u00e3o e Melhoria da Assist\u00eancia no Estado do Cear\u00e1, 16 Centros de Especialidades Odontol\u00f3gicas, com cinco j\u00e1 em constru\u00e7\u00e3o, e dois hospitais regionais, um no Cariri e outro na regi\u00e3o Norte. No Cariri, o hospital est\u00e1 em constru\u00e7\u00e3o. <\/p>\n<p>Nas novas policl\u00ednicas, a popula\u00e7\u00e3o do Interior ter\u00e1 acesso a exames e servi\u00e7os que atualmente, na rede p\u00fablica, s\u00e3o realizados somente na Capital. \u00c9 o caso do ecocardiograma, ofertados hoje por tr\u00eas hospitais estaduais, localizados na Capital &#8211;\u00a0 Hospital Geral de Fortaleza, Hospital de Messejana e Hospital Geral C\u00e9sar Cals. \u201cCom esse servi\u00e7o queremos acabar com a fila de espera pelo ecocardiograma, sem ser necess\u00e1rio o paciente sair da regi\u00e3o onde mora\u201d, afirma o Secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias. S\u00f3 para se ter uma id\u00e9ia da import\u00e2ncia desse servi\u00e7o, o Secret\u00e1rio lembra que hoje h\u00e1 253 pacientes na fila, aguardando a realiza\u00e7\u00e3o de ecocardioagrama. Outros servi\u00e7os importantes oferecidos pelas policl\u00ednicas: eletrocardiograma, endoscopia digestiva e respirat\u00f3ria, ultrassonografia, raio x. Com o objetivo de prevenir e controlar o c\u00e2ncer, nas novas unidades tamb\u00e9m ser\u00e3o feitos exames de mamografia. Somando mamografias e os diversos tipos de exames, cada policl\u00ednica far\u00e1 3344 exames por m\u00eas.<\/p>\n<p>A previs\u00e3o \u00e9 de que cada policl\u00ednica, com 92 profissionais, realize 3.696 consultas mensais. Os ambulat\u00f3rios especializados incluem oftalmologia, otorrinolaringologia, cl\u00ednica m\u00e9dica, cardiologia, ginecologia, mastologia, cirurgia geral, gastroenterologia, urologia. Nas policl\u00ednicas os pacientes com diabete ter\u00e3o sala do p\u00e9 diab\u00e9tico. Haver\u00e1 ainda sala de curativos, sala de gesso, sala de coleta de exames e cinco leitos de observa\u00e7\u00e3o.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre as policl\u00ednicas de Russas, Pacajus e Baturit\u00e9:<br \/><strong><br \/>RUSSAS<\/strong><br \/>\u00c1rea constru\u00edda \u2013 2.400 metros quadrados<br \/>Valor da obra \u2013 R$ 3.212.524,45<br \/>Prazo de execu\u00e7\u00e3o \u2013 8 meses<br \/>Construtora \u2013 Construtora e Imobili\u00e1ria JMV Ltda <br \/>Endere\u00e7o \u2013 Rua Felipe Santiago, s\/n.<br \/><strong><br \/>PACAJUS<\/strong><br \/>\u00c1rea constru\u00edda \u2013 2.400 metros quadrados<br \/>Valor da obra \u2013 R$2.771.652,38<br \/>Prazo de execu\u00e7\u00e3o \u2013 8 meses<br \/>Construtora &#8211; Tecnocon<br \/>Endere\u00e7o \u2013 Av. Doca Nogueira, s\/n, Cruz das Almas.<\/p>\n<p><strong>BATURIT\u00c9<\/strong><br \/>\u00c1rea constru\u00edda \u2013 2.400 metros quadrados<br \/>Valor da obra \u2013 R$ 2.946.134,12<br \/>Prazo de execu\u00e7\u00e3o \u2013 8 meses<br \/>Construtora \u2013 Ampengenharia Ltda<br \/>Endere\u00e7o \u2013 Rua Coronel Pedro Castelo, s\/n, Centro.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A popula\u00e7\u00e3o dos munic\u00edpios de Russas, Jaguaretama, Jaguaruana, Morada Nova e Palhano ser\u00e3o atendidos, com acesso a exames atualmente realizados\u00a0 apenas na capital, na nova policl\u00ednica que o Governo do Estado come\u00e7a a construir neste s\u00e1bado, 24. O Governador Cid Gomes e o Secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias, far\u00e3o a assinatura da ordem de servi\u00e7os [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1074","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A popula\u00e7\u00e3o dos munic\u00edpios de Russas, Jaguaretama, Jaguaruana, Morada Nova e Palhano ser\u00e3o atendidos, com acesso a exames atualmente realizados\u00a0 apenas na capital, na nova policl\u00ednica que o Governo do Estado come\u00e7a a construir neste s\u00e1bado, 24. O Governador Cid Gomes e o Secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias, far\u00e3o a assinatura da ordem de servi\u00e7os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-23T22:45:56+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios\",\"datePublished\":\"2009-04-23T22:45:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\",\"name\":\"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-04-23T22:45:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/","og_locale":"pt_BR","og_type":"article","og_title":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A popula\u00e7\u00e3o dos munic\u00edpios de Russas, Jaguaretama, Jaguaruana, Morada Nova e Palhano ser\u00e3o atendidos, com acesso a exames atualmente realizados\u00a0 apenas na capital, na nova policl\u00ednica que o Governo do Estado come\u00e7a a construir neste s\u00e1bado, 24. O Governador Cid Gomes e o Secret\u00e1rio da Sa\u00fade, Jo\u00e3o Ananias, far\u00e3o a assinatura da ordem de servi\u00e7os [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-04-23T22:45:56+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios","datePublished":"2009-04-23T22:45:56+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/"},"wordCount":519,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/","name":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-04-23T22:45:56+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/04\/23\/policlinica-de-russas-vai-atender-populacao-de-cinco-municipios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Policl\u00ednica de Russas vai atender popula\u00e7\u00e3o de cinco munic\u00edpios"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1074"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1074\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}