{"id":1069,"date":"2010-03-17T17:37:32","date_gmt":"2010-03-17T20:37:32","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/"},"modified":"2010-03-17T17:37:32","modified_gmt":"2010-03-17T20:37:32","slug":"pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/","title":{"rendered":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia"},"content":{"rendered":"<p>A Secretaria da Sa\u00fade do Estado e a Secretaria de Sa\u00fade de Fortaleza iniciam uma pesquisa sobre o perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia na capital. Nesta segunda-feira, 22, \u00e0s 8h30min, no Magna Praia Hotel,\u00a0 Avenida Historiador Raimundo Gir\u00e3o, 1002, come\u00e7am dos trabalhados da pesquisa, na \u201cOficina de lan\u00e7amento e planejamento do diagn\u00f3stico socioecon\u00f4mico e da sa\u00fade da pessoa com defici\u00eancia do munic\u00edpio de Fortaleza\u201d.\u00a0 A oficina vai apresentar o plano de trabalho da pesquisa que vai envolver cerca de 20 supervisores e pesquisadores no levantamento do n\u00famero de pessoas com defici\u00eancia, tipo de defici\u00eancia e an\u00e1lise do atendimento na rede de sa\u00fade. O relat\u00f3rio final, com lan\u00e7amento previsto para agosto deste ano, vai dar subs\u00eddios para o planejamento das atividades de inclus\u00e3o da pessoa com defici\u00eancia na sociedade, com \u00eanfase nas a\u00e7\u00f5es de sa\u00fade, educa\u00e7\u00e3o, esporte e de capacita\u00e7\u00e3o para o trabalho.<\/p>\n<p>O Censo populacional de 2000 (IBGE) identificou que o Cear\u00e1 est\u00e1 entre os cinco estados brasileiros com maior n\u00famero de pessoas com defici\u00eancia (17,34% da popula\u00e7\u00e3o). Fortaleza possui atualmente aproximadamente 293 mil pessoas com defici\u00eancia. De acordo com o Censo de 2000, no Brasil 24,5 milh\u00f5es de pessoas (14,5% da popula\u00e7\u00e3o) t\u00eam algum tipo de defici\u00eancia, desde alguma dificuldade para andar, ouvir e enxergar, at\u00e9 as graves les\u00f5es incapacitantes. Foram detectadas 48% de pessoas com defici\u00eancia visual, 23% com defici\u00eancia motora, 17% com defici\u00eancia auditiva, 8% com defici\u00eancia intelectual e 4% com defici\u00eancia f\u00edsica.<\/p>\n<p>As principais causas de defici\u00eancia est\u00e3o correlacionadas a eventos como transtornos cong\u00eanitos e perinatais, doen\u00e7as transmiss\u00edveis e cr\u00f4nicas, perturba\u00e7\u00f5es psiqui\u00e1tricas, abusos de \u00e1lcool e droga, desnutri\u00e7\u00e3o, traumas e les\u00f5es (viol\u00eancia, acidentes no tr\u00e2nsito, no trabalho e na moradia). A elas somam-se as conseq\u00fc\u00eancias das mudan\u00e7as do perfil epidemiol\u00f3gico e o aumento da esperan\u00e7a de vida no pa\u00eds, que amplia a necessidade de a\u00e7\u00f5es de preven\u00e7\u00e3o voltadas ao diabetes, hipertens\u00e3o arterial, doen\u00e7as vasculares, quedas de pessoas idosas e traumas.<\/p>\n<p>A Conven\u00e7\u00e3o da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) sobre os Direitos das Pessoas com Defici\u00eancia, incorporada \u00e0 Constitui\u00e7\u00e3o brasileira de 2008, \u00e9 composta por cinq\u00fcenta artigos. Ela trata dos direitos civis, pol\u00edticos, econ\u00f4micos, sociais e culturais das pessoas com defici\u00eancia, e as definem, em seu artigo 1\u00ba como: \u201caquelas que t\u00eam impedimentos de longo prazo de natureza f\u00edsica, mental, intelectual ou sensorial, os quais, em intera\u00e7\u00e3o com diversas barreiras, podem obstruir sua participa\u00e7\u00e3o plena e efetiva na sociedade em igualdade de condi\u00e7\u00f5es com as demais pessoas\u201d.<\/p>\n<p>A Pol\u00edtica Nacional de Sa\u00fade da Pessoa com Defici\u00eancia, institu\u00edda pela Portaria MS\/GM n\u00ba 1.060, de 5 de junho de 2002, define, como prop\u00f3sitos gerais: proteger a sa\u00fade da pessoa com defici\u00eancia; reabilitar a pessoa com defici\u00eancia na sua capacidade funcional e desempenho humano, contribuindo para a sua inclus\u00e3o em todas as esferas da vida social; e prevenir agravos que determinem o aparecimento de defici\u00eancias.<\/p>\n<p>Incluir socialmente as pessoas com defici\u00eancia significa respeitar as necessidades pr\u00f3prias da sua condi\u00e7\u00e3o e possibilitar acesso aos servi\u00e7os p\u00fablicos, aos bens culturais e art\u00edsticos e aos produtos decorrentes do avan\u00e7o social, pol\u00edtico, econ\u00f4mico, cient\u00edfico e tecnol\u00f3gico da sociedade contempor\u00e2nea.<br \/><strong><\/p>\n<p><\/strong><\/p>\n<div align=\"center\"><strong>PROGRAMA\u00c7\u00c3O<\/strong><\/div>\n<p><strong>8 horas<\/strong> &#8211; Inscri\u00e7\u00e3o;<\/p>\n<p><strong>9 horas<\/strong> &#8211; abertura e composi\u00e7\u00e3o da mesa;<\/p>\n<p><strong>9h40<\/strong> &#8211; palestra de abertura;<\/p>\n<p><strong>10h10 <\/strong>&#8211; assinatura do termo de parceria entre as Secretarias Estadual e Municipal de Sa\u00fade e a SDH\/COPEDEF;<\/p>\n<p><strong>10h20<\/strong> &#8211; apresenta\u00e7\u00e3o dos programas\/a\u00e7\u00f5es das Secretarias de Sa\u00fade na \u00e1rea da pessoa com defici\u00eancia;<\/p>\n<p><strong>11 horas<\/strong> &#8211; apresenta\u00e7\u00e3o do plano de trabalho preliminar da pesquisa; e,<\/p>\n<p><strong>11h20<\/strong> &#8211; apresenta\u00e7\u00e3o dos participantes e forma\u00e7\u00e3o dos grupos de trabalho;<\/p>\n<p><strong>12h30<\/strong> &#8211; almo\u00e7o.<\/p>\n<p><strong>14 horas \u00e0s 17h30min<\/strong><\/p>\n<p>&#8211; Grupos de trabalho<\/p>\n<blockquote><p>Grupo I \u2013 Debate e aperfei\u00e7oamento do question\u00e1rio de campo.<br \/>Grupo II \u2013 Debate e aperfei\u00e7oamento da metodologia com atua\u00e7\u00e3o dos parceiros.<br \/>Grupo III \u2013 Elabora\u00e7\u00e3o do roteiro de entrevistas de acordo com as pol\u00edticas, planos e programas existentes dirigidos \u00e0 pessoa com defici\u00eancia, a intersetorialidade e as responsabilidades institucionais.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Sa\u00fade do Estado e a Secretaria de Sa\u00fade de Fortaleza iniciam uma pesquisa sobre o perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia na capital. Nesta segunda-feira, 22, \u00e0s 8h30min, no Magna Praia Hotel,\u00a0 Avenida Historiador Raimundo Gir\u00e3o, 1002, come\u00e7am dos trabalhados da pesquisa, na \u201cOficina de lan\u00e7amento e planejamento do [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1069","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Secretaria da Sa\u00fade do Estado e a Secretaria de Sa\u00fade de Fortaleza iniciam uma pesquisa sobre o perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia na capital. Nesta segunda-feira, 22, \u00e0s 8h30min, no Magna Praia Hotel,\u00a0 Avenida Historiador Raimundo Gir\u00e3o, 1002, come\u00e7am dos trabalhados da pesquisa, na \u201cOficina de lan\u00e7amento e planejamento do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-17T20:37:32+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia\",\"datePublished\":\"2010-03-17T20:37:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\"},\"wordCount\":752,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\",\"name\":\"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2010-03-17T20:37:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Secretaria da Sa\u00fade do Estado e a Secretaria de Sa\u00fade de Fortaleza iniciam uma pesquisa sobre o perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia na capital. Nesta segunda-feira, 22, \u00e0s 8h30min, no Magna Praia Hotel,\u00a0 Avenida Historiador Raimundo Gir\u00e3o, 1002, come\u00e7am dos trabalhados da pesquisa, na \u201cOficina de lan\u00e7amento e planejamento do [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2010-03-17T20:37:32+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia","datePublished":"2010-03-17T20:37:32+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/"},"wordCount":752,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/","name":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2010-03-17T20:37:32+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2010\/03\/17\/pesquisa-mostrara-perfil-socioeconomico-e-da-saude-das-pessoas-com-deficiencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Pesquisa ter\u00e1 perfil socioecon\u00f4mico e da sa\u00fade das pessoas com defici\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1069"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1069\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}