{"id":1064,"date":"2009-06-05T19:08:35","date_gmt":"2009-06-05T22:08:35","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/"},"modified":"2009-06-05T19:08:35","modified_gmt":"2009-06-05T22:08:35","slug":"peca-teatral-reforca-mobilizacao-contra-a-dengue","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/","title":{"rendered":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue"},"content":{"rendered":"<p>A Cia. de Teatro &#8220;Os Cara da Arte&#8221; faz na segunda-feira, 8 de junho, apresenta\u00e7\u00f5es da pe\u00e7a \u201cRomeu e Julieta no tempo da dengue\u201d, de autoria de Jos\u00e9 Mapurunga, na Escola Joaquim Albano, no Dion\u00edsio Torres, \u00e0s 15 horas, e no Shopping Benfica, \u00e0s 17 hora. Antes, \u00e0s 12 horas, a pe\u00e7a ser\u00e1 encenada para os servidores da Secretaria da Sa\u00fade, na sede da Sesa, na Av. Almirante Barroso, 600, Praia de Iracema. As apresenta\u00e7\u00f5es integram projeto da Coordenadoria de Promo\u00e7\u00e3o e Prote\u00e7\u00e3o \u00e0 Sa\u00fade, que visa levar \u00e0 popula\u00e7\u00e3o do Estado informa\u00e7\u00f5es b\u00e1sicas sobre os cuidados necess\u00e1rios no combate \u00e0 dengue. A escolha do teatro, mais especificamente do teatro de rua, \u00e9 pelo seu apelo ao mesmo tempo c\u00f4mico e educativo.<\/p>\n<p>Em Fortaleza, as apresenta\u00e7\u00f5es come\u00e7aram na sexta-feira, 5 de junho, e acontecer\u00e3o, ainda, nos dias\u00a0 9, 10, 12 e 15 deste m\u00eas em mais oito escolas, contemplando as seis regionais da cidade. No ano passado, a vers\u00e3o radiof\u00f4nica da pe\u00e7a foi enviada a todos os munic\u00edpios do Cear\u00e1 para veicula\u00e7\u00e3o p\u00fablica, com o objetivo de envolver a popula\u00e7\u00e3o no combate ao mosquito Aedes aegypti e no controle da doen\u00e7a.<\/p>\n<p>De acordo com o boletim semanal divulgado na sexta-feira pela Secretaria da Sa\u00fade, at\u00e9 o dia 5 de junho haviam sido confirmados 3.290 casos de dengue em 91 munic\u00edpios do Cear\u00e1 em 2009. Casos confirmados de dengue hemorr\u00e1gico foram 11, com um \u00f3bito. Por m\u00eas, o n\u00famero de casos confirmados vem diminuindo desde mar\u00e7o, quando foi registrado o pico de 1.551 casos. Em abril foram 493 casos confirmados e, em maio, 100 casos.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Cia. de Teatro &#8220;Os Cara da Arte&#8221; faz na segunda-feira, 8 de junho, apresenta\u00e7\u00f5es da pe\u00e7a \u201cRomeu e Julieta no tempo da dengue\u201d, de autoria de Jos\u00e9 Mapurunga, na Escola Joaquim Albano, no Dion\u00edsio Torres, \u00e0s 15 horas, e no Shopping Benfica, \u00e0s 17 hora. Antes, \u00e0s 12 horas, a pe\u00e7a ser\u00e1 encenada para [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1064","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Cia. de Teatro &#8220;Os Cara da Arte&#8221; faz na segunda-feira, 8 de junho, apresenta\u00e7\u00f5es da pe\u00e7a \u201cRomeu e Julieta no tempo da dengue\u201d, de autoria de Jos\u00e9 Mapurunga, na Escola Joaquim Albano, no Dion\u00edsio Torres, \u00e0s 15 horas, e no Shopping Benfica, \u00e0s 17 hora. Antes, \u00e0s 12 horas, a pe\u00e7a ser\u00e1 encenada para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-05T22:08:35+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue\",\"datePublished\":\"2009-06-05T22:08:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\",\"name\":\"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"datePublished\":\"2009-06-05T22:08:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Cia. de Teatro &#8220;Os Cara da Arte&#8221; faz na segunda-feira, 8 de junho, apresenta\u00e7\u00f5es da pe\u00e7a \u201cRomeu e Julieta no tempo da dengue\u201d, de autoria de Jos\u00e9 Mapurunga, na Escola Joaquim Albano, no Dion\u00edsio Torres, \u00e0s 15 horas, e no Shopping Benfica, \u00e0s 17 hora. Antes, \u00e0s 12 horas, a pe\u00e7a ser\u00e1 encenada para [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2009-06-05T22:08:35+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue","datePublished":"2009-06-05T22:08:35+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/"},"wordCount":284,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/","name":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"datePublished":"2009-06-05T22:08:35+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2009\/06\/05\/peca-teatral-reforca-mobilizacao-contra-a-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Pe\u00e7a teatral refor\u00e7a mobiliza\u00e7\u00e3o contra a dengue"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1064"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1064\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}