{"id":105199,"date":"2022-01-19T11:16:18","date_gmt":"2022-01-19T14:16:18","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=105199"},"modified":"2022-01-19T14:52:12","modified_gmt":"2022-01-19T17:52:12","slug":"esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/","title":{"rendered":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99194 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_Valorizacao-de-pessoas.png\" alt=\"\" width=\"235\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-105201\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845-600x376.jpeg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845-600x376.jpeg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845-1200x751.jpeg 1200w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845-768x481.jpeg 768w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845-1536x962.jpeg 1536w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg 1616w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nA <strong>Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE)<\/strong> e a <strong>Secretaria da Sa\u00fade do Estado (Sesa)<\/strong> realizam, nesta quarta (19) e quinta-feira (20), o curso <em>Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar<\/em>.<\/p>\n<p>Em <strong>formato virtual<\/strong> e com <strong>carga hor\u00e1ria de quatro horas\/aula<\/strong>, a atividade tem o objetivo de <strong>capacitar m\u00e9dicos, enfermeiros e fisioterapeutas que atuam no atendimento de pacientes com Covid-19 ou influenza<\/strong> na rede p\u00fablica de sa\u00fade.<\/p>\n<p>Devem participar do curso profissionais pertencentes \u00e0s <strong>Unidades de Pronto Atendimento (UPAs)<\/strong> e de<strong> Internamento (enfermaria)<\/strong> das <strong>cinco Regi\u00f5es de Sa\u00fade<\/strong> do Estado.<\/p>\n<p>A capacita\u00e7\u00e3o ter\u00e1 como facilitadores o infectologista e consultor especial da ESP\/CE, Keny Colares; o pneumologista e supervisor do Centro de Educa\u00e7\u00e3o Permanente em Gest\u00e3o e Sa\u00fade da Escola, Fabr\u00edcio Martins; e a fisioterapeuta e instrutora de capacita\u00e7\u00f5es da ESP\/CE, Andrea Braide.<\/p>\n<p>Para participar, o profissional da Sa\u00fade deve acessar o link da sala virtual no respectivo dia da sua regi\u00e3o, \u00e0s 14h. Ao fim da atividade, um <strong>certificado ser\u00e1 emitido<\/strong> aos presentes.<\/p>\n<h3>Servi\u00e7o<\/h3>\n<p><strong>19.01 | 14h<\/strong><\/p>\n<p><strong>Curso Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar<\/strong><br \/>\n<strong>P\u00fablico:<\/strong> M\u00e9dicos, fisioterapeutas, enfermeiros das Unidades de Pronto Atendimento (UPAs) e de Internamento (enfermaria)<br \/>\n<strong>Regi\u00f5es:<\/strong> Fortaleza e Litoral Leste<br \/>\n<strong>Facilitadores:<\/strong> Keny Colares, infectologista; Fabr\u00edcio Martins, pneumologista; e Andrea Braide, fisioterapeuta.<br \/>\n<a href=\"https:\/\/meet.google.com\/soo-kasi-shg\" target=\"_blank\" rel=\"noopener noreferrer\">Sala virtual<\/a><\/p>\n<p><strong>20.01 | 14h<\/strong><\/p>\n<p><strong>Curso Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar<\/strong><br \/>\n<strong>P\u00fablico:<\/strong> M\u00e9dicos, fisioterapeutas, enfermeiros das Unidades de Pronto Atendimento (UPAs) e de Internamento (enfermaria)<br \/>\n<strong>Regi\u00f5es:<\/strong> Cariri, Sobral, Sert\u00e3o Central<br \/>\n<strong>Facilitadores:<\/strong> Fabr\u00edcio Martins, pneumologista, e Andrea Braide, fisioterapeuta.<br \/>\n<a href=\"https:\/\/meet.google.com\/hwo-wbew-mmn\" target=\"_blank\" rel=\"noopener noreferrer\">Sala virtual<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE) e a Secretaria da Sa\u00fade do Estado (Sesa) realizam, nesta quarta (19) e quinta-feira (20), o curso Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar. Em formato virtual e com carga hor\u00e1ria de quatro horas\/aula, a atividade tem [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":105201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,1515,379,226,431,426,1453,135],"class_list":["post-105199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-covid-19","tag-curso","tag-esp","tag-gripe","tag-influenza","tag-manejo-clinico","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE) e a Secretaria da Sa\u00fade do Estado (Sesa) realizam, nesta quarta (19) e quinta-feira (20), o curso Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar. Em formato virtual e com carga hor\u00e1ria de quatro horas\/aula, a atividade tem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-19T14:16:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T17:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"1012\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza\",\"datePublished\":\"2022-01-19T14:16:18+00:00\",\"dateModified\":\"2022-01-19T17:52:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg\",\"keywords\":[\"Cear\u00e1\",\"covid-19\",\"curso\",\"ESP\",\"gripe\",\"Influenza\",\"manejo cl\u00ednico\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\",\"name\":\"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg\",\"datePublished\":\"2022-01-19T14:16:18+00:00\",\"dateModified\":\"2022-01-19T17:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg\",\"width\":1616,\"height\":1012},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/","og_locale":"pt_BR","og_type":"article","og_title":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"A Escola de Sa\u00fade P\u00fablica do Cear\u00e1 Paulo Marcelo Martins Rodrigues (ESP\/CE) e a Secretaria da Sa\u00fade do Estado (Sesa) realizam, nesta quarta (19) e quinta-feira (20), o curso Manejo Cl\u00ednico no Contexto da Covid-19 &#8211; Abordagem do Paciente em Ambiente Hospitalar. Em formato virtual e com carga hor\u00e1ria de quatro horas\/aula, a atividade tem [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2022-01-19T14:16:18+00:00","article_modified_time":"2022-01-19T17:52:12+00:00","og_image":[{"width":1616,"height":1012,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/"},"author":{"name":"","@id":""},"headline":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza","datePublished":"2022-01-19T14:16:18+00:00","dateModified":"2022-01-19T17:52:12+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/"},"wordCount":317,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg","keywords":["Cear\u00e1","covid-19","curso","ESP","gripe","Influenza","manejo cl\u00ednico","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/","name":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg","datePublished":"2022-01-19T14:16:18+00:00","dateModified":"2022-01-19T17:52:12+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2022\/01\/photo1642598845.jpeg","width":1616,"height":1012},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2022\/01\/19\/esp-ce-e-sesa-capacitam-profissionais-da-saude-para-abordagem-de-pacientes-com-sintomas-de-covid-19-e-influenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"ESP\/CE e Sesa capacitam profissionais da Sa\u00fade para abordagem de pacientes com sintomas de Covid-19 e influenza"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/105199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=105199"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/105199\/revisions"}],"predecessor-version":[{"id":105206,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/105199\/revisions\/105206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/105201"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=105199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=105199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=105199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}