{"id":104454,"date":"2021-12-20T17:33:36","date_gmt":"2021-12-20T20:33:36","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=104454"},"modified":"2021-12-20T17:33:36","modified_gmt":"2021-12-20T20:33:36","slug":"termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/","title":{"rendered":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade"},"content":{"rendered":"<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-99196 alignleft\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/07\/Topo-Materia-Site_inovacao.png\" alt=\"\" width=\"198\" height=\"69\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-104456 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>Pelo conv\u00eanio, profissionais de sa\u00fade, pesquisadores e t\u00e9cnicos do setor industrial atuar\u00e3o conjuntamente no desenvolvimento de equipamentos e solu\u00e7\u00f5es tecnol\u00f3gicas para o segmento<\/em><\/p>\n<p>Os projetos que ser\u00e3o desenvolvidos por meio da <strong>Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade<\/strong> foram discutidos nesta segunda-feira (20), em reuni\u00e3o entre gestores da <strong>Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)<\/strong>, <strong>Universidade Estadual do Cear\u00e1 (Uece)<\/strong> e do<strong> Instituto Desenvolvimento, Estrat\u00e9gia e Conhecimento (Idesco)<\/strong>. Na ocasi\u00e3o, foi feita a assinatura simb\u00f3lica do<strong> Acordo de Coopera\u00e7\u00e3o T\u00e9cnica<\/strong> entre as institui\u00e7\u00f5es. Pelo conv\u00eanio, profissionais de sa\u00fade, pesquisadores e t\u00e9cnicos do setor industrial atuar\u00e3o conjuntamente no<strong> desenvolvimento de equipamentos e solu\u00e7\u00f5es tecnol\u00f3gicas para o segmento<\/strong>.<\/p>\n<p>Citando a experi\u00eancia do <strong>capacete de respira\u00e7\u00e3o assistida Elmo<\/strong>, inova\u00e7\u00e3o desenvolvida pela ESP\/CE em parceria com outras institui\u00e7\u00f5es cearenses, o superintendente Marcelo Alcantara falou da import\u00e2ncia de se trabalhar a inova\u00e7\u00e3o por meio da multidisciplinaridade e da intelig\u00eancia em sa\u00fade. \u201cSe a gente inovar em torno de um prop\u00f3sito, e se esse prop\u00f3sito for claro para os participantes, fica muito mais f\u00e1cil trabalhar as equipes. Na verdade, temos uma intelig\u00eancia coletiva e, por meio dela, \u00e9 que se acham solu\u00e7\u00f5es\u201d, pontuou.<\/p>\n<h3>Laborat\u00f3rio de Prototipa\u00e7\u00e3o em Sa\u00fade<\/h3>\n<p>Para fortalecer a constru\u00e7\u00e3o dessa rede, o futuro<strong> Laborat\u00f3rio de Prototipa\u00e7\u00e3o em Sa\u00fade (LPS)<\/strong>, a ser instalado na sede do Idesco, ser\u00e1 o <a href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/17\/ceara-tera-primeiro-laboratorio-especializado-em-prototipacao-de-tecnologias-em-saude\/\" target=\"_blank\" rel=\"noopener noreferrer\">primeiro equipamento especializado em prototipa\u00e7\u00e3o \u00e1gil do Nordeste<\/a> voltado inteiramente \u00e0 Sa\u00fade. Aberto a parceiros, ir\u00e1 disponibilizar equipe especializada em eletr\u00f4nica, mecatr\u00f4nica, mec\u00e2nica, corte a laser e impress\u00e3o 3D, entre outras \u00e1reas.<\/p>\n<p>O professor adjunto da Uece, pesquisador colaborador do LPS (Idesco) e cientista chefe de Inova\u00e7\u00e3o, Samuel Fa\u00e7anha, destacou a relev\u00e2ncia da parceria a partir do desejo de se somar com solu\u00e7\u00f5es que v\u00e3o melhorar a vida da sociedade a partir de um trabalho em colabora\u00e7\u00e3o. O gestor destacou o projeto do LPS como uma iniciativa inspirada nessa l\u00f3gica de evolu\u00e7\u00e3o das tecnologias em rede. \u201c\u00c9 um momento importante de estarmos com professores da Universidade, pesquisadores, conselheiros do Idesco, construindo expertises combinadas para que a gente consiga acelerar esse processo de amadurecimento das tecnologias em sa\u00fade\u201d, afirmou.<\/p>\n<p>Toda a infraestrutura do laborat\u00f3rio ser\u00e1 utilizada para a cria\u00e7\u00e3o e o aperfei\u00e7oamento de prot\u00f3tipos com baixo custo de produ\u00e7\u00e3o a serem aplicados na Sa\u00fade, al\u00e9m de oferecer apoio aos pesquisadores no desenvolvimento de suas cria\u00e7\u00f5es a partir das normas estabelecidas pelos \u00f3rg\u00e3os reguladores, como a <strong>Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa)<\/strong>. A partir da iniciativa, s\u00e3o previstos prototipagem de equipamentos, inven\u00e7\u00f5es, modelos de utilidade, desenhos industriais, marcas e programas de computador.<\/p>\n<p>As a\u00e7\u00f5es previstas na rede tamb\u00e9m foram destacadas pela coordenadora do N\u00facleo de Inova\u00e7\u00e3o Tecnol\u00f3gica (NIT) da ESP\/CE, Alice Pequeno. \u201cA partir da experi\u00eancia do Elmo, n\u00f3s estamos agora ampliando possibilidades de desenvolver ou aperfei\u00e7oar outras tecnologias a partir do estabelecimento dessa parceria, al\u00e9m de outros dispositivos que a gente est\u00e1 firmando por meio dessa coopera\u00e7\u00e3o t\u00e9cnica\u201d.<\/p>\n<h3>Acordo: dura\u00e7\u00e3o de cinco anos<\/h3>\n<p>A partir do acordo firmado entre as institui\u00e7\u00f5es, que ter\u00e1 <strong>dura\u00e7\u00e3o inicial de cinco anos<\/strong>, caber\u00e1 ao Idesco estar respons\u00e1vel pelo LPS, divulgar as inova\u00e7\u00f5es a ele relacionados, gerenciar o portf\u00f3lio dos produtos, al\u00e9m de assessorar a ESP\/CE. \u00c0 parceria caber\u00e1, ainda, o fortalecimento do papel da Escola, enquanto Instituto de Ci\u00eancia e Tecnologia (ICT), no incentivo \u00e0 produ\u00e7\u00e3o e incorpora\u00e7\u00e3o de conhecimento e novas tecnologias.<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-104459 size-full\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5495-2.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5495-2.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5495-2-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5495-2-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\n<em>Nova reuni\u00e3o ser\u00e1 realizada na pr\u00f3xima ter\u00e7a (28) para detalhamento dos projetos para 2022<\/em><\/p>\n<p style=\"text-align: left\">Al\u00e9m de Alcantara, Fa\u00e7anha e Pequeno, estiveram presentes na solenidade, representando o Idesco, os diretores Nilo Alves, Hermano Carvalho e Roberto Pinto; e a gerente de Projetos do Instituto, Rafaela Cajado.<\/p>\n<p>Tamb\u00e9m participaram o pesquisador colaborador do LPS e Idesco, Thiago Ayres; o professor adjunto da Uece, Francisco Sales \u00c1vila; e a professora do Centro de Ci\u00eancias da Sa\u00fade da Uece, Ivelise Brasil.<\/p>\n<p>Na pr\u00f3xima ter\u00e7a-feira (28), ser\u00e1 realizada nova reuni\u00e3o para o detalhamento e constitui\u00e7\u00e3o das equipes que ir\u00e3o trabalhar no desenvolvimento dos dois primeiros projetos para 2022 ligados \u00e0 estrutura\u00e7\u00e3o do LPS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pelo conv\u00eanio, profissionais de sa\u00fade, pesquisadores e t\u00e9cnicos do setor industrial atuar\u00e3o conjuntamente no desenvolvimento de equipamentos e solu\u00e7\u00f5es tecnol\u00f3gicas para o segmento Os projetos que ser\u00e3o desenvolvidos por meio da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade foram discutidos nesta segunda-feira (20), em reuni\u00e3o entre gestores da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE), [&hellip;]<\/p>\n","protected":false},"author":520,"featured_media":104456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[706],"tags":[133,2133,1608,1031,135],"class_list":["post-104454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esp-ce","tag-ceara","tag-escola-de-saude-publica","tag-idesco","tag-inovacao","tag-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"Pelo conv\u00eanio, profissionais de sa\u00fade, pesquisadores e t\u00e9cnicos do setor industrial atuar\u00e3o conjuntamente no desenvolvimento de equipamentos e solu\u00e7\u00f5es tecnol\u00f3gicas para o segmento Os projetos que ser\u00e3o desenvolvidos por meio da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade foram discutidos nesta segunda-feira (20), em reuni\u00e3o entre gestores da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-20T20:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade\",\"datePublished\":\"2021-12-20T20:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\"},\"wordCount\":776,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\",\"keywords\":[\"Cear\u00e1\",\"Escola de Sa\u00fade P\u00fablica\",\"Idesco\",\"inova\u00e7\u00e3o\",\"sa\u00fade\"],\"articleSection\":[\"Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\",\"name\":\"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\",\"datePublished\":\"2021-12-20T20:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"Pelo conv\u00eanio, profissionais de sa\u00fade, pesquisadores e t\u00e9cnicos do setor industrial atuar\u00e3o conjuntamente no desenvolvimento de equipamentos e solu\u00e7\u00f5es tecnol\u00f3gicas para o segmento Os projetos que ser\u00e3o desenvolvidos por meio da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade foram discutidos nesta segunda-feira (20), em reuni\u00e3o entre gestores da Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE), [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2021-12-20T20:33:36+00:00","og_image":[{"width":775,"height":485,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/"},"author":{"name":"","@id":""},"headline":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade","datePublished":"2021-12-20T20:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/"},"wordCount":776,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg","keywords":["Cear\u00e1","Escola de Sa\u00fade P\u00fablica","Idesco","inova\u00e7\u00e3o","sa\u00fade"],"articleSection":["Escola de Sa\u00fade P\u00fablica do Cear\u00e1 (ESP\/CE)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/","name":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg","datePublished":"2021-12-20T20:33:36+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2021\/12\/IMG_5610-1.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2021\/12\/20\/termo-de-cooperacao-firma-parceria-entre-esp-ce-e-idesco-para-criacao-da-rede-de-inovacao-aberta-para-a-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Termo de Coopera\u00e7\u00e3o firma parceria entre ESP\/CE e Idesco para cria\u00e7\u00e3o da Rede de Inova\u00e7\u00e3o Aberta para a Sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/ww16.ce.gov.br\/saude\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/104454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/520"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=104454"}],"version-history":[{"count":4,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/104454\/revisions"}],"predecessor-version":[{"id":104461,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/104454\/revisions\/104461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/104456"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=104454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=104454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=104454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}