{"id":10422,"date":"2018-02-02T16:40:04","date_gmt":"2018-02-02T19:40:04","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/?p=10422"},"modified":"2019-01-07T09:48:47","modified_gmt":"2019-01-07T12:48:47","slug":"banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/","title":{"rendered":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10423\" src=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\" alt=\"\" width=\"775\" height=\"485\" srcset=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg 775w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf-600x375.jpg 600w, https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf-768x481.jpg 768w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><br \/>\nO m\u00eas de fevereiro chegou e com ele vem o carnaval. A cidade j\u00e1 est\u00e1 no clima carnavalesco com os blocos de pr\u00e9-carnaval e a chegada de mais um feriado prolongado. Nesse per\u00edodo, por\u00e9m, as doa\u00e7\u00f5es no Banco de Leite do Hospital Geral de Fortaleza (HGF), da rede p\u00fablica de sa\u00fade do Governo do Cear\u00e1, costumam cair. Para n\u00e3o faltar leite materno para os 40 beb\u00eas que est\u00e3o internados na Unidade de Terapia Intensiva Neonatal (UTIN), o HGF lembra \u00e0s m\u00e3es que est\u00e3o amamentando sobre a import\u00e2ncia de doar.<\/p>\n<p>Maiane Almeida de Sousa, de 29 anos, est\u00e1 na unidade acompanhando a m\u00e3e, internada por conta de um Acidente Vascular Cerebral (AVC). Ela \u00e9 m\u00e3e de duas meninas, uma de sete anos e outra com apenas um m\u00eas. Maiane conta que nas duas gesta\u00e7\u00f5es sempre produziu bastante leite, mas que s\u00f3 veio realizar as doa\u00e7\u00f5es depois do nascimento da segunda filha.\u201cEu tenho tanto leite, que o peito fica doendo quando eu n\u00e3o tiro. Como eu estou aqui no HGF, fiquei sabendo da exist\u00eancia do banco e aproveitei para fazer a doa\u00e7\u00e3o. Foi a melhor coisa. Se eu tenho tanto leite, porque n\u00e3o ajudar as outras m\u00e3es que precisam?\u201d, fala.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.hgf.ce.gov.br\/images\/stories\/foto_banner_blh.jpg\" alt=\"alt\" \/><\/p>\n<p>Por acompanhar a m\u00e3e, Maiane n\u00e3o tem como amamentar a filha mais nova. Em casos assim, \u00e9 orientado deixar leite estocado para os beb\u00eas. Em casa mesmo, a doadora deve separar um recipiente de vidro para fazer a coleta e um outro, com tampa pl\u00e1stica, para guardar o leite no congelador ou freezer. Se usar vidro de caf\u00e9, por exemplo, deve-se retirar os r\u00f3tulos. O recipiente precisa ser lavado e fervido em \u00e1gua por at\u00e9 15 minutos, junto com a tampa. Em seguida, \u00e9 s\u00f3 deixar escorrer sobre um pano limpo e utiliz\u00e1-lo.<\/p>\n<p>A enfermeira Saionara Oswaldina ressalta a import\u00e2ncia de doar e alerta para uso correto do leite armazenado. \u201cAs doa\u00e7\u00f5es s\u00e3o muito importantes e se tornam fundamentais durante os feriados mais prolongados. \u00c9 primordial que a m\u00e3e, ao retirar o leite, fa\u00e7a o correto asseio e esteja em um ambiente limpo e arejado. Quando for fazer o uso desse leite que ela congelou, que vale at\u00e9 12 horas, ela deve tirar somente o necess\u00e1rio para alimenta\u00e7\u00e3o do beb\u00ea e n\u00e3o pode guardar o restante que sobrou, descartando o excedente\u201d, orienta.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.hgf.ce.gov.br\/images\/stories\/foto_banner_blh02.jpg\" alt=\"alt\" \/><\/p>\n<p>Em 2017, o Hospital Geral de Fortaleza realizou 8.323 atendimentos \u00e0s m\u00e3es que buscam orienta\u00e7\u00f5es no Banco de Leite Humano. Os n\u00fameros registrados superaram o \u00edndice de 2016, quando foram feitos 4.971 atendimentos. Al\u00e9m do acompanhamento \u00e0s m\u00e3es com dificuldades na amamenta\u00e7\u00e3o, o banco \u00e9 respons\u00e1vel pela capta\u00e7\u00e3o, pasteuriza\u00e7\u00e3o e distribui\u00e7\u00e3o de leite para os rec\u00e9m-nascidos internados na UTIN.<\/p>\n<p><b>Doa\u00e7\u00f5es de Frascos<\/b><\/p>\n<p>A utiliza\u00e7\u00e3o dos frascos \u00e9 ideal para guardar o leite doado, destinado aos rec\u00e9m-nascidos internados na Unidade Neonatal. Tamb\u00e9m s\u00e3o encaminhados para a casa das m\u00e3es doadoras, onde s\u00e3o utilizados para manter o leite no freezer ou congelador at\u00e9 o momento da doa\u00e7\u00e3o. Os frascos de vidro doados passam por um processo de higieniza\u00e7\u00e3o e esteriliza\u00e7\u00e3o. Primeiro, \u00e9 feita a lavagem, depois \u00e9 a vez da estufa, onde acontece a secagem, em seguida, s\u00e3o esterilizados e, por fim, embalados. Ap\u00f3s esse processo, eles est\u00e3o prontos para serem encaminhados para a casa das m\u00e3es doadoras.<\/p>\n<p><b>Cuidados com a higiene<\/b><\/p>\n<p>Quando for coletar o leite, o local escolhido precisa ser limpo e arejado. O primeiro passo \u00e9 prender os cabelos e fazer a higiene das m\u00e3os. Isso vai evitar que o leite seja contaminado e desperdi\u00e7ado. Ap\u00f3s a coleta, o leite vai para o segundo recipiente de vidro. Em seguida, j\u00e1 tampado, o frasco dever\u00e1 ser guardado no congelador. Sempre que fizer a coleta, a m\u00e3e deve colocar o leite no mesmo recipiente at\u00e9 atingir a marca de dois dedos antes da tampa. Quando isso acontecer, \u00e9 s\u00f3 ligar para o HGF e uma equipe ser\u00e1 enviada \u00e0 casa da doadora para buscar a doa\u00e7\u00e3o.<\/p>\n<p><b>Ligue para Banco de Leite Humano do HGF<\/b><\/p>\n<p>As m\u00e3es que nunca doaram e tamb\u00e9m as que j\u00e1 fazem a doa\u00e7\u00e3o podem ligar para o n\u00famero (85) 3101.3335 e tirar todas as d\u00favidas. Por telefone ou pessoalmente, o banco de leite do HGF possui uma equipe especializada para transmitir todas as orienta\u00e7\u00f5es e informa\u00e7\u00f5es sobre doa\u00e7\u00e3o, aleitamento materno, cuidados com a mama e com o beb\u00ea, entre outros questionamentos.<\/p>\n<p><b>Servi\u00e7o:<br \/>\nBanco de Leite Humano do Hospital Geral de Fortaleza<\/b><br \/>\nAtendimento: segunda a sexta-feira, das 8 \u00e0s 16h<br \/>\nRua \u00c1vila Goulart, 900, Papicu, Fortaleza<br \/>\n(85) 3101-3335<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00eas de fevereiro chegou e com ele vem o carnaval. A cidade j\u00e1 est\u00e1 no clima carnavalesco com os blocos de pr\u00e9-carnaval e a chegada de mais um feriado prolongado. Nesse per\u00edodo, por\u00e9m, as doa\u00e7\u00f5es no Banco de Leite do Hospital Geral de Fortaleza (HGF), da rede p\u00fablica de sa\u00fade do Governo do Cear\u00e1, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[496],"tags":[161,114,157],"class_list":["post-10422","post","type-post","status-publish","format-standard","hentry","category-hgf","tag-carnaval","tag-doacao-de-leite-materno","tag-hospital-geral-de-fortaleza"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"O m\u00eas de fevereiro chegou e com ele vem o carnaval. A cidade j\u00e1 est\u00e1 no clima carnavalesco com os blocos de pr\u00e9-carnaval e a chegada de mais um feriado prolongado. Nesse per\u00edodo, por\u00e9m, as doa\u00e7\u00f5es no Banco de Leite do Hospital Geral de Fortaleza (HGF), da rede p\u00fablica de sa\u00fade do Governo do Cear\u00e1, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-02T19:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-07T12:48:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval\",\"datePublished\":\"2018-02-02T19:40:04+00:00\",\"dateModified\":\"2019-01-07T12:48:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\"},\"wordCount\":804,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\",\"keywords\":[\"Carnaval\",\"doa\u00e7\u00e3o de leite materno\",\"Hospital Geral de Fortaleza\"],\"articleSection\":[\"Hospital Geral de Fortaleza (HGF)\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\",\"name\":\"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\",\"datePublished\":\"2018-02-02T19:40:04+00:00\",\"dateModified\":\"2019-01-07T12:48:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg\",\"width\":775,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"O m\u00eas de fevereiro chegou e com ele vem o carnaval. A cidade j\u00e1 est\u00e1 no clima carnavalesco com os blocos de pr\u00e9-carnaval e a chegada de mais um feriado prolongado. Nesse per\u00edodo, por\u00e9m, as doa\u00e7\u00f5es no Banco de Leite do Hospital Geral de Fortaleza (HGF), da rede p\u00fablica de sa\u00fade do Governo do Cear\u00e1, [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2018-02-02T19:40:04+00:00","article_modified_time":"2019-01-07T12:48:47+00:00","og_image":[{"url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval","datePublished":"2018-02-02T19:40:04+00:00","dateModified":"2019-01-07T12:48:47+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/"},"wordCount":804,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg","keywords":["Carnaval","doa\u00e7\u00e3o de leite materno","Hospital Geral de Fortaleza"],"articleSection":["Hospital Geral de Fortaleza (HGF)"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/","name":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage"},"thumbnailUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg","datePublished":"2018-02-02T19:40:04+00:00","dateModified":"2019-01-07T12:48:47+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2018\/02\/banner_doacao_leite_hgf.jpg","width":775,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2018\/02\/02\/banco-de-leite-humano-do-hgf-precisa-de-doacao-para-o-carnaval\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Banco de Leite Humano precisa de doa\u00e7\u00e3o para o Carnaval"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/10422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=10422"}],"version-history":[{"count":2,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/10422\/revisions"}],"predecessor-version":[{"id":76008,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/10422\/revisions\/76008"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=10422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=10422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=10422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}