{"id":1006,"date":"2011-04-28T18:26:36","date_gmt":"2011-04-28T21:26:36","guid":{"rendered":"http:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/"},"modified":"2011-04-28T18:26:36","modified_gmt":"2011-04-28T21:26:36","slug":"nova-diretoria-do-conass-destaca-gestao-compartilhada","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/","title":{"rendered":"Nova diretoria do Conass destaca gest\u00e3o compartilhada"},"content":{"rendered":"<p>&#8220;\u00c9 fascinante o amadurecimento que o exerc\u00edcio de cogest\u00e3o pode nos proporcionar para que possamos lidar com os avan\u00e7os e os desafios do SUS e para que nos ajude a seguir em frente&#8221;, disse na solenidade de posse a presidente reeleita do Conselho Nacional de Secret\u00e1rios da Sa\u00fade, Beatriz Dobashi. Ela e toda a diretoria do Conass tomaram posse na noite da \u00faltima quarta-feira, 27, entre eles o secret\u00e1rio da sa\u00fade do Estado, Arruda Bastos, na vice-presid\u00eancia na regi\u00e3o Nordeste (na foto ele recebe diploma de posse de Beatriz Dobashi).<\/p>\n<p>Nesta sexta-feira, 29, e 30, Arruda Bastos estar\u00e1 em S\u00e3o Paulo, onde participa do semin\u00e1rio &#8220;A sa\u00fade no projeto nacional de desenvolvimento&#8221;.Durante o semin\u00e1rio em S\u00e3o Paulo, Arruda Bastos coordenar\u00e1 no s\u00e1bado, 30, a mesa redonda \u201cGest\u00e3o e financiamento da Sa\u00fade\u201d. Na sua apresenta\u00e7\u00e3o, mostrar\u00e1 os investimentos do Governo do Cear\u00e1 na estrutura\u00e7\u00e3o de uma nova rede de assist\u00eancia \u00e0 sa\u00fade, que inclui tr\u00eas hospitais regionais (no Cariri, j\u00e1 inaugurado, na Regi\u00e3o Norte, em constru\u00e7\u00e3o em Sobral, e no Sert\u00e3o Central, em processo de defini\u00e7\u00e3o da localiza\u00e7\u00e3o), 21 policl\u00ednicas, 18 Centros de Especialidades Odontol\u00f3gicas (CEOs) regionais e 32 unidades de pronto atendimento (UPAs 24 horas). O ex-secret\u00e1rio da Sa\u00fade do Cear\u00e1, deputado federal Jo\u00e3o Ananias ser\u00e1 palestrante do semin\u00e1rio na sexta-feira, na mesa \u201cDemocracia e participa\u00e7\u00e3o social e a 14\u00aa Confer\u00eancia Nacional de Sa\u00fade.<\/p>\n<p>Na solenidade de posse, a presidente do Conass destacou a import\u00e2ncia da gest\u00e3o compartilhada entre as tr\u00eas esferas de governo, alertando para a necessidade da organiza\u00e7\u00e3o das redes de aten\u00e7\u00e3o \u00e0 sa\u00fade que, segundo ela, deve ser coordenada pelos Estados. Na mesma linha, o ministro da sa\u00fade, Alexandre Padilha, presente na solenidade de posse,&nbsp; afirmou que &#8220;apostamos no di\u00e1logo e na coopera\u00e7\u00e3o, pois temos a compreens\u00e3o de que n\u00e3o \u00e9 poss\u00edvel aprimorar o SUS sem esta rela\u00e7\u00e3o tripartite&#8221;. <\/p>\n<p>O ministro disse que far\u00e1 esfor\u00e7o para contribuir com o fortalecimento do Conass e do Conselho Nacional de Secret\u00e1rios Municipais de Sa\u00fade (Conasems). Destacou a necessidade de aprimoramento da aten\u00e7\u00e3o prim\u00e1ria \u00e0 sa\u00fade e da pol\u00edtica de urg\u00eancia e emerg\u00eancia. <\/p>\n<p><strong>O que \u00e9 o Conass&nbsp;&nbsp;<\/strong>&nbsp; &nbsp;<\/p>\n<p>Fundado em 1982, o Conass \u00e9 a entidade que re\u00fane todos os secret\u00e1rios estaduais de sa\u00fade. Integra a Comiss\u00e3o Intergestores Tripartite (CIT), inst\u00e2ncia de articula\u00e7\u00e3o e pactua\u00e7\u00e3o na esfera federal que atua no fortalecimento do Sistema \u00danico de Sa\u00fade, com seis membros: presidente e representantes de cada uma das cinco regi\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Assessoria de comunica\u00e7\u00e3o do Conass<\/em><\/p>\n<p><em>Assessoria de comunica\u00e7\u00e3o da Sesa<\/p>\n<p><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00c9 fascinante o amadurecimento que o exerc\u00edcio de cogest\u00e3o pode nos proporcionar para que possamos lidar com os avan\u00e7os e os desafios do SUS e para que nos ajude a seguir em frente&#8221;, disse na solenidade de posse a presidente reeleita do Conselho Nacional de Secret\u00e1rios da Sa\u00fade, Beatriz Dobashi. Ela e toda a diretoria [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":1005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"og:description\" content=\"&#8220;\u00c9 fascinante o amadurecimento que o exerc\u00edcio de cogest\u00e3o pode nos proporcionar para que possamos lidar com os avan\u00e7os e os desafios do SUS e para que nos ajude a seguir em frente&#8221;, disse na solenidade de posse a presidente reeleita do Conselho Nacional de Secret\u00e1rios da Sa\u00fade, Beatriz Dobashi. Ela e toda a diretoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria da Sa\u00fade do Cear\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-28T21:26:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Nova diretoria do Conass destaca gest\u00e3o compartilhada\",\"datePublished\":\"2011-04-28T21:26:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\"},\"wordCount\":475,\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\",\"name\":\"Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg\",\"datePublished\":\"2011-04-28T21:26:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg\",\"contentUrl\":\"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg\",\"width\":555,\"height\":274,\"caption\":\"banner_conass_posse_2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nova diretoria do Conass destaca gest\u00e3o compartilhada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"name\":\"Secretaria da Sa\u00fade\",\"description\":\"Secretaria da Sa\u00fade do Cear\u00e1\",\"publisher\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#organization\",\"name\":\"Secretaria da Sa\u00fade\",\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"contentUrl\":\"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png\",\"width\":559,\"height\":106,\"caption\":\"Secretaria da Sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/","og_locale":"pt_BR","og_type":"article","og_title":"Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1","og_description":"&#8220;\u00c9 fascinante o amadurecimento que o exerc\u00edcio de cogest\u00e3o pode nos proporcionar para que possamos lidar com os avan\u00e7os e os desafios do SUS e para que nos ajude a seguir em frente&#8221;, disse na solenidade de posse a presidente reeleita do Conselho Nacional de Secret\u00e1rios da Sa\u00fade, Beatriz Dobashi. Ela e toda a diretoria [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/","og_site_name":"Secretaria da Sa\u00fade do Cear\u00e1","article_published_time":"2011-04-28T21:26:36+00:00","og_image":[{"width":555,"height":274,"url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg","type":"image\/jpeg"}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Nova diretoria do Conass destaca gest\u00e3o compartilhada","datePublished":"2011-04-28T21:26:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/"},"wordCount":475,"publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/","url":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/","name":"Nova diretoria do Conass destaca gest\u00e3o compartilhada - Secretaria da Sa\u00fade do Cear\u00e1","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage"},"thumbnailUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg","datePublished":"2011-04-28T21:26:36+00:00","breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#primaryimage","url":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg","contentUrl":"https:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/64\/2011\/04\/banner_conass_posse_2.jpg","width":555,"height":274,"caption":"banner_conass_posse_2"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/saude\/2011\/04\/28\/nova-diretoria-do-conass-destaca-gestao-compartilhada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/saude\/"},{"@type":"ListItem","position":2,"name":"Nova diretoria do Conass destaca gest\u00e3o compartilhada"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/saude\/#website","url":"https:\/\/ww16.ce.gov.br\/saude\/","name":"Secretaria da Sa\u00fade","description":"Secretaria da Sa\u00fade do Cear\u00e1","publisher":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ww16.ce.gov.br\/saude\/#organization","name":"Secretaria da Sa\u00fade","url":"https:\/\/ww16.ce.gov.br\/saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/","url":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","contentUrl":"http:\/\/ww16.ce.gov.br\/saude\/wp-content\/uploads\/sites\/9\/2017\/11\/clara.png","width":559,"height":106,"caption":"Secretaria da Sa\u00fade"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/saude\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/saude\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}