{"id":668,"date":"2015-09-27T16:50:11","date_gmt":"2015-09-27T19:50:11","guid":{"rendered":"http:\/\/www.hsmm.ce.gov.br\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/"},"modified":"2015-09-27T16:50:11","modified_gmt":"2015-09-27T19:50:11","slug":"saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/","title":{"rendered":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9)"},"content":{"rendered":"<p> \tA popula\u00e7\u00e3o do Cear\u00e1 tem todos os dias acesso \u00e0s informa\u00e7\u00f5es de atendimentos dos hospitais da rede p\u00fablica estadual. Veja abaixo os atendimentos feitos, da zero hora de s\u00e1bado, 26, \u00e0 zero hora de domingo, 27 de setembro, nas seguintes unidades: Hospital Geral de Fortaleza (HGF), Hospital Infantil Albert Sabin, Hospital de Messejana Dr. Carlos Alberto Studart Gomes, Hospital Geral C\u00e9sar Cals, Hospital S\u00e3o Jos\u00e9, Hospital Geral Dr. Waldemar Alc\u00e2ntara, Hospital de Sa\u00fade Mental Professor Frota Pinto, Hospital Jos\u00e9 Martiniano de Alencar (o antigo da Pol\u00edcia) e, no interior, o Hospital Regional do Cariri, em Juazeiro do Norte, e o Hospital Regional Norte, em Sobral.<\/p>\n<div class=\"yj6qo ajU\">\n<div class=\"ajR\" data-tooltip=\"Mostrar conte\u00fado cortado\" id=\":136\" role=\"button\" tabindex=\"0\">\n<p> \t\t<img decoding=\"async\" alt=\"alt\" src=\"https:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\" style=\"width: 555px; height: 414px;\" \/><\/p>\n<p> \t\tAssessoria de Comunica\u00e7\u00e3o da Sesa<br \/> \t\tSelma Oliveira \/ Marcus S\u00e1 \/\u00a0 ( <a href=\"mailto:selma.oliveira@saude.ce.gov.br\">selma.oliveira@saude.ce.gov.br<\/a> \/ 85 3101.5221 \/ 3101.5220)<br \/> \t\tTwitter: @SaudeCeara<br \/> \t\twww.facebook.com\/SaudeCeara<\/div>\n<p class=\"ajR\" data-tooltip=\"Mostrar conte\u00fado cortado\" role=\"button\" tabindex=\"0\"> \t\t\u00a0<\/p>\n<p class=\"ajR\" data-tooltip=\"Mostrar conte\u00fado cortado\" role=\"button\" tabindex=\"0\"> \t\t\u00a0<\/p>\n<p class=\"ajR\" data-tooltip=\"Mostrar conte\u00fado cortado\" role=\"button\" tabindex=\"0\"> \t\t\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A popula\u00e7\u00e3o do Cear\u00e1 tem todos os dias acesso \u00e0s informa\u00e7\u00f5es de atendimentos dos hospitais da rede p\u00fablica estadual. Veja abaixo os atendimentos feitos, da zero hora de s\u00e1bado, 26, \u00e0 zero hora de domingo, 27 de setembro, nas seguintes unidades: Hospital Geral de Fortaleza (HGF), Hospital Infantil Albert Sabin, Hospital de Messejana Dr. Carlos [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-668","post","type-post","status-publish","format-standard","hentry","category-lista-de-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM\" \/>\n<meta property=\"og:description\" content=\"A popula\u00e7\u00e3o do Cear\u00e1 tem todos os dias acesso \u00e0s informa\u00e7\u00f5es de atendimentos dos hospitais da rede p\u00fablica estadual. Veja abaixo os atendimentos feitos, da zero hora de s\u00e1bado, 26, \u00e0 zero hora de domingo, 27 de setembro, nas seguintes unidades: Hospital Geral de Fortaleza (HGF), Hospital Infantil Albert Sabin, Hospital de Messejana Dr. Carlos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\" \/>\n<meta property=\"og:site_name\" content=\"HSM\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-27T19:50:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9)\",\"datePublished\":\"2015-09-27T19:50:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\"},\"wordCount\":144,\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\",\"articleSection\":[\"Lista de Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\",\"name\":\"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\",\"datePublished\":\"2015-09-27T19:50:11+00:00\",\"author\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage\",\"url\":\"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\",\"contentUrl\":\"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/hsm\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/\",\"name\":\"HSM\",\"description\":\"Portal HSM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/hsm\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/","og_locale":"pt_BR","og_type":"article","og_title":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM","og_description":"A popula\u00e7\u00e3o do Cear\u00e1 tem todos os dias acesso \u00e0s informa\u00e7\u00f5es de atendimentos dos hospitais da rede p\u00fablica estadual. Veja abaixo os atendimentos feitos, da zero hora de s\u00e1bado, 26, \u00e0 zero hora de domingo, 27 de setembro, nas seguintes unidades: Hospital Geral de Fortaleza (HGF), Hospital Infantil Albert Sabin, Hospital de Messejana Dr. Carlos [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/","og_site_name":"HSM","article_published_time":"2015-09-27T19:50:11+00:00","og_image":[{"url":"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png","type":"","width":"","height":""}],"author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9)","datePublished":"2015-09-27T19:50:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/"},"wordCount":144,"image":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage"},"thumbnailUrl":"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png","articleSection":["Lista de Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/","url":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/","name":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9) - HSM","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage"},"image":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage"},"thumbnailUrl":"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png","datePublished":"2015-09-27T19:50:11+00:00","author":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#primaryimage","url":"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png","contentUrl":"http:\/\/www.saude.ce.gov.br\/images\/banners\/banners_2015\/atendimentos_hospitais\/antend__corpo_da_materia_27_09_2015.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/09\/27\/saude-informa-atendimentos-nos-10-hospitais-do-estado-no-sabado-269\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/hsm\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade informa atendimentos nos 10 hospitais do Estado no s\u00e1bado (26\/9)"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#website","url":"https:\/\/ww16.ce.gov.br\/hsm\/","name":"HSM","description":"Portal HSM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/hsm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/hsm\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}