{"id":570,"date":"2015-06-18T20:28:34","date_gmt":"2015-06-18T23:28:34","guid":{"rendered":"http:\/\/www.hsmm.ce.gov.br\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/"},"modified":"2015-06-18T20:28:34","modified_gmt":"2015-06-18T23:28:34","slug":"hospital-insere-dependentes-quimicos-no-mercado-de-trabalho","status":"publish","type":"post","link":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/","title":{"rendered":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho"},"content":{"rendered":"<p> \tO Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM), unidade da Secretaria da Sa\u00fade do Estado, concluiu na manh\u00e3 desta quinta-feira, 18 de junho, a mobiliza\u00e7\u00e3o de dependentes qu\u00edmicos egressos de tratamento para participa\u00e7\u00e3o no projeto Conex\u00e3o Vida, que objetiva contribuir para a reinser\u00e7\u00e3o social e laboral de dependentes qu\u00edmicos ap\u00f3s alta terap\u00eautica. Formulado pelo Servi\u00e7o de Aten\u00e7\u00e3o ao Dependente Qu\u00edmico, o projeto foi aprovado pelo Servi\u00e7o Nacional de Aprendizagem Comercial (Senac) e pelo Servi\u00e7o Social do Com\u00e9rcio (Sesc), que se tornaram parceiros do Hospital de Sa\u00fade mental na proposta de desenvolver as potencialidades de dependentes qu\u00edmicos, sua qualifica\u00e7\u00e3o profissional, inser\u00e7\u00e3o no mercado de trabalho e melhoria da qualidade de vida.<\/p>\n<p> \tNo Dia Mundial sem Drogas, 26 de junho, dependentes egressos de qualquer servi\u00e7o, abstinentes h\u00e1 pelo menos quatro meses, se encontrar\u00e3o no hospital para uma gincana que ter\u00e1 como temas a preven\u00e7\u00e3o da reca\u00edda, vida sem drogas, alimenta\u00e7\u00e3o saud\u00e1vel e mercado de trabalho. Com o prop\u00f3sito de contribuir para a reinser\u00e7\u00e3o social e laboral de dependentes qu\u00edmicos ap\u00f3s alta terap\u00eautica, o projeto tem meta de atender anualmente 100 pessoas que est\u00e3o em processo ou em alta terap\u00eautica. Para cumprir os objetivos, o projeto Conex\u00e3o Vida \u00e9 desenvolvido em quatro etapas &ndash; mobiliza\u00e7\u00e3o do p\u00fablico e sensibiliza\u00e7\u00e3o, capacita\u00e7\u00e3o para a inser\u00e7\u00e3o no mundo do trabalho, inser\u00e7\u00e3o laboral e acompanhamento dos egressos.<\/p>\n<p> \tA inser\u00e7\u00e3o laboral prevista no projeto \u00e9 qualquer atividade de natureza produtiva e geradora de renda, como emprego formal, grupos produtivos, cooperativismo, empreendedorismo individual, entre outras atividades. No projeto, o Sistema SESC\/SENAC desenvolver\u00e1 a\u00e7\u00f5es de educa\u00e7\u00e3o &ndash; cursos de Educa\u00e7\u00e3o de Jovens e Adultos (EJA) e Supletivo &ndash;, esportes para a pr\u00e1tica de atividades f\u00edsicas, oficinas de gera\u00e7\u00e3o de renda, atividades socioculturais, levantamento de demandas por forma\u00e7\u00e3o profissional e encaminhamento ao mercado de trabalho. Os parceiros no projeto Conex\u00e3o Vida tamb\u00e9m promover\u00e3o a\u00e7\u00f5es de sensibiliza\u00e7\u00e3o de empresas para a contrata\u00e7\u00e3o dos egressos capacitados.<\/p>\n<p> \tO N\u00facleo de Atendimento ao Dependente Qu\u00edmico do HSM \u00e9 composto de dois servi\u00e7os: Unidade de Desintoxica\u00e7\u00e3o, com 20 leitos masculinos, e o Centro de Conviv\u00eancia Elo de Vida, para dependentes qu\u00edmicos, com capacidade para 30 pacientes\/dia. Criado em junho de 1995 no HSM, o Centro de Conviv\u00eancia Elo de Vida recebe pacientes encaminhados pela Unidade de Desintoxica\u00e7\u00e3o, atende pacientes com depend\u00eancia qu\u00edmica e objetiva dar continuidade ao processo de manuten\u00e7\u00e3o da abstin\u00eancia ap\u00f3s a desintoxica\u00e7\u00e3o, favorecendo a mudan\u00e7a de h\u00e1bitos e comportamentos. O tempo de perman\u00eancia no tratamento \u00e9 flex\u00edvel, mas \u00e9 cumprido o m\u00ednimo de tr\u00eas meses do programa terap\u00eautico. Os participantes s\u00e3o acompanhados diariamente por equipe multidisciplinar, de segunda a sexta-feira, de 8 \u00e0s 17 horas.<\/p>\n<p> \t<strong style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\">Assessoria de Comunica\u00e7\u00e3o da Sesa<\/strong><br style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\" \/> \t<span style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\">Selma Oliveira \/ Marcus S\u00e1 \/\u00a0 (\u00a0<\/span><a href=\"mailto:%20Este%20endere%C3%A7o%20de%20e-mail%20est%C3%A1%20protegido%20contra%20spambots.%20Voc%C3%AA%20deve%20habilitar%20o%20JavaScript%20para%20visualiz%C3%A1-lo.\" style=\"cursor: pointer; font-family: Arial; font-size: 11px;\">\u00a0<\/a><a href=\"mailto:%20%3Cscript%20language=%27JavaScript%27%20type=%27text\/javascript%27%3E%20%3C%21--%20var%20prefix%20=%20%27mailto:%27;%20var%20suffix%20=%20%27%27;%20var%20attribs%20=%20%27%27;%20var%20path%20=%20%27hr%27%20+%20%27ef%27%20+%20%27=%27;%20var%20addy81514%20=%20%27selma.oliveira%27%20+%20%27@%27;%20addy81514%20=%20addy81514%20+%20%27saude%27%20+%20%27.%27%20+%20%27ce%27%20+%20%27.%27%20+%20%27gov%27%20+%20%27.%27%20+%20%27br%27;%20document.write%28%20%27%3Ca%20%27%20+%20path%20+%20%27%5C%27%27%20+%20prefix%20+%20addy81514%20+%20suffix%20+%20%27%5C%27%27%20+%20attribs%20+%20%27%3E%27%20%29;%20document.write%28%20addy81514%20%29;%20document.write%28%20%27%3C%5C\/a%3E%27%20%29;%20\/\/--%3E%20%3C\/script%3E%3Cscript%20language=%27JavaScript%27%20type=%27text\/javascript%27%3E%20%3C%21--%20document.write%28%20%27%3Cspan%20style=%5C%27display:%20none;%5C%27%3E%27%20%29;%20\/\/--%3E%20%3C\/script%3EEste%20endere%C3%A7o%20de%20e-mail%20est%C3%A1%20protegido%20contra%20spambots.%20Voc%C3%AA%20deve%20habilitar%20o%20JavaScript%20para%20visualiz%C3%A1-lo.%20%3Cscript%20language=%27JavaScript%27%20type=%27text\/javascript%27%3E%20%3C%21--%20document.write%28%20%27%3C\/%27%20%29;%20document.write%28%20%27span%3E%27%20%29;%20\/\/--%3E%20%3C\/script%3E\" style=\"cursor: pointer; font-family: Arial; font-size: 11px;\"> <\/a> <a href=\"mailto:selma.oliveira@saude.ce.gov.br\">selma.oliveira@saude.ce.gov.br<\/a><span style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\">\u00a0\/ 85 3101.5221 \/ 3101.5220)<\/span><br style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\" \/> \t<span style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\">Twitter: @SaudeCeara<\/span><br style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\" \/> \t<strong style=\"color: rgb(0, 0, 0); font-family: Arial; font-size: 11px;\"><a href=\"https:\/\/www.facebook.com\/SaudeCeara\" style=\"cursor: pointer;\" target=\"_blank\">www.facebook.com\/SaudeCeara<\/a><\/strong><\/p>\n<p> \t\u00a0<\/p>\n<p> \t\u00a0<\/p>\n<p> \t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM), unidade da Secretaria da Sa\u00fade do Estado, concluiu na manh\u00e3 desta quinta-feira, 18 de junho, a mobiliza\u00e7\u00e3o de dependentes qu\u00edmicos egressos de tratamento para participa\u00e7\u00e3o no projeto Conex\u00e3o Vida, que objetiva contribuir para a reinser\u00e7\u00e3o social e laboral de dependentes qu\u00edmicos ap\u00f3s alta terap\u00eautica. Formulado pelo [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-570","post","type-post","status-publish","format-standard","hentry","category-lista-de-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM\" \/>\n<meta property=\"og:description\" content=\"O Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM), unidade da Secretaria da Sa\u00fade do Estado, concluiu na manh\u00e3 desta quinta-feira, 18 de junho, a mobiliza\u00e7\u00e3o de dependentes qu\u00edmicos egressos de tratamento para participa\u00e7\u00e3o no projeto Conex\u00e3o Vida, que objetiva contribuir para a reinser\u00e7\u00e3o social e laboral de dependentes qu\u00edmicos ap\u00f3s alta terap\u00eautica. Formulado pelo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"HSM\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-18T23:28:34+00:00\" \/>\n<meta name=\"author\" content=\"Felipe Regino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felipe Regino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\"},\"author\":{\"name\":\"Felipe Regino\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"headline\":\"Hospital insere dependentes qu\u00edmicos no mercado de trabalho\",\"datePublished\":\"2015-06-18T23:28:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\"},\"wordCount\":529,\"articleSection\":[\"Lista de Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\",\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\",\"name\":\"Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM\",\"isPartOf\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#website\"},\"datePublished\":\"2015-06-18T23:28:34+00:00\",\"author\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\"},\"breadcrumb\":{\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ww16.ce.gov.br\/hsm\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital insere dependentes qu\u00edmicos no mercado de trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#website\",\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/\",\"name\":\"HSM\",\"description\":\"Portal HSM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ww16.ce.gov.br\/hsm\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e\",\"name\":\"Felipe Regino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g\",\"caption\":\"Felipe Regino\"},\"url\":\"https:\/\/ww16.ce.gov.br\/hsm\/author\/sspdsfeliperegino\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/","og_locale":"pt_BR","og_type":"article","og_title":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM","og_description":"O Hospital de Sa\u00fade Mental Professor Frota Pinto (HSM), unidade da Secretaria da Sa\u00fade do Estado, concluiu na manh\u00e3 desta quinta-feira, 18 de junho, a mobiliza\u00e7\u00e3o de dependentes qu\u00edmicos egressos de tratamento para participa\u00e7\u00e3o no projeto Conex\u00e3o Vida, que objetiva contribuir para a reinser\u00e7\u00e3o social e laboral de dependentes qu\u00edmicos ap\u00f3s alta terap\u00eautica. Formulado pelo [&hellip;]","og_url":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/","og_site_name":"HSM","article_published_time":"2015-06-18T23:28:34+00:00","author":"Felipe Regino","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Felipe Regino","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#article","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/"},"author":{"name":"Felipe Regino","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"headline":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho","datePublished":"2015-06-18T23:28:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/"},"wordCount":529,"articleSection":["Lista de Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/","url":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/","name":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho - HSM","isPartOf":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/#website"},"datePublished":"2015-06-18T23:28:34+00:00","author":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e"},"breadcrumb":{"@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ww16.ce.gov.br\/hsm\/2015\/06\/18\/hospital-insere-dependentes-quimicos-no-mercado-de-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ww16.ce.gov.br\/hsm\/"},{"@type":"ListItem","position":2,"name":"Hospital insere dependentes qu\u00edmicos no mercado de trabalho"}]},{"@type":"WebSite","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#website","url":"https:\/\/ww16.ce.gov.br\/hsm\/","name":"HSM","description":"Portal HSM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ww16.ce.gov.br\/hsm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/98cfc5ab393b3ae8249357c5024a620e","name":"Felipe Regino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ww16.ce.gov.br\/hsm\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5948532bfed4bf995ab94c145699ff618fbb1a11e1bffe93097e84e5ffdeec3?s=96&d=mm&r=g","caption":"Felipe Regino"},"url":"https:\/\/ww16.ce.gov.br\/hsm\/author\/sspdsfeliperegino\/"}]}},"_links":{"self":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts\/570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/comments?post=570"}],"version-history":[{"count":0,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/posts\/570\/revisions"}],"wp:attachment":[{"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/media?parent=570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/categories?post=570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ww16.ce.gov.br\/hsm\/wp-json\/wp\/v2\/tags?post=570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}